{"id":5166,"date":"2015-12-10T22:19:11","date_gmt":"2015-12-10T22:19:11","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/1ki03\/"},"modified":"2020-03-08T08:44:10","modified_gmt":"2020-03-08T12:44:10","slug":"1ki03","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/1ki03\/","title":{"rendered":"1 Reyes 3"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 3<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y SALOM\u00d3N hizo parentesco con Fara\u00f3n rey de Egipto, porque tom\u00f3 la hija de Fara\u00f3n, y tr\u00e1jola \u00e1 la ciudad de David, entre tanto que acababa de edificar su casa, y la casa de Jehov\u00e1, y los muros de Jerusalem alrededor.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Hasta entonces el pueblo sacrificaba en los altos; porque no hab\u00eda casa edificada al nombre de Jehov\u00e1 hasta aquellos tiempos.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Mas Salom\u00f3n am\u00f3 \u00e1 Jehov\u00e1, andando en los estatutos de su padre David: solamente sacrificaba y quemaba perfumes en los altos.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> E iba el rey \u00e1 Gaba\u00f3n, porque aqu\u00e9l era el alto principal, y sacrificaba all\u00ed: mil holocaustos sacrificaba Salom\u00f3n sobre aquel altar.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y apareci\u00f3se Jehov\u00e1 \u00e1 Salom\u00f3n en Gaba\u00f3n una noche en sue\u00f1os, y d\u00edjo<span class=\"add\">le<\/span> Dios: Pide lo que <span class=\"add\">quisieres que<\/span> yo te d\u00e9.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y Salom\u00f3n dijo: T\u00fa hiciste gran misericordia \u00e1 tu siervo David mi padre, seg\u00fan que \u00e9l anduvo delante de ti en verdad, en justicia, y con rectitud de coraz\u00f3n para contigo: y t\u00fa le has guardado esta tu grande misericordia, que le diste hijo que se sentase en su trono, como <span class=\"add\">sucede<\/span> en este d\u00eda.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Ahora pues, Jehov\u00e1 Dios m\u00edo, t\u00fa has puesto \u00e1 m\u00ed tu siervo por rey en lugar de David mi padre: y yo soy mozo peque\u00f1o, que no s\u00e9 c\u00f3mo entrar ni salir.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y tu siervo est\u00e1 en medio de tu pueblo al cual t\u00fa escogiste; un pueblo grande, que no se puede contar ni numerar por su multitud.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Da pues \u00e1 tu siervo coraz\u00f3n d\u00f3cil para juzgar \u00e1 tu pueblo, para discernir entre lo bueno y lo malo: porque \u00bfqui\u00e9n podr\u00e1 gobernar este tu pueblo tan grande?  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y agrad\u00f3 delante de Adonai que Salom\u00f3n pidiese esto.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y d\u00edjole Dios: Porque has demandado esto, y no pediste para ti muchos d\u00edas, ni pediste para ti riquezas, ni pediste la vida de tus enemigos, mas demandaste para ti inteligencia para oir juicio;  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> He aqu\u00ed lo he hecho conforme \u00e1 tus palabras: he aqu\u00ed que te he dado coraz\u00f3n sabio y entendido, tanto que no haya habido antes de ti otro como t\u00fa, ni despu\u00e9s de ti se levantar\u00e1 otro como t\u00fa.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y aun tambi\u00e9n te he dado las cosas que no pediste, riquezas y gloria: tal, que entre los reyes ninguno haya como t\u00fa en todos tus d\u00edas.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y si anduvieres en mis caminos, guardando mis estatutos y mis mandamientos, como anduvo David tu padre, yo alargar\u00e9 tus d\u00edas.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y como Salom\u00f3n despert\u00f3, vi\u00f3 que era sue\u00f1o: y vino \u00e1 Jerusalem, y present\u00f3se delante del arca del pacto de Jehov\u00e1, y sacrific\u00f3 holocaustos, \u00e9 hizo pac\u00edficos; hizo tambi\u00e9n banquete \u00e1 todos sus siervos.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> En aquella saz\u00f3n vinieron dos mujeres rameras al rey, y present\u00e1ronse delante de \u00e9l.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y dijo la una mujer: \u00a1Ah, se\u00f1or m\u00edo! yo y esta mujer mor\u00e1bamos en una misma casa, y yo par\u00ed <span class=\"add\">estando<\/span> con ella en la casa.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Y aconteci\u00f3 al tercer d\u00eda despu\u00e9s que yo par\u00ed, que \u00e9sta pari\u00f3 tambi\u00e9n, y mor\u00e1bamos nosotras juntas; ninguno de fuera estaba en casa, sino nosotras dos en la casa.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y una noche el hijo de esta mujer muri\u00f3, porque ella se acost\u00f3 sobre \u00e9l.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y levant\u00f3se \u00e1 media noche, y tom\u00f3 \u00e1 mi hijo de junto \u00e1 m\u00ed, estando yo tu sierva durmiendo, y p\u00fasolo \u00e1 su lado, y p\u00fasome \u00e1 mi lado su hijo muerto.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y como yo me levant\u00e9 por la ma\u00f1ana para dar el pecho \u00e1 mi hijo, he aqu\u00ed que estaba muerto: mas observ\u00e9le por la ma\u00f1ana, y vi que no era mi hijo, que yo hab\u00eda parido.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Entonces la otra mujer dijo: No; mi hijo es el que vive, y tu hijo es el muerto. Y la otra volvi\u00f3 \u00e1 decir: No; tu hijo es el muerto, y mi hijo es el que vive. As\u00ed hablaban delante del rey.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> El rey entonces dijo: Esta dice: Mi hijo es el que vive, y tu hijo es el muerto: y la otra dice, No, mas el tuyo es el muerto, y mi hijo es el que vive.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y dijo el rey: Traedme un cuchillo. Y trajeron al rey un cuchillo.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> En seguida el rey dijo: Partid por medio el ni\u00f1o vivo, y dad la mitad \u00e1 la una, y la otra mitad \u00e1 la otra.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Entonces la mujer cuyo era el hijo vivo, habl\u00f3 al rey (porque sus entra\u00f1as se le conmovieron por su hijo), y dijo: \u00a1Ah, se\u00f1or m\u00edo! dad \u00e1 \u00e9sta el ni\u00f1o vivo, y no lo mat\u00e9is. Mas la otra dijo: Ni \u00e1 m\u00ed ni \u00e1 ti; partidlo.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Entonces el rey respondi\u00f3, y dijo: Dad \u00e1 aqu\u00e9lla el hijo vivo, y no lo mat\u00e9is: ella es su madre.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Y todo Israel oy\u00f3 aquel juicio que hab\u00eda dado el rey: y temieron al rey, porque vieron que hab\u00eda en \u00e9l sabidur\u00eda de Dios para juzgar.  <\/div><hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de 1 Reyes<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki22\">22<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>3 1\u00a0 Y SALOM\u00d3N hizo parentesco con Fara\u00f3n rey de Egipto, porque tom\u00f3 la hija de Fara\u00f3n, y tr\u00e1jola \u00e1 la ciudad de David, entre tanto que acababa de edificar su casa, y la casa de Jehov\u00e1, y los muros de Jerusalem alrededor. 2\u00a0 Hasta entonces el pueblo sacrificaba en los altos; porque no hab\u00eda casa edificada al nombre de Jehov\u00e1 hasta aquellos tiempos. 3\u00a0 Mas Salom\u00f3n am\u00f3 \u00e1 Jehov\u00e1, andando en los estatutos de su padre David: solamente sacrificaba y quemaba perfumes en los altos. 4\u00a0 E iba el rey \u00e1 Gaba\u00f3n, porque aqu\u00e9l era el alto principal, y sacrificaba all\u00ed: mil holocaustos sacrificaba Salom\u00f3n sobre aquel altar. 5\u00a0 Y apareci\u00f3se Jehov\u00e1 \u00e1 Salom\u00f3n en Gaba\u00f3n una noche en sue\u00f1os, y d\u00edjole Dios: Pide lo que quisieres que yo te d\u00e9. 6\u00a0 Y Salom\u00f3n dijo: T\u00fa hiciste gran misericordia \u00e1 tu siervo David mi padre, seg\u00fan que \u00e9l anduvo delante de ti en verdad, en justicia, y con rectitud de coraz\u00f3n para contigo: y t\u00fa le has guardado esta tu grande misericordia, que le diste hijo que se sentase en su trono, como sucede en este d\u00eda. 7\u00a0 Ahora pues, Jehov\u00e1 Dios m\u00edo, t\u00fa has puesto \u00e1 m\u00ed tu siervo por rey en lugar de David mi padre: y yo soy mozo peque\u00f1o, que no s\u00e9 c\u00f3mo entrar ni salir. 8\u00a0 Y tu siervo est\u00e1 en medio de tu pueblo al cual t\u00fa escogiste; un pueblo grande, que no se puede contar ni numerar por su multitud. 9\u00a0 Da pues \u00e1 tu siervo coraz\u00f3n d\u00f3cil para juzgar \u00e1 tu pueblo, para discernir entre lo bueno y lo malo: porque \u00bfqui\u00e9n podr\u00e1 gobernar este tu pueblo tan grande? 10\u00a0 Y agrad\u00f3 delante de Adonai que Salom\u00f3n pidiese esto. 11\u00a0 Y d\u00edjole Dios: Porque has demandado esto, y no pediste para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5166","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5166"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5166\/revisions"}],"predecessor-version":[{"id":7434,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5166\/revisions\/7434"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}