{"id":5183,"date":"2015-12-10T22:19:13","date_gmt":"2015-12-10T22:19:13","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/1ki20\/"},"modified":"2020-03-08T08:44:35","modified_gmt":"2020-03-08T12:44:35","slug":"1ki20","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/1ki20\/","title":{"rendered":"1 Reyes 20"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 20<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> ENTONCES Ben-adad rey de Siria junt\u00f3 \u00e1 todo su ej\u00e9rcito, y con \u00e9l treinta y dos reyes, con caballos y carros: y subi\u00f3, y puso cerco \u00e1 Samaria, y combati\u00f3la.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y envi\u00f3 mensajeros \u00e1 la ciudad \u00e1 Ach\u00e2b rey de Israel, diciendo:  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> As\u00ed ha dicho Ben-adad: Tu plata y tu oro es m\u00edo, y tus mujeres y tus hijos hermosos son m\u00edos.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y el rey de Israel respondi\u00f3, y dijo: Como t\u00fa dices, rey se\u00f1or m\u00edo, yo soy tuyo, y todo lo que tengo.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y volviendo los mensajeros otra vez, dijeron: As\u00ed dijo Ben-adad: Yo te envi\u00e9 \u00e1 decir: Tu plata y tu oro, y tus mujeres y tus hijos me dar\u00e1s.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Adem\u00e1s ma\u00f1ana \u00e1 estas horas enviar\u00e9 yo \u00e1 ti mis siervos, los cuales escudri\u00f1ar\u00e1n tu casa, y las casas de tus siervos; y tomar\u00e1n con sus manos, y llevar\u00e1n todo lo precioso que tuvieres.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Entonces el rey de Israel llam\u00f3 \u00e1 todos los ancianos de la tierra, y d\u00edjoles: Entended, y ved ahora c\u00f3mo \u00e9ste no busca sino mal: pues que ha enviado \u00e1 m\u00ed por mis mujeres y mis hijos, y por mi plata y por mi oro; y yo no se lo he negado.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y todos los ancianos y todo el pueblo le respondieron: No le obedezcas, ni hagas lo que te pide.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Entonces \u00e9l respondi\u00f3 \u00e1 los embajadores de Ben-adad: Decid al rey mi se\u00f1or: Har\u00e9 todo lo que mandaste \u00e1 tu siervo al principio; mas esto no lo puedo hacer. Y los embajadores fueron, y di\u00e9ronle la respuesta.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y Ben-adad torn\u00f3 \u00e1 enviarle \u00e1 decir: As\u00ed me hagan los dioses, y as\u00ed me a\u00f1adan, que el polvo de Samaria no bastar\u00e1 \u00e1 los pu\u00f1os de todo el pueblo que me sigue.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y el rey de Israel respondi\u00f3, y dijo: Decidle, que no se alabe el que se ci\u00f1e, como el que ya se desci\u00f1e.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y como \u00e9l oy\u00f3 esta palabra, estando bebiendo con los reyes en las tiendas, dijo \u00e1 sus siervos: Poned. Y ellos pusieron contra la ciudad.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y he aqu\u00ed un profeta se lleg\u00f3 \u00e1 Ach\u00e2b rey de Israel, y le dijo: As\u00ed ha dicho Jehov\u00e1: \u00bfHas visto esta grande multitud? he aqu\u00ed yo te la entregar\u00e9 hoy en tu mano, para que conozcas que yo soy Jehov\u00e1.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y respondi\u00f3 Ach\u00e2b: \u00bfPor <span class=\"add\">mano de<\/span> qui\u00e9n? Y \u00e9l dijo: As\u00ed ha dicho Jehov\u00e1: Por <span class=\"add\">mano de<\/span> los criados de los pr\u00edncipes de las provincias. Y dijo Ach\u00e2b: \u00bfQui\u00e9n comenzar\u00e1 la batalla? Y \u00e9l respondi\u00f3: T\u00fa.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Entonces \u00e9l reconoci\u00f3 los criados de los pr\u00edncipes de las provincias, los cuales fueron doscientos treinta y dos. Luego reconoci\u00f3 todo el pueblo, todos los hijos de Israel, que <span class=\"add\">fueron<\/span> siete mil.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y salieron \u00e1 medio d\u00eda. Y estaba Ben-adad bebiendo, borracho en las tiendas, \u00e9l y los reyes, los treinta y dos reyes que hab\u00edan venido en su ayuda.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y los criados de los pr\u00edncipes de las provincias salieron los primeros. Y hab\u00eda Ben-adad enviado quien le di\u00f3 aviso, diciendo: Han salido hombres de Samaria.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> El entonces dijo: Si han salido por paz, tomadlos vivos; y si han salido para pelear, tomadlos vivos.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Salieron pues de la ciudad los criados de los pr\u00edncipes de las provincias, y en pos de ellos el ej\u00e9rcito.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> E hiri\u00f3 cada uno al que ven\u00eda contra s\u00ed: y huyeron los Siros, sigui\u00e9ndolos los de Israel. Y el rey de Siria, Ben-adad, se escap\u00f3 en un caballo con alguna gente de caballer\u00eda.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y sali\u00f3 el rey de Israel, \u00e9 hiri\u00f3 la gente de \u00e1 caballo, y los carros; y deshizo los Siros con grande estrago.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Lleg\u00e1ndose luego el profeta al rey de Israel, le dijo: Ve, fortal\u00e9cete, y considera y mira lo que has de hacer; porque pasado el a\u00f1o, el rey de Siria ha de venir contra ti.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y los siervos del rey de Siria le dijeron: Sus dioses son dioses de los montes, por eso nos han vencido; mas si pele\u00e1remos con ellos en la llanura, <span class=\"add\">se ver\u00e1<\/span> si no los vencemos.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Haz pues as\u00ed: Saca \u00e1 los reyes cada uno de su puesto, y pon capitanes en lugar de ellos.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y t\u00fa, f\u00f3rmate otro ej\u00e9rcito como el ej\u00e9rcito que perdiste, caballos por caballos, y carros por carros; luego pelearemos con ellos en campo raso, y <span class=\"add\">veremos<\/span> si no los vencemos. Y \u00e9l les di\u00f3 o\u00eddo, \u00e9 h\u00edzolo as\u00ed.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Pasado el a\u00f1o, Ben-adad reconoci\u00f3 los Siros, y vino \u00e1 Aphec \u00e1 pelear contra Israel.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Y los hijos de Israel fueron tambi\u00e9n inspeccionados, y tomando provisiones fu\u00e9ronles al encuentro; y asentaron campo lo hijos de Israel delante de ellos, como dos reba\u00f1uelos de cabras; y los Siros hench\u00edan la tierra.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Lleg\u00e1ndose entonces el var\u00f3n de Dios al rey de Israel, habl\u00f3le diciendo: As\u00ed dijo Jehov\u00e1: Por cuanto los Siros han dicho, Jehov\u00e1 es Dios de los montes, no Dios de los valles, yo entregar\u00e9 toda esta grande multitud en tu mano, para que conozc\u00e1is que yo soy Jehov\u00e1.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Siete d\u00edas tuvieron asentado campo los unos delante de los otros, y al s\u00e9ptimo d\u00eda se di\u00f3 la batalla: y mataron los hijos de Israel de los Siros en un d\u00eda cien mil hombres de \u00e1 pie.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Los dem\u00e1s huyeron \u00e1 Aphec, \u00e1 la ciudad: y el muro cay\u00f3 sobre veinte y siete mil hombres que hab\u00edan quedado. Tambi\u00e9n Ben-adad vino huyendo \u00e1 la ciudad, y <span class=\"add\">escond\u00edase<\/span> de c\u00e1mara en c\u00e1mara.  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Entonces sus siervos le dijeron: He aqu\u00ed, hemos o\u00eddo de los reyes de la casa de Israel que son reyes clementes: pongamos pues ahora sacos en nuestros lomos, y sogas en nuestras cabezas, y salgamos al rey de Israel: por ventura te salvar\u00e1 la vida.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Ci\u00f1eron pues sus lomos de sacos, y sogas \u00e1 sus cabezas, y vinieron al rey de Israel, y dij\u00e9ronle: Tu siervo Ben-adad dice: Ru\u00e9gote que viva mi alma. Y \u00e9l respondi\u00f3: Si \u00e9l vive a\u00fan, mi hermano es.  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Esto tomaron aquellos hombres por buen ag\u00fcero, y presto tomaron esta palabra de su boca, y dijeron: \u00a1Tu hermano Ben-adad! Y \u00e9l dijo: Id, y traedle. Ben-adad entonces se present\u00f3 \u00e1 Ach\u00e2b, y \u00e9l le hizo subir en un carro.  <span class=\"verse\" id=\"V34\">34\u00a0<\/span> Y d\u00edjole <span class=\"add\">Ben-adad<\/span>: Las ciudades que mi padre tom\u00f3 al tuyo, yo las restituir\u00e9; y haz plazas en Damasco para ti, como mi padre las hizo en Samaria. Y yo, <span class=\"add\">dijo Ach\u00e2b<\/span>, te dejar\u00e9 partir con esta alianza. Hizo pues con \u00e9l alianza, y dej\u00f3le ir.  <span class=\"verse\" id=\"V35\">35\u00a0<\/span> Entonces un var\u00f3n de los hijos de los profetas dijo \u00e1 su compa\u00f1ero por palabra de Dios: Hi\u00e9reme ahora. Mas el <span class=\"add\">otro<\/span> var\u00f3n no quiso herirle.  <span class=\"verse\" id=\"V36\">36\u00a0<\/span> Y \u00e9l le dijo: Por cuanto no has obedecido \u00e1 la palabra de Jehov\u00e1, he aqu\u00ed en apart\u00e1ndote de m\u00ed, te herir\u00e1 un le\u00f3n. Y como se apart\u00f3 de \u00e9l, top\u00f3le un le\u00f3n, \u00e9 hiri\u00f3le.  <span class=\"verse\" id=\"V37\">37\u00a0<\/span> Encontr\u00f3se luego con otro hombre, y d\u00edjole: Hi\u00e9reme ahora. Y el hombre le di\u00f3 un golpe, \u00e9 h\u00edzole una herida.  <span class=\"verse\" id=\"V38\">38\u00a0<\/span> Y el profeta se fu\u00e9, y p\u00fasose delante del rey en el camino, y disfraz\u00f3se con un velo sobre los ojos.  <span class=\"verse\" id=\"V39\">39\u00a0<\/span> Y como el rey pasaba, \u00e9l di\u00f3 voces al rey, y dijo: Tu siervo sali\u00f3 entre la tropa: y he aqu\u00ed apart\u00e1ndose uno, tr\u00e1jome un hombre, diciendo: Guarda \u00e1 este hombre, y si llegare \u00e1 faltar, tu vida ser\u00e1 por la suya, \u00f3 pagar\u00e1s un talento de plata.  <span class=\"verse\" id=\"V40\">40\u00a0<\/span> Y como tu siervo estaba ocupado \u00e1 una parte y \u00e1 otra, \u00e9l desapareci\u00f3. Entonces el rey de Israel le dijo: Esa ser\u00e1 tu sentencia: t\u00fa la has pronunciado.  <span class=\"verse\" id=\"V41\">41\u00a0<\/span> Pero \u00e9l se quit\u00f3 de presto el velo de sobre sus ojos, y el rey de Israel conoci\u00f3 que era de los profetas.  <span class=\"verse\" id=\"V42\">42\u00a0<\/span> Y \u00e9l le dijo: As\u00ed ha dicho Jehov\u00e1: Por cuanto soltaste de la mano el hombre de mi anatema, tu vida ser\u00e1 por la suya, y tu pueblo por el suyo.  <span class=\"verse\" id=\"V43\">43\u00a0<\/span> Y el rey de Israel se fu\u00e9 \u00e1 su casa triste y enojado, y lleg\u00f3 \u00e1 Samaria.  <\/div><hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de 1 Reyes<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/1ki22\">22<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>20 1\u00a0 ENTONCES Ben-adad rey de Siria junt\u00f3 \u00e1 todo su ej\u00e9rcito, y con \u00e9l treinta y dos reyes, con caballos y carros: y subi\u00f3, y puso cerco \u00e1 Samaria, y combati\u00f3la. 2\u00a0 Y envi\u00f3 mensajeros \u00e1 la ciudad \u00e1 Ach\u00e2b rey de Israel, diciendo: 3\u00a0 As\u00ed ha dicho Ben-adad: Tu plata y tu oro es m\u00edo, y tus mujeres y tus hijos hermosos son m\u00edos. 4\u00a0 Y el rey de Israel respondi\u00f3, y dijo: Como t\u00fa dices, rey se\u00f1or m\u00edo, yo soy tuyo, y todo lo que tengo. 5\u00a0 Y volviendo los mensajeros otra vez, dijeron: As\u00ed dijo Ben-adad: Yo te envi\u00e9 \u00e1 decir: Tu plata y tu oro, y tus mujeres y tus hijos me dar\u00e1s. 6\u00a0 Adem\u00e1s ma\u00f1ana \u00e1 estas horas enviar\u00e9 yo \u00e1 ti mis siervos, los cuales escudri\u00f1ar\u00e1n tu casa, y las casas de tus siervos; y tomar\u00e1n con sus manos, y llevar\u00e1n todo lo precioso que tuvieres. 7\u00a0 Entonces el rey de Israel llam\u00f3 \u00e1 todos los ancianos de la tierra, y d\u00edjoles: Entended, y ved ahora c\u00f3mo \u00e9ste no busca sino mal: pues que ha enviado \u00e1 m\u00ed por mis mujeres y mis hijos, y por mi plata y por mi oro; y yo no se lo he negado. 8\u00a0 Y todos los ancianos y todo el pueblo le respondieron: No le obedezcas, ni hagas lo que te pide. 9\u00a0 Entonces \u00e9l respondi\u00f3 \u00e1 los embajadores de Ben-adad: Decid al rey mi se\u00f1or: Har\u00e9 todo lo que mandaste \u00e1 tu siervo al principio; mas esto no lo puedo hacer. Y los embajadores fueron, y di\u00e9ronle la respuesta. 10\u00a0 Y Ben-adad torn\u00f3 \u00e1 enviarle \u00e1 decir: As\u00ed me hagan los dioses, y as\u00ed me a\u00f1adan, que el polvo de Samaria no bastar\u00e1 \u00e1 los pu\u00f1os de todo el pueblo que me sigue. 11\u00a0 Y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5183","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5183"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5183\/revisions"}],"predecessor-version":[{"id":7437,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5183\/revisions\/7437"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}