{"id":5251,"date":"2015-12-10T22:19:12","date_gmt":"2015-12-10T22:19:12","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/2ch35\/"},"modified":"2020-03-08T10:11:10","modified_gmt":"2020-03-08T14:11:10","slug":"2ch35","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/2ch35\/","title":{"rendered":"2 Cr\u00f3nicas 35"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 35<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y JOS\u00cdAS hizo pascua \u00e1 Jehov\u00e1 en Jerusalem, y sacrificaron la pascua \u00e1 los catorce del mes primero.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y puso \u00e1 los sacerdotes en sus empleos, y confirm\u00f3los en el ministerio de la casa de Jehov\u00e1.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y dijo \u00e1 los Levitas que ense\u00f1aban \u00e1 todo Israel, y que estaban dedicados \u00e1 Jehov\u00e1: Poned el arca del santuario en la casa que edific\u00f3 Salom\u00f3n hijo de David, rey de Israel, para que no la cargu\u00e9is m\u00e1s sobre los hombros. Ahora servir\u00e9is \u00e1 Jehov\u00e1 vuestro Dios, y \u00e1 su pueblo Israel.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Apercib\u00edos seg\u00fan las familias de vuestros padres, por vuestros \u00f3rdenes, conforme \u00e1 la prescripci\u00f3n de David rey de Israel, y de Salom\u00f3n su hijo.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Estad en el santuario seg\u00fan la distribuci\u00f3n de las familias de vuestros hermanos los hijos del pueblo, y <span class=\"add\">seg\u00fan<\/span> la divisi\u00f3n de la familia de los Levitas.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Sacrificad luego la pascua: y despu\u00e9s de santificaros, apercibid \u00e1 vuestros hermanos, para que hagan conforme \u00e1 la palabra de Jehov\u00e1 <span class=\"add\">dada<\/span> por mano de Mois\u00e9s.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y ofreci\u00f3 el rey Jos\u00edas \u00e1 los del pueblo ovejas, corderos, y cabritos de los reba\u00f1os, en n\u00famero de treinta mil, y tres mil bueyes, todo para la pascua, para todos los que se hallaron presentes: esto de la hacienda del rey.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Tambi\u00e9n sus pr\u00edncipes ofrecieron con liberalidad al pueblo, y \u00e1 los sacerdotes y Levitas. Hilc\u00edas, Zach\u00e2r\u00edas y Jehiel, pr\u00edncipes de la casa de Dios, dieron \u00e1 los sacerdotes para hacer la pascua dos mil seiscientas <span class=\"add\">ovejas<\/span>, y trescientos bueyes.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Asimismo Ch\u00f4nan\u00edas, y Seme\u00edas y Nathanael sus hermanos, y Hasab\u00edas, Jehiel, y Josabad, pr\u00edncipes de los Levitas, dieron \u00e1 los Levitas para los sacrificios de la pascua cinco mil <span class=\"add\">ovejas<\/span>, y quinientos bueyes.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Aprestado as\u00ed el servicio, los sacerdotes se colocaron en sus puestos, y asimismo los Levitas en sus \u00f3rdenes, conforme al mandamiento del rey.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y sacrificaron la pascua; y esparc\u00edan los sacerdotes <span class=\"add\">la sangre tomada<\/span> de mano de los Levitas, y los Levitas desollaban.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Tomaron luego del holocausto, para dar conforme \u00e1 los repartimientos por las familias de los del pueblo, \u00e1 fin de que ofreciesen \u00e1 Jehov\u00e1, seg\u00fan est\u00e1 escrito en el libro de Mois\u00e9s: y asimismo <span class=\"add\">tomaron<\/span> de los bueyes.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y asaron la pascua al fuego seg\u00fan la costumbre: mas lo que hab\u00eda sido santificado <span class=\"add\">lo<\/span> cocieron en ollas, en calderos, y calderas, y reparti\u00e9ron<span class=\"add\">lo<\/span> prestamente \u00e1 todo el pueblo.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y despu\u00e9s aderezaron para s\u00ed y para los sacerdotes; porque los sacerdotes, hijos de Aar\u00f3n, estuvieron ocupados hasta la noche en el sacrificio de los holocaustos y de los sebos; por tanto, los Levitas aderezaron para s\u00ed, y para los sacerdotes hijos de Aar\u00f3n.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Asimismo los cantores hijos de Asaph estaban en su puesto, conforme al mandamiento de David, de Asaph y de Hem\u00e1n, y de Jeduth\u00fan vidente del rey; tambi\u00e9n los porteros estaban \u00e1 cada puerta; y no era menester que se apartasen de su ministerio, porque sus hermanos los Levitas aparejaban para ellos.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> As\u00ed fu\u00e9 aprestado todo el servicio de Jehov\u00e1 en aquel d\u00eda, para hacer la pascua, y sacrificar los holocaustos sobre el altar de Jehov\u00e1, conforme al mandamiento del rey Jos\u00edas.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y los hijos de Israel que se hallaron all\u00ed, hicieron la pascua en aquel tiempo, y la solemnidad de los panes sin levadura, por siete d\u00edas.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Nunca tal pascua fu\u00e9 hecha en Israel desde los d\u00edas de Samuel el profeta; ni ning\u00fan rey de Israel hizo pascua tal como la que hizo el rey Jos\u00edas, y los sacerdotes y Levitas, y todo Jud\u00e1 \u00e9 Israel, los que se hallaron all\u00ed, juntamente con los moradores de Jerusalem.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Esta pascua fu\u00e9 celebrada en el a\u00f1o dieciocho del rey Jos\u00edas.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Despu\u00e9s de todas estas cosas, luego de haber Jos\u00edas preparado la casa, Nech\u00e2o rey de Egipto subi\u00f3 \u00e1 hacer guerra en Carch\u00eamis junto \u00e1 Eufrates; y sali\u00f3 Jos\u00edas contra \u00e9l.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y \u00e9l le envi\u00f3 embajadores, diciendo: \u00bfQu\u00e9 tenemos yo y t\u00fa, rey de Jud\u00e1? Yo no vengo contra ti hoy, sino contra la casa que me hace guerra: y Dios dijo que me apresurase. D\u00e9jate de <span class=\"add\">meterte<\/span> con Dios, que es conmigo, no te destruya.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Mas Jos\u00edas no volvi\u00f3 su rostro de \u00e9l, antes disfraz\u00f3se para darle batalla, y no atendi\u00f3 \u00e1 las palabras de Nech\u00e2o, <span class=\"add\">que eran<\/span> de boca de Dios; y vino \u00e1 darle la batalla en el campo de Megiddo.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y los archeros tiraron al rey Jos\u00edas <span class=\"add\">flechas<\/span>; y dijo el rey \u00e1 sus siervos: Quitadme de aqu\u00ed, porque estoy herido gravemente.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Entonces sus siervos lo quitaron de aquel carro, y pusi\u00e9ronle en <span class=\"add\">otro<\/span> segundo carro que ten\u00eda, y llev\u00e1ronle \u00e1 Jerusalem, y muri\u00f3; y sepult\u00e1ronle en los sepulcros de sus padres. Y todo Jud\u00e1 y Jerusalem hizo duelo por Jos\u00edas.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y endech\u00f3 Jerem\u00edas por Jos\u00edas, y todos los cantores y cantoras recitan sus lamentaciones sobre Jos\u00edas hasta hoy; y las dieron por norma <span class=\"add\">para endechar<\/span> en Israel, las cuales est\u00e1n escritas en las Lamentaciones.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Lo dem\u00e1s de los hechos de Jos\u00edas, y sus piadosas obras, conforme \u00e1 lo que est\u00e1 escrito en la ley de Jehov\u00e1,  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Y sus hechos, primeros y postreros, he aqu\u00ed est\u00e1 escrito en el libro de los reyes de Israel y de Jud\u00e1.  <\/div><hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de 2 Cr\u00f3nicas<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/2ch36\">36<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>35 1\u00a0 Y JOS\u00cdAS hizo pascua \u00e1 Jehov\u00e1 en Jerusalem, y sacrificaron la pascua \u00e1 los catorce del mes primero. 2\u00a0 Y puso \u00e1 los sacerdotes en sus empleos, y confirm\u00f3los en el ministerio de la casa de Jehov\u00e1. 3\u00a0 Y dijo \u00e1 los Levitas que ense\u00f1aban \u00e1 todo Israel, y que estaban dedicados \u00e1 Jehov\u00e1: Poned el arca del santuario en la casa que edific\u00f3 Salom\u00f3n hijo de David, rey de Israel, para que no la cargu\u00e9is m\u00e1s sobre los hombros. Ahora servir\u00e9is \u00e1 Jehov\u00e1 vuestro Dios, y \u00e1 su pueblo Israel. 4\u00a0 Apercib\u00edos seg\u00fan las familias de vuestros padres, por vuestros \u00f3rdenes, conforme \u00e1 la prescripci\u00f3n de David rey de Israel, y de Salom\u00f3n su hijo. 5\u00a0 Estad en el santuario seg\u00fan la distribuci\u00f3n de las familias de vuestros hermanos los hijos del pueblo, y seg\u00fan la divisi\u00f3n de la familia de los Levitas. 6\u00a0 Sacrificad luego la pascua: y despu\u00e9s de santificaros, apercibid \u00e1 vuestros hermanos, para que hagan conforme \u00e1 la palabra de Jehov\u00e1 dada por mano de Mois\u00e9s. 7\u00a0 Y ofreci\u00f3 el rey Jos\u00edas \u00e1 los del pueblo ovejas, corderos, y cabritos de los reba\u00f1os, en n\u00famero de treinta mil, y tres mil bueyes, todo para la pascua, para todos los que se hallaron presentes: esto de la hacienda del rey. 8\u00a0 Tambi\u00e9n sus pr\u00edncipes ofrecieron con liberalidad al pueblo, y \u00e1 los sacerdotes y Levitas. Hilc\u00edas, Zach\u00e2r\u00edas y Jehiel, pr\u00edncipes de la casa de Dios, dieron \u00e1 los sacerdotes para hacer la pascua dos mil seiscientas ovejas, y trescientos bueyes. 9\u00a0 Asimismo Ch\u00f4nan\u00edas, y Seme\u00edas y Nathanael sus hermanos, y Hasab\u00edas, Jehiel, y Josabad, pr\u00edncipes de los Levitas, dieron \u00e1 los Levitas para los sacrificios de la pascua cinco mil ovejas, y quinientos bueyes. 10\u00a0 Aprestado as\u00ed el servicio, los sacerdotes se colocaron en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5251","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5251"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5251\/revisions"}],"predecessor-version":[{"id":7516,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5251\/revisions\/7516"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}