{"id":5369,"date":"2015-12-10T22:18:27","date_gmt":"2015-12-10T22:18:27","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/exo01\/"},"modified":"2019-07-26T20:01:26","modified_gmt":"2019-07-27T00:01:26","slug":"exo01","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/exo01\/","title":{"rendered":"\u00c9xodo 1"},"content":{"rendered":"<div class=\"main\">\r\n  <div class=\"mt\">\u00c9xodo <\/div><div class=\"chapterlabel\" id=\"V0\"> 1<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> ESTOS son los nombres de los hijos de Israel, que entraron en Egipto con Jacob; cada uno entr\u00f3 con su familia.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Rub\u00e9n, Sime\u00f3n, Lev\u00ed y Jud\u00e1;  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Issach\u00e2r, Zabul\u00f3n y Benjam\u00edn;  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Dan y Nephtal\u00ed, Gad y Aser.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y todas las almas de los que salieron del muslo de Jacob, fueron setenta. Y Jos\u00e9 estaba en Egipto.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y muri\u00f3 Jos\u00e9, y todos sus hermanos, y toda aquella generaci\u00f3n.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y los hijos de Israel crecieron, y multiplicaron, y fueron aumentados y corroborados en extremo; y llen\u00f3se la tierra de ellos.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Levant\u00f3se entretanto un nuevo rey sobre Egipto, que no conoc\u00eda \u00e1 Jos\u00e9; el cual dijo \u00e1 su pueblo:  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> He aqu\u00ed, el pueblo de los hijos de Israel es mayor y m\u00e1s fuerte que nosotros:  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Ahora, pues, seamos sabios para con \u00e9l, porque no se multiplique, y acontezca que viniendo guerra, \u00e9l tambi\u00e9n se junte con nuestros enemigos, y pelee contra nosotros, y se vaya de la tierra.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Entonces pusieron sobre \u00e9l comisarios de tributos que los molestasen con sus cargas; y edificaron \u00e1 Fara\u00f3n las ciudades de los bastimentos, Phithom y Raamses.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Empero cuanto m\u00e1s los oprim\u00edan, tanto m\u00e1s se multiplicaban y crec\u00edan: as\u00ed que estaban ellos fastidiados de los hijos de Israel.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y los Egipcios hicieron servir \u00e1 los hijos de Israel con dureza:  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y amargaron su vida con dura servidumbre, en <span class=\"add\">hacer<\/span> barro y ladrillo, y en toda labor del campo, y en todo su servicio, al cual los obligaban con rigorismo.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y habl\u00f3 el rey de Egipto \u00e1 las parteras de las Hebreas, una de las cuales se llamaba Siphra, y otra Ph\u00faa, y d\u00edjoles:  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Cuando parteareis \u00e1 las Hebreas, y mirareis los asientos, si fuere hijo, matadlo; y si fuere hija, entonces viva.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Mas las parteras temieron \u00e1 Dios, y no hicieron como les mand\u00f3 el rey de Egipto, sino que reservaban la vida \u00e1 los ni\u00f1os.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Y el rey de Egipto hizo llamar \u00e1 las parteras, y d\u00edjoles: Por qu\u00e9 hab\u00e9is hecho esto, que hab\u00e9is reservado la vida \u00e1 los ni\u00f1os?  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y las parteras respondieron \u00e1 Fara\u00f3n: Porque las mujeres Hebreas no son como las Egipcias: porque son robustas, y paren antes que la partera venga \u00e1 ellas.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y Dios hizo bien \u00e1 las parteras: y el pueblo se multiplic\u00f3, y se corroboraron en gran manera.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y por haber las parteras temido \u00e1 Dios, \u00e9l les hizo casas.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Entonces Fara\u00f3n mand\u00f3 \u00e1 todo su pueblo, diciendo: Echad en el r\u00edo todo hijo que naciere, y \u00e1 toda hija reservad la vida.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de \u00c9xodo<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo40\">40<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>\u00c9xodo 1 1\u00a0 ESTOS son los nombres de los hijos de Israel, que entraron en Egipto con Jacob; cada uno entr\u00f3 con su familia. 2\u00a0 Rub\u00e9n, Sime\u00f3n, Lev\u00ed y Jud\u00e1; 3\u00a0 Issach\u00e2r, Zabul\u00f3n y Benjam\u00edn; 4\u00a0 Dan y Nephtal\u00ed, Gad y Aser. 5\u00a0 Y todas las almas de los que salieron del muslo de Jacob, fueron setenta. Y Jos\u00e9 estaba en Egipto. 6\u00a0 Y muri\u00f3 Jos\u00e9, y todos sus hermanos, y toda aquella generaci\u00f3n. 7\u00a0 Y los hijos de Israel crecieron, y multiplicaron, y fueron aumentados y corroborados en extremo; y llen\u00f3se la tierra de ellos. 8\u00a0 Levant\u00f3se entretanto un nuevo rey sobre Egipto, que no conoc\u00eda \u00e1 Jos\u00e9; el cual dijo \u00e1 su pueblo: 9\u00a0 He aqu\u00ed, el pueblo de los hijos de Israel es mayor y m\u00e1s fuerte que nosotros: 10\u00a0 Ahora, pues, seamos sabios para con \u00e9l, porque no se multiplique, y acontezca que viniendo guerra, \u00e9l tambi\u00e9n se junte con nuestros enemigos, y pelee contra nosotros, y se vaya de la tierra. 11\u00a0 Entonces pusieron sobre \u00e9l comisarios de tributos que los molestasen con sus cargas; y edificaron \u00e1 Fara\u00f3n las ciudades de los bastimentos, Phithom y Raamses. 12\u00a0 Empero cuanto m\u00e1s los oprim\u00edan, tanto m\u00e1s se multiplicaban y crec\u00edan: as\u00ed que estaban ellos fastidiados de los hijos de Israel. 13\u00a0 Y los Egipcios hicieron servir \u00e1 los hijos de Israel con dureza: 14\u00a0 Y amargaron su vida con dura servidumbre, en hacer barro y ladrillo, y en toda labor del campo, y en todo su servicio, al cual los obligaban con rigorismo. 15\u00a0 Y habl\u00f3 el rey de Egipto \u00e1 las parteras de las Hebreas, una de las cuales se llamaba Siphra, y otra Ph\u00faa, y d\u00edjoles: 16\u00a0 Cuando parteareis \u00e1 las Hebreas, y mirareis los asientos, si fuere hijo, matadlo; y si fuere hija,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5369","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5369"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5369\/revisions"}],"predecessor-version":[{"id":6906,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5369\/revisions\/6906"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}