{"id":5377,"date":"2015-12-10T22:18:45","date_gmt":"2015-12-10T22:18:45","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/exo09\/"},"modified":"2019-07-26T20:04:40","modified_gmt":"2019-07-27T00:04:40","slug":"exo09","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/exo09\/","title":{"rendered":"\u00c9xodo 9"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 9<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> ENTONCES Jehov\u00e1 dijo \u00e1 Mois\u00e9s: Entra \u00e1 Fara\u00f3n, y dile: Jehov\u00e1, el Dios de los Hebreos, dice as\u00ed: Deja ir \u00e1 mi pueblo, para que me sirvan;  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Porque si no lo quieres dejar ir, y los detuvieres a\u00fan,  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> He aqu\u00ed la mano de Jehov\u00e1 ser\u00e1 sobre tus ganados que est\u00e1n en el campo, caballos, asnos, camellos, vacas y ovejas, con pestilencia grav\u00edsima:  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y Jehov\u00e1 har\u00e1 separaci\u00f3n entre los ganados de Israel y los de Egipto, de modo que nada muera de todo lo de los hijos de Israel.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y Jehov\u00e1 se\u00f1al\u00f3 tiempo, diciendo: Ma\u00f1ana har\u00e1 Jehov\u00e1 esta cosa en la tierra.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y el d\u00eda siguiente Jehov\u00e1 hizo aquello, y muri\u00f3 todo el ganado de Egipto; mas del ganado de los hijos de Israel no muri\u00f3 uno.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Entonces Fara\u00f3n envi\u00f3, y he aqu\u00ed que del ganado de los hijos de Israel no hab\u00eda muerto uno. Mas el coraz\u00f3n de Fara\u00f3n se agrav\u00f3, y no dej\u00f3 ir al pueblo.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y Jehov\u00e1 dijo \u00e1 Mois\u00e9s y \u00e1 Aar\u00f3n: Tomad pu\u00f1ados de ceniza de un horno, y esp\u00e1rzala Mois\u00e9s hacia el cielo delante de Fara\u00f3n:  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y vendr\u00e1 \u00e1 ser polvo sobre toda la tierra de Egipto, el cual originar\u00e1 sarpullido que cause tumores apostemados en los hombres y en las bestias, por todo el pa\u00eds de Egipto.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y tomaron la ceniza del horno, y pusi\u00e9ronse delante de Fara\u00f3n, y esparci\u00f3la Mois\u00e9s hacia el cielo; y vino un sarpullido que causaba tumores apostemados as\u00ed en los hombres como en las bestias.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y los magos no pod\u00edan estar delante de Mois\u00e9s \u00e1 causa de los tumores, porque hubo sarpullido en los magos y en todos los Egipcios.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y Jehov\u00e1 endureci\u00f3 el coraz\u00f3n de Fara\u00f3n, y no los oy\u00f3; como Jehov\u00e1 lo hab\u00eda dicho \u00e1 Mois\u00e9s.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Entonces Jehov\u00e1 dijo \u00e1 Mois\u00e9s: Lev\u00e1ntate de ma\u00f1ana, y ponte delante de Fara\u00f3n, y dile: Jehov\u00e1, el Dios de los Hebreos, dice as\u00ed: Deja ir \u00e1 mi pueblo, para que me sirva.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Porque yo enviar\u00e9 esta vez todas mis plagas \u00e1 tu coraz\u00f3n, sobre tus siervos, y sobre tu pueblo, para que entiendas que no hay otro como yo en toda la tierra.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Porque ahora yo extender\u00e9 mi mano para herirte \u00e1 ti y \u00e1 tu pueblo de pestilencia, y ser\u00e1s quitado de la tierra.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y \u00e1 la verdad yo te he puesto para declarar en ti mi potencia, y que mi Nombre sea contado en toda la tierra.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> \u00bfTodav\u00eda te ensalzas t\u00fa contra mi pueblo, para no dejarlos ir?  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> He aqu\u00ed que ma\u00f1ana \u00e1 estas horas yo har\u00e9 llover granizo muy grave, cual nunca fu\u00e9 en Egipto, desde el d\u00eda que se fund\u00f3 hasta ahora.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Env\u00eda, pues, \u00e1 recoger tu ganado, y todo lo que tienes en el campo; porque todo hombre \u00f3 animal que se hallare en el campo, y no fuere recogido \u00e1 casa, el granizo descender\u00e1 sobre \u00e9l, y morir\u00e1.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> De los siervos de Fara\u00f3n el que temi\u00f3 la palabra de Jehov\u00e1, hizo huir sus criados y su ganado \u00e1 casa:  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Mas el que no puso en su coraz\u00f3n la palabra de Jehov\u00e1, dej\u00f3 sus criados y sus ganados en el campo.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y Jehov\u00e1 dijo \u00e1 Mois\u00e9s: Extiende tu mano hacia el cielo, para que venga granizo en toda la tierra de Egipto sobre los hombres, y sobre las bestias, y sobre toda la hierba del campo en el pa\u00eds de Egipto.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y Mois\u00e9s extendi\u00f3 su vara hacia el cielo, y Jehov\u00e1 hizo tronar y granizar, y el fuego discurr\u00eda por la tierra; y llovi\u00f3 Jehov\u00e1 granizo sobre la tierra de Egipto.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Hubo pues granizo, y fuego mezclado con el granizo, tan grande, cual nunca hubo en toda la tierra de Egipto desde que fu\u00e9 habitada.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y aquel granizo hiri\u00f3 en toda la tierra de Egipto todo lo que estaba en el campo, as\u00ed hombres como bestias; asimismo hiri\u00f3 el granizo toda la hierba del campo, y desgaj\u00f3 todos los \u00e1rboles del pa\u00eds.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Solamente en la tierra de Gos\u00e9n, donde los hijos de Israel estaban, no hubo granizo.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Entonces Fara\u00f3n envi\u00f3 \u00e1 llamar \u00e1 Mois\u00e9s y \u00e1 Aar\u00f3n, y les dijo: He pecado esta vez: Jehov\u00e1 es justo, y yo y mi pueblo imp\u00edos.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Orad \u00e1 Jehov\u00e1: y cesen los truenos de Dios y el granizo; y yo os dejar\u00e9 ir, y no os detendr\u00e9is m\u00e1s.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Y respondi\u00f3le Mois\u00e9s: En saliendo yo de la ciudad extender\u00e9 mis manos \u00e1 Jehov\u00e1, <span class=\"add\">y<\/span> los truenos cesar\u00e1n, y no habr\u00e1 m\u00e1s granizo; para que sepas que de Jehov\u00e1 es la tierra.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Mas yo s\u00e9 que ni t\u00fa ni tus siervos temer\u00e9is todav\u00eda la presencia del Dios Jehov\u00e1.  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> El lino, pues, y la cebada fueron heridos; porque la cebada estaba ya espigada, y el lino en ca\u00f1a.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Mas el trigo y el centeno no fueron heridos; porque eran tard\u00edos.  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Y salido Mois\u00e9s de con Fara\u00f3n de la ciudad, extendi\u00f3 sus manos \u00e1 Jehov\u00e1, y cesaron los truenos y el granizo; y la lluvia no cay\u00f3 m\u00e1s sobre la tierra.  <span class=\"verse\" id=\"V34\">34\u00a0<\/span> Y viendo Fara\u00f3n que la lluvia hab\u00eda cesado y el granizo y los truenos, persever\u00f3 en pecar, y agrav\u00f3 su coraz\u00f3n, \u00e9l y sus siervos.  <span class=\"verse\" id=\"V35\">35\u00a0<\/span> Y el coraz\u00f3n de Fara\u00f3n se endureci\u00f3, y no dej\u00f3 ir \u00e1 los hijos de Israel; como Jehov\u00e1 lo hab\u00eda dicho por medio de Mois\u00e9s.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de \u00c9xodo<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo40\">40<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>9 1\u00a0 ENTONCES Jehov\u00e1 dijo \u00e1 Mois\u00e9s: Entra \u00e1 Fara\u00f3n, y dile: Jehov\u00e1, el Dios de los Hebreos, dice as\u00ed: Deja ir \u00e1 mi pueblo, para que me sirvan; 2\u00a0 Porque si no lo quieres dejar ir, y los detuvieres a\u00fan, 3\u00a0 He aqu\u00ed la mano de Jehov\u00e1 ser\u00e1 sobre tus ganados que est\u00e1n en el campo, caballos, asnos, camellos, vacas y ovejas, con pestilencia grav\u00edsima: 4\u00a0 Y Jehov\u00e1 har\u00e1 separaci\u00f3n entre los ganados de Israel y los de Egipto, de modo que nada muera de todo lo de los hijos de Israel. 5\u00a0 Y Jehov\u00e1 se\u00f1al\u00f3 tiempo, diciendo: Ma\u00f1ana har\u00e1 Jehov\u00e1 esta cosa en la tierra. 6\u00a0 Y el d\u00eda siguiente Jehov\u00e1 hizo aquello, y muri\u00f3 todo el ganado de Egipto; mas del ganado de los hijos de Israel no muri\u00f3 uno. 7\u00a0 Entonces Fara\u00f3n envi\u00f3, y he aqu\u00ed que del ganado de los hijos de Israel no hab\u00eda muerto uno. Mas el coraz\u00f3n de Fara\u00f3n se agrav\u00f3, y no dej\u00f3 ir al pueblo. 8\u00a0 Y Jehov\u00e1 dijo \u00e1 Mois\u00e9s y \u00e1 Aar\u00f3n: Tomad pu\u00f1ados de ceniza de un horno, y esp\u00e1rzala Mois\u00e9s hacia el cielo delante de Fara\u00f3n: 9\u00a0 Y vendr\u00e1 \u00e1 ser polvo sobre toda la tierra de Egipto, el cual originar\u00e1 sarpullido que cause tumores apostemados en los hombres y en las bestias, por todo el pa\u00eds de Egipto. 10\u00a0 Y tomaron la ceniza del horno, y pusi\u00e9ronse delante de Fara\u00f3n, y esparci\u00f3la Mois\u00e9s hacia el cielo; y vino un sarpullido que causaba tumores apostemados as\u00ed en los hombres como en las bestias. 11\u00a0 Y los magos no pod\u00edan estar delante de Mois\u00e9s \u00e1 causa de los tumores, porque hubo sarpullido en los magos y en todos los Egipcios. 12\u00a0 Y Jehov\u00e1 endureci\u00f3 el coraz\u00f3n de Fara\u00f3n, y no los oy\u00f3; como Jehov\u00e1 lo hab\u00eda dicho&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5377","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5377"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5377\/revisions"}],"predecessor-version":[{"id":6908,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5377\/revisions\/6908"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}