{"id":5388,"date":"2015-12-10T22:19:09","date_gmt":"2015-12-10T22:19:09","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/exo20\/"},"modified":"2019-07-26T19:59:47","modified_gmt":"2019-07-26T23:59:47","slug":"exo20","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/exo20\/","title":{"rendered":"\u00c9xodo 20"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 20<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y HABL\u00d3 Dios todas estas palabras, diciendo:  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Yo soy JEHOV\u00c1 tu Dios, que te saqu\u00e9 de la tierra de Egipto, de casa de siervos.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> No tendr\u00e1s dioses ajenos delante de m\u00ed.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> No te har\u00e1s imagen, ni ninguna semejanza <span class=\"add\">de cosa<\/span> que est\u00e9 arriba en el cielo, ni abajo en la tierra, ni en las aguas debajo de la tierra:  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> No te inclinar\u00e1s \u00e1 ellas, ni las honrar\u00e1s; porque yo soy Jehov\u00e1 tu Dios, fuerte, celoso, que visito la maldad de los padres sobre los hijos, sobre los terceros y sobre los cuartos, \u00e1 los que me aborrecen,  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y que hago misericordia en millares \u00e1 los que me aman, y guardan mis mandamientos.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> No tomar\u00e1s el nombre de Jehov\u00e1 tu Dios en vano; porque no dar\u00e1 por inocente Jehov\u00e1 al que tomare su nombre en vano.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Acordarte has del d\u00eda del reposo, para santificarlo:  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Seis d\u00edas trabajar\u00e1s, y har\u00e1s toda tu obra;  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Mas el s\u00e9ptimo d\u00eda ser\u00e1 reposo para Jehov\u00e1 tu Dios: no hagas <span class=\"add\">en \u00e9l<\/span> obra alguna, t\u00fa, ni tu hijo, ni tu hija, ni tu siervo, ni tu criada ni tu bestia, ni tu extranjero que est\u00e1 dentro de tus puertas:  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Porque en seis d\u00edas hizo Jehov\u00e1 los cielos y la tierra, la mar y todas las cosas que en ellos hay, y repos\u00f3 en el s\u00e9ptimo d\u00eda: por tanto Jehov\u00e1 bendijo el d\u00eda del reposo y lo santific\u00f3.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Honra \u00e1 tu padre y \u00e1 tu madre, porque tus d\u00edas se alarguen en la tierra que Jehov\u00e1 tu Dios te da.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> No matar\u00e1s.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> No cometer\u00e1s adulterio.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> No hurtar\u00e1s.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> No hablar\u00e1s contra tu pr\u00f3jimo falso testimonio.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> No codiciar\u00e1s la casa de tu pr\u00f3jimo, no codiciar\u00e1s la mujer de tu pr\u00f3jimo, ni su siervo, ni su criada, ni su buey, ni su asno, ni cosa alguna de tu pr\u00f3jimo.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Todo el pueblo consideraba las voces, y las llamas, y el sonido de la bocina, y el monte que humeaba: y vi\u00e9ndolo el pueblo, temblaron, y pusi\u00e9ronse de lejos.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y dijeron \u00e1 Mois\u00e9s: Habla t\u00fa con nosotros, que nosotros oiremos; mas no hable Dios con nosotros, porque no muramos.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y Mois\u00e9s respondi\u00f3 al pueblo: No tem\u00e1is; que por probaros vino Dios, y porque su temor est\u00e9 en vuestra presencia para que no pequ\u00e9is.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Entonces el pueblo se puso de lejos, y Mois\u00e9s se lleg\u00f3 \u00e1 la osbcuridad, en la cual estaba Dios.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y Jehov\u00e1 dijo \u00e1 Mois\u00e9s: As\u00ed dir\u00e1s \u00e1 los hijos de Israel: Vosotros hab\u00e9is visto que he hablado desde el cielo con vosotros.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> No hag\u00e1is conmigo dioses de plata, ni dioses de oro os har\u00e9is.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Altar de tierra har\u00e1s para m\u00ed, y sacrificar\u00e1s sobre \u00e9l tus holocaustos y tus pac\u00edficos, tus ovejas y tus vacas: en cualquier lugar donde yo hiciere que est\u00e9 la memoria de mi nombre, vendr\u00e9 \u00e1 ti, y te bendecir\u00e9.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y si me hicieres altar de piedras, no las labres de canter\u00eda; porque si alzares tu pico sobre \u00e9l, t\u00fa lo profanar\u00e1s.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y no subir\u00e1s por gradas \u00e1 mi altar, porque tu desnudez no sea junto \u00e1 \u00e9l descubierta.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de \u00c9xodo<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo40\">40<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>20 1\u00a0 Y HABL\u00d3 Dios todas estas palabras, diciendo: 2\u00a0 Yo soy JEHOV\u00c1 tu Dios, que te saqu\u00e9 de la tierra de Egipto, de casa de siervos. 3\u00a0 No tendr\u00e1s dioses ajenos delante de m\u00ed. 4\u00a0 No te har\u00e1s imagen, ni ninguna semejanza de cosa que est\u00e9 arriba en el cielo, ni abajo en la tierra, ni en las aguas debajo de la tierra: 5\u00a0 No te inclinar\u00e1s \u00e1 ellas, ni las honrar\u00e1s; porque yo soy Jehov\u00e1 tu Dios, fuerte, celoso, que visito la maldad de los padres sobre los hijos, sobre los terceros y sobre los cuartos, \u00e1 los que me aborrecen, 6\u00a0 Y que hago misericordia en millares \u00e1 los que me aman, y guardan mis mandamientos. 7\u00a0 No tomar\u00e1s el nombre de Jehov\u00e1 tu Dios en vano; porque no dar\u00e1 por inocente Jehov\u00e1 al que tomare su nombre en vano. 8\u00a0 Acordarte has del d\u00eda del reposo, para santificarlo: 9\u00a0 Seis d\u00edas trabajar\u00e1s, y har\u00e1s toda tu obra; 10\u00a0 Mas el s\u00e9ptimo d\u00eda ser\u00e1 reposo para Jehov\u00e1 tu Dios: no hagas en \u00e9l obra alguna, t\u00fa, ni tu hijo, ni tu hija, ni tu siervo, ni tu criada ni tu bestia, ni tu extranjero que est\u00e1 dentro de tus puertas: 11\u00a0 Porque en seis d\u00edas hizo Jehov\u00e1 los cielos y la tierra, la mar y todas las cosas que en ellos hay, y repos\u00f3 en el s\u00e9ptimo d\u00eda: por tanto Jehov\u00e1 bendijo el d\u00eda del reposo y lo santific\u00f3. 12\u00a0 Honra \u00e1 tu padre y \u00e1 tu madre, porque tus d\u00edas se alarguen en la tierra que Jehov\u00e1 tu Dios te da. 13\u00a0 No matar\u00e1s. 14\u00a0 No cometer\u00e1s adulterio. 15\u00a0 No hurtar\u00e1s. 16\u00a0 No hablar\u00e1s contra tu pr\u00f3jimo falso testimonio. 17\u00a0 No codiciar\u00e1s la casa de tu pr\u00f3jimo, no codiciar\u00e1s la mujer de tu pr\u00f3jimo, ni su&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5388","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5388"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5388\/revisions"}],"predecessor-version":[{"id":6895,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5388\/revisions\/6895"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}