{"id":5393,"date":"2015-12-10T22:18:40","date_gmt":"2015-12-10T22:18:40","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/exo25\/"},"modified":"2019-07-26T19:59:01","modified_gmt":"2019-07-26T23:59:01","slug":"exo25","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/exo25\/","title":{"rendered":"\u00c9xodo 25"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 25<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y JEHOV\u00c1 habl\u00f3 \u00e1 Mois\u00e9s, diciendo:  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Di \u00e1 los hijos de Israel que tomen para m\u00ed ofrenda: de todo var\u00f3n que la diere de su voluntad, de coraz\u00f3n, tomar\u00e9is mi ofrenda.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y esta es la ofrenda que tomar\u00e9is de ellos: Oro, y plata, y cobre,  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y jacinto, y p\u00farpura, y carmes\u00ed, y lino fino, y <span class=\"add\">pelo<\/span> de cabras,  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y cueros de carneros te\u00f1idos de rojo, y cueros de tejones, y madera de Sittim;  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Aceite para la luminaria, especias para el aceite de la unci\u00f3n, y para el sahumerio arom\u00e1tico;  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Piedras de onix, y piedras de engastes, para el ephod, y para el racional.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y hacerme han un santuario, y yo habitar\u00e9 entre ellos.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Conforme \u00e1 todo lo que yo te mostrare, el dise\u00f1o del tabern\u00e1culo, y el dise\u00f1o de todos sus vasos, as\u00ed lo har\u00e9is.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Har\u00e1n tambi\u00e9n un arca de madera de Sittim, cuya longitud ser\u00e1 de dos codos y medio, y su anchura de codo y medio, y su altura de codo y medio.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y la cubrir\u00e1s de oro puro; por dentro y por fuera la cubrir\u00e1s; y har\u00e1s sobre ella una cornisa de oro alrededor.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y para ella har\u00e1s de fundici\u00f3n cuatro anillos de oro, que pondr\u00e1s \u00e1 sus cuatro esquinas; dos anillos al un lado de ella, y dos anillos al otro lado.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y har\u00e1s unas varas de madera de Sittim, las cuales cubrir\u00e1s de oro:  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y meter\u00e1s las varas por los anillos \u00e1 los lados del arca, para llevar el arca con ellas.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Las varas se estar\u00e1n en los anillos del arca: no se quitar\u00e1n de ella.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y pondr\u00e1s en el arca el testimonio que yo te dar\u00e9.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y har\u00e1s una cubierta de oro fino, cuya longitud <span class=\"add\">ser\u00e1<\/span> de dos codos y medio, y su anchura de codo y medio.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Har\u00e1s tambi\u00e9n dos querubines de oro, labrados \u00e1 martillo los har\u00e1s, en los dos cabos de la cubierta.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Har\u00e1s, pues, un querub\u00edn al extremo de un lado, y un querub\u00edn al otro extremo del lado opuesto: de la calidad de la cubierta har\u00e1s los querubines en sus dos extremidades.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y los querubines extender\u00e1n por encima las alas, cubriendo con sus alas la cubierta: sus caras la una enfrente de la otra, mirando \u00e1 la cubierta las caras de los querubines.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y pondr\u00e1s la cubierta encima del arca, y en el arca pondr\u00e1s el testimonio que yo te dar\u00e9.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y de all\u00ed me declarar\u00e9 \u00e1 ti, y hablar\u00e9 contigo de sobre la cubierta, de entre los dos querubines que est\u00e1n sobre el arca del testimonio, todo lo que yo te mandar\u00e9 para los hijos de Israel.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Har\u00e1s asimismo una mesa de madera de Sittim: su longitud ser\u00e1 de dos codos, y de un codo su anchura, y su altura de codo y medio.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y la cubrir\u00e1s de oro puro, y le has de hacer una cornisa de oro alrededor.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Hacerle has tambi\u00e9n una moldura alrededor, del ancho de una mano, \u00e1 la cual moldura har\u00e1s una cornisa de oro en circunferencia.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y le har\u00e1s cuatro anillos de oro, los cuales pondr\u00e1s \u00e1 las cuatro esquinas que corresponden \u00e1 sus cuatro pies.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Los anillos estar\u00e1n antes de la moldura, por lugares de las varas, para llevar la mesa.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Y har\u00e1s las varas de madera de Sittim, y las cubrir\u00e1s de oro, y con ellas ser\u00e1 llevada la mesa.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Har\u00e1s tambi\u00e9n sus platos, y sus cucharas, y sus cubiertas, y sus tazones, con que se libar\u00e1: de oro fino los har\u00e1s.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Y pondr\u00e1s sobre la mesa el pan de la proposici\u00f3n delante de m\u00ed continuamente.  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Har\u00e1s adem\u00e1s un candelero de oro puro; labrado \u00e1 martillo se har\u00e1 el candelero: su pie, y su ca\u00f1a, sus copas, sus manzanas, y sus flores, ser\u00e1n de lo mismo:  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Y saldr\u00e1n seis brazos de sus lados: tres brazos del candelero del un lado suyo, y tres brazos del candelero del otro su lado:  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Tres copas en forma de almendras en el un brazo, una manzana y una flor; y tres copas, figura de almendras, en el otro brazo, una manzana y una flor: as\u00ed pues, en los seis brazos que salen del candelero:  <span class=\"verse\" id=\"V34\">34\u00a0<\/span> Y en el candelero cuatro copas en forma de almendras, sus manzanas y sus flores.  <span class=\"verse\" id=\"V35\">35\u00a0<\/span> Habr\u00e1 una manzana debajo de los dos brazos de lo mismo, otra manzana debajo de los otros dos brazos de lo mismo, y otra manzana debajo de los <span class=\"add\">otros<\/span> dos brazos de lo mismo, en conformidad \u00e1 los seis brazos que salen del candelero.  <span class=\"verse\" id=\"V36\">36\u00a0<\/span> Sus manzanas y sus brazos ser\u00e1n de lo mismo, todo ello una pieza labrada \u00e1 martillo, de oro puro.  <span class=\"verse\" id=\"V37\">37\u00a0<\/span> Y hacerle has siete candilejas, las cuales encender\u00e1s para que alumbren \u00e1 la parte de su delantera:  <span class=\"verse\" id=\"V38\">38\u00a0<\/span> Tambi\u00e9n sus despabiladeras y sus platillos, de oro puro.  <span class=\"verse\" id=\"V39\">39\u00a0<\/span> De un talento de oro fino lo har\u00e1s, con todos estos vasos.  <span class=\"verse\" id=\"V40\">40\u00a0<\/span> Y mira, y hazlos conforme \u00e1 su modelo, que te ha sido mostrado en el monte.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de \u00c9xodo<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo40\">40<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>25 1\u00a0 Y JEHOV\u00c1 habl\u00f3 \u00e1 Mois\u00e9s, diciendo: 2\u00a0 Di \u00e1 los hijos de Israel que tomen para m\u00ed ofrenda: de todo var\u00f3n que la diere de su voluntad, de coraz\u00f3n, tomar\u00e9is mi ofrenda. 3\u00a0 Y esta es la ofrenda que tomar\u00e9is de ellos: Oro, y plata, y cobre, 4\u00a0 Y jacinto, y p\u00farpura, y carmes\u00ed, y lino fino, y pelo de cabras, 5\u00a0 Y cueros de carneros te\u00f1idos de rojo, y cueros de tejones, y madera de Sittim; 6\u00a0 Aceite para la luminaria, especias para el aceite de la unci\u00f3n, y para el sahumerio arom\u00e1tico; 7\u00a0 Piedras de onix, y piedras de engastes, para el ephod, y para el racional. 8\u00a0 Y hacerme han un santuario, y yo habitar\u00e9 entre ellos. 9\u00a0 Conforme \u00e1 todo lo que yo te mostrare, el dise\u00f1o del tabern\u00e1culo, y el dise\u00f1o de todos sus vasos, as\u00ed lo har\u00e9is. 10\u00a0 Har\u00e1n tambi\u00e9n un arca de madera de Sittim, cuya longitud ser\u00e1 de dos codos y medio, y su anchura de codo y medio, y su altura de codo y medio. 11\u00a0 Y la cubrir\u00e1s de oro puro; por dentro y por fuera la cubrir\u00e1s; y har\u00e1s sobre ella una cornisa de oro alrededor. 12\u00a0 Y para ella har\u00e1s de fundici\u00f3n cuatro anillos de oro, que pondr\u00e1s \u00e1 sus cuatro esquinas; dos anillos al un lado de ella, y dos anillos al otro lado. 13\u00a0 Y har\u00e1s unas varas de madera de Sittim, las cuales cubrir\u00e1s de oro: 14\u00a0 Y meter\u00e1s las varas por los anillos \u00e1 los lados del arca, para llevar el arca con ellas. 15\u00a0 Las varas se estar\u00e1n en los anillos del arca: no se quitar\u00e1n de ella. 16\u00a0 Y pondr\u00e1s en el arca el testimonio que yo te dar\u00e9. 17\u00a0 Y har\u00e1s una cubierta de oro fino, cuya longitud ser\u00e1&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5393","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5393"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5393\/revisions"}],"predecessor-version":[{"id":6890,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5393\/revisions\/6890"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}