{"id":5395,"date":"2015-12-10T22:18:56","date_gmt":"2015-12-10T22:18:56","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/exo27\/"},"modified":"2019-07-26T20:07:53","modified_gmt":"2019-07-27T00:07:53","slug":"exo27","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/exo27\/","title":{"rendered":"\u00c9xodo 27"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 27<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> HAR\u00c1S tambi\u00e9n altar de madera de Sittim de cinco codos de longitud, y de cinco codos de anchura: ser\u00e1 cuadrado el altar, y su altura de tres codos.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y har\u00e1s sus cuernos \u00e1 sus cuatro esquinas; los cuernos ser\u00e1n de lo mismo; y lo cubrir\u00e1s de metal.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Har\u00e1s tambi\u00e9n sus calderas para echar su ceniza; y sus paletas, y sus tazones, y sus garfios, y sus braseros: har\u00e1s todos sus vasos de metal.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y le har\u00e1s un enrejado de metal de obra de malla; y sobre el enrejado har\u00e1s cuatro anillos de metal \u00e1 sus cuatro esquinas.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y lo has de poner dentro del cerco del altar abajo; y llegar\u00e1 el enrejado hasta el medio del altar.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Har\u00e1s tambi\u00e9n varas para el altar, varas de madera de Sittim, las cuales cubrir\u00e1s de metal.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y sus varas se meter\u00e1n por los anillos: y estar\u00e1n aquellas varas \u00e1 ambos lados del altar, cuando hubiere de ser llevado.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> De tablas lo har\u00e1s, hueco: de la manera que te fu\u00e9 mostrado en el monte, as\u00ed lo har\u00e1s.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Asimismo har\u00e1s el atrio del tabern\u00e1culo: al lado del mediod\u00eda, al austro, tendr\u00e1 el atrio cortinas de lino torcido, de cien codos de longitud cada un lado;  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Sus veinte columnas, y sus veinte basas ser\u00e1n de metal; los capiteles de las columnas y sus molduras, de plata.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y de la misma manera al lado del aquil\u00f3n habr\u00e1 \u00e1 lo largo cortinas de cien codos de longitud, y sus veinte columnas, con sus veinte basas de metal; los capiteles de sus columnas y sus molduras, de plata.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y el ancho del atrio del lado occidental tendr\u00e1 cortinas de cincuenta codos; sus columnas diez, con sus diez basas.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y en el ancho del atrio por la parte de levante, al oriente, habr\u00e1 cincuenta codos.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y las cortinas del un lado ser\u00e1n de quince codos; sus columnas tres, con sus tres basas.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Al otro lado quince codos de cortinas; sus columnas tres, con sus tres basas.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y \u00e1 la puerta del atrio habr\u00e1 un pabell\u00f3n de veinte codos, de c\u00e1rdeno, y p\u00farpura, y carmes\u00ed, y lino torcido, de obra de bordador: sus columnas cuatro, con sus cuatro basas.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Todas las columnas del atrio en derredor ser\u00e1n ce\u00f1idas de plata; sus capiteles de plata, y sus basas de metal.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> La longitud del atrio ser\u00e1 de cien codos, y la anchura cincuenta por un lado y cincuenta por el otro, y la altura de cinco codos: <span class=\"add\">sus cortinas<\/span> de lino torcido, y sus basas de metal.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Todos los vasos del tabern\u00e1culo en todo su servicio, y todos sus clavos, y todos los clavos del atrio, ser\u00e1n de metal.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y t\u00fa mandar\u00e1s \u00e1 los hijos de Israel que te traigan aceite puro de olivas, molido, para la luminaria, para hacer arder continuamente las l\u00e1mparas.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> En el tabern\u00e1culo del testimonio, afuera del velo que est\u00e1 delante del testimonio, las pondr\u00e1 en orden Aar\u00f3n y sus hijos, delante de Jehov\u00e1 desde la tarde hasta la ma\u00f1ana, como estatuto perpetuo de los hijos de Israel por sus generaciones.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de \u00c9xodo<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo40\">40<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>27 1\u00a0 HAR\u00c1S tambi\u00e9n altar de madera de Sittim de cinco codos de longitud, y de cinco codos de anchura: ser\u00e1 cuadrado el altar, y su altura de tres codos. 2\u00a0 Y har\u00e1s sus cuernos \u00e1 sus cuatro esquinas; los cuernos ser\u00e1n de lo mismo; y lo cubrir\u00e1s de metal. 3\u00a0 Har\u00e1s tambi\u00e9n sus calderas para echar su ceniza; y sus paletas, y sus tazones, y sus garfios, y sus braseros: har\u00e1s todos sus vasos de metal. 4\u00a0 Y le har\u00e1s un enrejado de metal de obra de malla; y sobre el enrejado har\u00e1s cuatro anillos de metal \u00e1 sus cuatro esquinas. 5\u00a0 Y lo has de poner dentro del cerco del altar abajo; y llegar\u00e1 el enrejado hasta el medio del altar. 6\u00a0 Har\u00e1s tambi\u00e9n varas para el altar, varas de madera de Sittim, las cuales cubrir\u00e1s de metal. 7\u00a0 Y sus varas se meter\u00e1n por los anillos: y estar\u00e1n aquellas varas \u00e1 ambos lados del altar, cuando hubiere de ser llevado. 8\u00a0 De tablas lo har\u00e1s, hueco: de la manera que te fu\u00e9 mostrado en el monte, as\u00ed lo har\u00e1s. 9\u00a0 Asimismo har\u00e1s el atrio del tabern\u00e1culo: al lado del mediod\u00eda, al austro, tendr\u00e1 el atrio cortinas de lino torcido, de cien codos de longitud cada un lado; 10\u00a0 Sus veinte columnas, y sus veinte basas ser\u00e1n de metal; los capiteles de las columnas y sus molduras, de plata. 11\u00a0 Y de la misma manera al lado del aquil\u00f3n habr\u00e1 \u00e1 lo largo cortinas de cien codos de longitud, y sus veinte columnas, con sus veinte basas de metal; los capiteles de sus columnas y sus molduras, de plata. 12\u00a0 Y el ancho del atrio del lado occidental tendr\u00e1 cortinas de cincuenta codos; sus columnas diez, con sus diez basas. 13\u00a0 Y en el ancho del atrio por&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5395","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5395"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5395\/revisions"}],"predecessor-version":[{"id":6928,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5395\/revisions\/6928"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}