{"id":5404,"date":"2015-12-10T22:19:03","date_gmt":"2015-12-10T22:19:03","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/exo36\/"},"modified":"2019-07-26T20:06:07","modified_gmt":"2019-07-27T00:06:07","slug":"exo36","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/exo36\/","title":{"rendered":"\u00c9xodo 36"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 36<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> HIZO, pues, Bezaleel y Aholiab, y todo hombre sabio de coraz\u00f3n, \u00e1 quien Jehov\u00e1 di\u00f3 sabidur\u00eda \u00e9 inteligencia para que supiesen hacer toda la obra del servicio del santuario, todas las cosas que hab\u00eda mandado Jehov\u00e1.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y Mois\u00e9s llam\u00f3 \u00e1 Bezaleel y \u00e1 Aholiab, y \u00e1 todo var\u00f3n sabio de coraz\u00f3n, en cuyo coraz\u00f3n hab\u00eda dado Jehov\u00e1 sabidur\u00eda, y \u00e1 todo hombre \u00e1 quien su coraz\u00f3n le movi\u00f3 \u00e1 llegarse \u00e1 la obra, para trabajar en ella;  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y tomaron de delante de Mois\u00e9s toda la ofrenda que los hijos de Israel hab\u00edan tra\u00eddo para la obra del servicio del santuario, \u00e1 fin de hacerla. Y ellos le tra\u00edan a\u00fan ofrenda voluntaria cada ma\u00f1ana.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Vinieron, por tanto, todos los maestros que hac\u00edan toda la obra del santuario, cada uno de la obra que hac\u00eda.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y hablaron \u00e1 Mois\u00e9s, diciendo: El pueblo trae mucho m\u00e1s de lo que es menester para la atenci\u00f3n de hacer la obra que Jehov\u00e1 ha mandado que se haga.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Entonces Mois\u00e9s mand\u00f3 pregonar por el campo, diciendo: Ning\u00fan hombre ni mujer haga m\u00e1s obra para ofrecer para el santuario. Y as\u00ed fu\u00e9 el pueblo impedido de ofrecer;  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Pues ten\u00eda material abundante para hacer toda la obra, y sobraba.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y todos los sabios de coraz\u00f3n entre los que hac\u00edan la obra, hicieron el tabern\u00e1culo de diez cortinas, de lino torcido, y de jacinto, y de p\u00farpura y carmes\u00ed; las cuales hicieron de obra prima, con querubines.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> La longitud de la una cortina era de veintiocho codos, y la anchura de cuatro codos: todas las cortinas ten\u00edan una misma medida.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y junt\u00f3 las cinco cortinas la una con la otra: asimismo uni\u00f3 las otras cinco cortinas la una con la otra.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> E hizo las lazadas de color de jacinto en la orilla de la una cortina, en el borde, \u00e1 la juntura; y as\u00ed hizo en la orilla al borde de la segunda cortina, en la juntura.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Cincuenta lazadas hizo en la una cortina, y otras cincuenta en la segunda cortina, en el borde, en la juntura; las unas lazadas enfrente de las otras.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Hizo tambi\u00e9n cincuenta corchetes de oro, con los cuales junt\u00f3 las cortinas, la una con la otra; \u00e9 h\u00edzose un tabern\u00e1culo.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Hizo asimismo cortinas de <span class=\"add\">pelo<\/span> de cabras para la tienda sobre el tabern\u00e1culo, \u00e9 h\u00edzolas <span class=\"add\">en n\u00famero<\/span> de once.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> La longitud de la una cortina era de treinta codos, y la anchura de cuatro codos: las once cortinas ten\u00edan una misma medida.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y junt\u00f3 las cinco cortinas de por s\u00ed, y las seis cortinas aparte.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Hizo adem\u00e1s cincuenta lazadas en la orilla de la postrera cortina en la juntura, y otras cincuenta lazadas en la orilla de la otra cortina en la juntura.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Hizo tambi\u00e9n cincuenta corchetes de metal para juntar la tienda, de modo que fuese una.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> E hizo una cubierta para la tienda de cueros rojos de carneros, y una cubierta encima de cueros de tejones.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Adem\u00e1s hizo las tablas para el tabern\u00e1culo de madera de Sittim, para estar derechas.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> La longitud de cada tabla de diez codos, y de codo y medio la anchura.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Cada tabla ten\u00eda dos quicios enclavijados el uno delante del otro: as\u00ed hizo todas las tablas del tabern\u00e1culo.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Hizo, pues, las tablas para el tabern\u00e1culo: veinte tablas al lado del austro, al mediod\u00eda.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Hizo tambi\u00e9n las cuarenta basas de plata debajo de las veinte tablas: dos basas debajo de la una tabla para sus dos quicios, y dos basas debajo de la otra tabla para sus dos quicios.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y para el otro lado del tabern\u00e1culo, \u00e1 la parte del aquil\u00f3n, hizo veinte tablas,  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Con sus cuarenta basas de plata: dos basas debajo de la una tabla, y dos basas debajo de la otra tabla.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Y para el lado occidental del tabern\u00e1culo hizo seis tablas.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Para las esquinas del tabern\u00e1culo en los dos lados hizo dos tablas,  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Las cuales se juntaban por abajo, y asimismo por arriba \u00e1 un gozne: y as\u00ed hizo \u00e1 la una y \u00e1 la otra en las dos esquinas.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Eran, pues, ocho tablas, y sus basas de plata diecis\u00e9is; dos basas debajo de cada tabla.  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Hizo tambi\u00e9n las barras de madera de Sittim; cinco para las tablas del un lado del tabern\u00e1culo,  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Y cinco barras para las tablas del otro lado del tabern\u00e1culo, y cinco barras para las tablas del lado del tabern\u00e1culo \u00e1 la parte occidental.  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> E hizo que la barra del medio pasase por medio de las tablas del un cabo al otro.  <span class=\"verse\" id=\"V34\">34\u00a0<\/span> Y cubri\u00f3 las tablas de oro, \u00e9 hizo de oro los anillos de ellas por donde pasasen las barras: cubri\u00f3 tambi\u00e9n de oro las barras.  <span class=\"verse\" id=\"V35\">35\u00a0<\/span> Hizo asimismo el velo de c\u00e1rdeno, y p\u00farpura, y carmes\u00ed, y lino torcido, el cual hizo con querubines de delicada obra.  <span class=\"verse\" id=\"V36\">36\u00a0<\/span> Y para \u00e9l hizo cuatro columnas de madera de Sittim; y cubri\u00f3las de oro, los capiteles de las cuales eran de oro; \u00e9 hizo para ellas cuatro basas de plata de fundici\u00f3n.  <span class=\"verse\" id=\"V37\">37\u00a0<\/span> Hizo tambi\u00e9n el velo para la puerta del tabern\u00e1culo, de jacinto, y p\u00farpura, y carmes\u00ed, y lino torcido, obra de recamador;  <span class=\"verse\" id=\"V38\">38\u00a0<\/span> Y sus cinco columnas con sus capiteles: y cubri\u00f3 las cabezas de ellas y sus molduras de oro: pero sus cinco basas las hizo de metal.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de \u00c9xodo<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/exo40\">40<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>36 1\u00a0 HIZO, pues, Bezaleel y Aholiab, y todo hombre sabio de coraz\u00f3n, \u00e1 quien Jehov\u00e1 di\u00f3 sabidur\u00eda \u00e9 inteligencia para que supiesen hacer toda la obra del servicio del santuario, todas las cosas que hab\u00eda mandado Jehov\u00e1. 2\u00a0 Y Mois\u00e9s llam\u00f3 \u00e1 Bezaleel y \u00e1 Aholiab, y \u00e1 todo var\u00f3n sabio de coraz\u00f3n, en cuyo coraz\u00f3n hab\u00eda dado Jehov\u00e1 sabidur\u00eda, y \u00e1 todo hombre \u00e1 quien su coraz\u00f3n le movi\u00f3 \u00e1 llegarse \u00e1 la obra, para trabajar en ella; 3\u00a0 Y tomaron de delante de Mois\u00e9s toda la ofrenda que los hijos de Israel hab\u00edan tra\u00eddo para la obra del servicio del santuario, \u00e1 fin de hacerla. Y ellos le tra\u00edan a\u00fan ofrenda voluntaria cada ma\u00f1ana. 4\u00a0 Vinieron, por tanto, todos los maestros que hac\u00edan toda la obra del santuario, cada uno de la obra que hac\u00eda. 5\u00a0 Y hablaron \u00e1 Mois\u00e9s, diciendo: El pueblo trae mucho m\u00e1s de lo que es menester para la atenci\u00f3n de hacer la obra que Jehov\u00e1 ha mandado que se haga. 6\u00a0 Entonces Mois\u00e9s mand\u00f3 pregonar por el campo, diciendo: Ning\u00fan hombre ni mujer haga m\u00e1s obra para ofrecer para el santuario. Y as\u00ed fu\u00e9 el pueblo impedido de ofrecer; 7\u00a0 Pues ten\u00eda material abundante para hacer toda la obra, y sobraba. 8\u00a0 Y todos los sabios de coraz\u00f3n entre los que hac\u00edan la obra, hicieron el tabern\u00e1culo de diez cortinas, de lino torcido, y de jacinto, y de p\u00farpura y carmes\u00ed; las cuales hicieron de obra prima, con querubines. 9\u00a0 La longitud de la una cortina era de veintiocho codos, y la anchura de cuatro codos: todas las cortinas ten\u00edan una misma medida. 10\u00a0 Y junt\u00f3 las cinco cortinas la una con la otra: asimismo uni\u00f3 las otras cinco cortinas la una con la otra. 11\u00a0 E hizo las lazadas de color&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5404","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5404"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5404\/revisions"}],"predecessor-version":[{"id":6918,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5404\/revisions\/6918"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}