{"id":5409,"date":"2015-12-10T22:18:39","date_gmt":"2015-12-10T22:18:39","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/ezk01\/"},"modified":"2019-07-27T11:00:48","modified_gmt":"2019-07-27T15:00:48","slug":"ezk01","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/ezk01\/","title":{"rendered":"Ezequiel 1"},"content":{"rendered":"<div class=\"main\">\r\n  <div class=\"mt\">Ezequiel  <\/div><div class=\"chapterlabel\" id=\"V0\"> 1<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y FU\u00c9 <span class=\"add\">que<\/span> \u00e1 los treinta a\u00f1os, en el <span class=\"add\">mes<\/span> cuarto, \u00e1 cinco del mes, estando yo en medio de los trasportados junto al r\u00edo de Chebar, los cielos se abrieron, y vi visiones de Dios.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> A los cinco del mes, que fu\u00e9 en el quinto a\u00f1o de la transmigraci\u00f3n del rey Joach\u00een,  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Fu\u00e9 palabra de Jehov\u00e1 \u00e1 Ezequiel sacerdote, hijo de Buzi, en la tierra de los Caldeos, junto al r\u00edo de Chebar; fu\u00e9 all\u00ed sobre \u00e9l la mano de Jehov\u00e1.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y mir\u00e9, y he aqu\u00ed un viento tempestuoso ven\u00eda del aquil\u00f3n, una gran nube, con un fuego envolvente, y en derredor suyo un resplandor, y en medio del fuego una cosa que parec\u00eda como de \u00e1mbar,  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y en medio de ella, figura de cuatro animales. Y este era su parecer; hab\u00eda en ellos semejanza de hombre.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y cada uno ten\u00eda cuatro rostros, y cuatro alas.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y los pies de ellos eran derechos, y la planta de sus pies como la planta de pie de becerro; y centelleaban \u00e1 manera de bronce muy bru\u00f1ido.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y debajo de sus alas, \u00e1 sus cuatro lados, ten\u00edan manos de hombre; y sus rostros y sus alas por los cuatro lados.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Con las alas se juntaban el uno al otro. No se volv\u00edan cuando andaban; cada uno caminaba en derecho de su rostro.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y la figura de sus rostros era rostro de hombre; y rostro de le\u00f3n \u00e1 la parte derecha en los cuatro; y \u00e1 la izquierda rostro de buey en los cuatro; asimismo hab\u00eda en los cuatro rostro de \u00e1guila.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> <span class=\"add\">Tales eran<\/span> sus rostros; y <span class=\"add\">ten\u00edan<\/span> sus alas extendidas por encima, cada uno dos, las cuales se juntaban; y las otras dos cubr\u00edan sus cuerpos.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y cada uno caminaba en derecho de su rostro: hacia donde el esp\u00edritu era que anduviesen, andaban; cuando andaban, no se volv\u00edan.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Cuanto \u00e1 la semejanza de los animales, su parecer era como de carbones de fuego encendidos, como parecer de hachones <span class=\"add\">encendidos<\/span>: discurr\u00eda entre los animales; y el fuego resplandec\u00eda, y del fuego sal\u00edan rel\u00e1mpagos.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y los animales corr\u00edan y tornaban \u00e1 semejanza de rel\u00e1mpagos.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y estando yo mirando los animales, he aqu\u00ed una rueda en la tierra junto \u00e1 los animales, \u00e1 sus cuatro caras.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y el parecer de las ruedas y su obra semej\u00e1base al color del topacio. Y las cuatro ten\u00edan una misma semejanza: su apariencia y su obra como rueda en medio de rueda.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Cuando andaban, se mov\u00edan sobre sus cuatro costados: no se volv\u00edan cuando andaban.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Y sus cercos eran altos y espantosos, y llenos de ojos alrededor en las cuatro.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y cuando los animales andaban, las ruedas andaban junto \u00e1 ellos: y cuando los animales se levantaban de la tierra, las ruedas se levantaban.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Hacia donde el esp\u00edritu era que anduviesen, andaban; hacia donde era el esp\u00edritu que anduviesen, las ruedas tambi\u00e9n se levantaban tras ellos; porque el esp\u00edritu de los animales estaba en las ruedas.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Cuando ellos andaban, andaban ellas; y cuando ellos se paraban, se paraban ellas; asimismo cuando se levantaban de la tierra, las ruedas se levantaban tras ellos; porque el esp\u00edritu de los animales estaba en las ruedas.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y sobre las cabezas de cada animal aparec\u00eda expansi\u00f3n \u00e1 manera de cristal maravilloso, extendido encima sobre sus cabezas.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y debajo de la expansi\u00f3n estaban las alas de ellos derechas la una \u00e1 la otra; \u00e1 cada uno dos, y otras dos con que se cubr\u00edan sus cuerpos.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y o\u00ed el sonido de sus alas cuando andaban, como sonido de muchas aguas, como la voz del Omnipotente, como ruido de muchedumbre, como la voz de un ej\u00e9rcito. Cuando se paraban, aflojaban sus alas.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y cuando se paraban <span class=\"add\">y<\/span> aflojaban sus alas, o\u00edase voz de arriba de la expansi\u00f3n que hab\u00eda sobre sus cabezas.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y sobre la expansi\u00f3n que hab\u00eda sobre sus cabezas, <span class=\"add\">ve\u00edase<\/span> la figura de un trono que parec\u00eda de piedra de zafiro; y sobre la figura del trono hab\u00eda una semejanza que parec\u00eda de hombre sentado sobre \u00e9l.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Y vi apariencia como de \u00e1mbar, como apariencia de fuego dentro de ella en contorno, por el aspecto de sus lomos para arriba; y desde sus lomos para abajo, vi que parec\u00eda como fuego, y que ten\u00eda resplandor alrededor.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Cual parece el arco del cielo que est\u00e1 en las nubes el d\u00eda que llueve, as\u00ed era el parecer del resplandor alrededor. Esta fu\u00e9 la visi\u00f3n de la semejanza de la gloria de Jehov\u00e1. Y luego que yo la hube visto, ca\u00ed sobre mi rostro, y o\u00ed voz de uno que hablaba.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Ezequiel<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk40\">40<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk41\">41<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk42\">42<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk43\">43<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk44\">44<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk45\">45<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk46\">46<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk47\">47<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk48\">48<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>Ezequiel 1 1\u00a0 Y FU\u00c9 que \u00e1 los treinta a\u00f1os, en el mes cuarto, \u00e1 cinco del mes, estando yo en medio de los trasportados junto al r\u00edo de Chebar, los cielos se abrieron, y vi visiones de Dios. 2\u00a0 A los cinco del mes, que fu\u00e9 en el quinto a\u00f1o de la transmigraci\u00f3n del rey Joach\u00een, 3\u00a0 Fu\u00e9 palabra de Jehov\u00e1 \u00e1 Ezequiel sacerdote, hijo de Buzi, en la tierra de los Caldeos, junto al r\u00edo de Chebar; fu\u00e9 all\u00ed sobre \u00e9l la mano de Jehov\u00e1. 4\u00a0 Y mir\u00e9, y he aqu\u00ed un viento tempestuoso ven\u00eda del aquil\u00f3n, una gran nube, con un fuego envolvente, y en derredor suyo un resplandor, y en medio del fuego una cosa que parec\u00eda como de \u00e1mbar, 5\u00a0 Y en medio de ella, figura de cuatro animales. Y este era su parecer; hab\u00eda en ellos semejanza de hombre. 6\u00a0 Y cada uno ten\u00eda cuatro rostros, y cuatro alas. 7\u00a0 Y los pies de ellos eran derechos, y la planta de sus pies como la planta de pie de becerro; y centelleaban \u00e1 manera de bronce muy bru\u00f1ido. 8\u00a0 Y debajo de sus alas, \u00e1 sus cuatro lados, ten\u00edan manos de hombre; y sus rostros y sus alas por los cuatro lados. 9\u00a0 Con las alas se juntaban el uno al otro. No se volv\u00edan cuando andaban; cada uno caminaba en derecho de su rostro. 10\u00a0 Y la figura de sus rostros era rostro de hombre; y rostro de le\u00f3n \u00e1 la parte derecha en los cuatro; y \u00e1 la izquierda rostro de buey en los cuatro; asimismo hab\u00eda en los cuatro rostro de \u00e1guila. 11\u00a0 Tales eran sus rostros; y ten\u00edan sus alas extendidas por encima, cada uno dos, las cuales se juntaban; y las otras dos cubr\u00edan sus cuerpos. 12\u00a0 Y cada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5409","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5409"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5409\/revisions"}],"predecessor-version":[{"id":6947,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5409\/revisions\/6947"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}