{"id":5413,"date":"2015-12-10T22:18:31","date_gmt":"2015-12-10T22:18:31","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/ezk05\/"},"modified":"2019-07-27T11:09:14","modified_gmt":"2019-07-27T15:09:14","slug":"ezk05","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/ezk05\/","title":{"rendered":"Ezequiel 5"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 5<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y T\u00da, hijo del hombre, t\u00f3mate un cuchillo agudo, una navaja de barbero toma, y hazla pasar sobre tu cabeza y tu barba: t\u00f3mate despu\u00e9s un peso de balanza, y reparte los pelos.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Una tercera parte quemar\u00e1s con fuego en medio de la ciudad, cuando se cumplieren los d\u00edas del cerco, y tomar\u00e1s una tercera parte, y herir\u00e1s con cuchillo alrededor de ella; y una tercera parte esparcir\u00e1s al viento, y yo desenvainar\u00e9 espada en pos de ellos.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Tomar\u00e1s tambi\u00e9n de all\u00ed unos pocos por cuenta, y los atar\u00e1s en el canto de tu ropa.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y tomar\u00e1s otra vez de ellos, y los echar\u00e1s en mitad del fuego, y en el fuego los quemar\u00e1s: de all\u00ed saldr\u00e1 el fuego en toda la casa de Israel.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Esta es Jerusalem: p\u00fasela en medio de las gentes y de las tierras alrededor de ella.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y ella mud\u00f3 mis juicios y mis ordenanzas en impiedad m\u00e1s que las gentes, y m\u00e1s que las tierras que est\u00e1n alrededor de ella; porque desecharon mis juicios y mis mandamientos, y no anduvieron en ellos.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Por tanto, as\u00ed ha dicho Jehov\u00e1: \u00bfPor haberos multiplicado m\u00e1s que \u00e1 las gentes que est\u00e1n alrededor de vosotros, no hab\u00e9is andado en mis mandamientos, ni hab\u00e9is guardado mis leyes? Ni aun seg\u00fan las leyes de las gentes que est\u00e1n alrededor de vosotros hab\u00e9is hecho.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> As\u00ed pues ha dicho el Se\u00f1or Jehov\u00e1: He aqu\u00ed yo contra ti; s\u00ed, yo, y har\u00e9 juicios en medio de ti \u00e1 los ojos de las naciones.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y har\u00e9 en ti lo que nunca hice, ni jam\u00e1s har\u00e9 cosa semejante, \u00e1 causa de todas tus abominaciones.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Por eso los padres comer\u00e1n \u00e1 los hijos en medio de ti, y los hijos comer\u00e1n \u00e1 sus padres; y har\u00e9 en ti juicios, y esparcir\u00e9 \u00e1 todos vientos todo tu residuo.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Por tanto, vivo yo, dice el Se\u00f1or Jehov\u00e1, ciertamente por haber violado mi santuario con todas tus abominaciones, <span class=\"add\">te<\/span> quebrantar\u00e9 yo tambi\u00e9n: mi ojo no perdonar\u00e1, ni tampoco tendr\u00e9 yo misericordia.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Una tercera parte de ti morir\u00e1 de pestilencia, y de hambre ser\u00e1 consumida en medio de ti; y una tercera parte caer\u00e1 \u00e1 cuchillo alrededor de ti; y una tercera parte esparcir\u00e9 \u00e1 todos los vientos, y tras ellos desenvainar\u00e9 espada.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y cumplir\u00e1se mi furor, y har\u00e9 que repose en ellos mi enojo, y tomar\u00e9 satisfacci\u00f3n: y sabr\u00e1n que yo Jehov\u00e1 he hablado en mi celo, cuando habr\u00e9 cumplido en ellos mi enojo.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y te tornar\u00e9 en desierto y en oprobio entre las gentes que est\u00e1n alrededor de ti, \u00e1 los ojos de todo transeunte.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y ser\u00e1s oprobio, y escarnio, y escarmiento, y espanto \u00e1 las gentes que est\u00e1n alrededor de ti, cuando yo hiciere en ti juicios en furor \u00e9 indignaci\u00f3n, y en reprensiones de ira. Yo Jehov\u00e1 he hablado.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Cuando arrojare yo sobre ellos las perniciosas saetas del hambre, que ser\u00e1n para destrucci\u00f3n, las cuales enviar\u00e9 para destruiros, entonces aumentar\u00e9 el hambre sobre vosotros, y quebrantar\u00e9 entre vosotros el arrimo del pan.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Enviar\u00e9 pues sobre vosotros hambre, y malas bestias que te destruyan; y pestilencia y sangre pasar\u00e1n por ti; y meter\u00e9 sobre ti cuchillo. Yo Jehov\u00e1 he hablado.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Ezequiel<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk40\">40<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk41\">41<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk42\">42<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk43\">43<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk44\">44<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk45\">45<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk46\">46<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk47\">47<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk48\">48<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>5 1\u00a0 Y T\u00da, hijo del hombre, t\u00f3mate un cuchillo agudo, una navaja de barbero toma, y hazla pasar sobre tu cabeza y tu barba: t\u00f3mate despu\u00e9s un peso de balanza, y reparte los pelos. 2\u00a0 Una tercera parte quemar\u00e1s con fuego en medio de la ciudad, cuando se cumplieren los d\u00edas del cerco, y tomar\u00e1s una tercera parte, y herir\u00e1s con cuchillo alrededor de ella; y una tercera parte esparcir\u00e1s al viento, y yo desenvainar\u00e9 espada en pos de ellos. 3\u00a0 Tomar\u00e1s tambi\u00e9n de all\u00ed unos pocos por cuenta, y los atar\u00e1s en el canto de tu ropa. 4\u00a0 Y tomar\u00e1s otra vez de ellos, y los echar\u00e1s en mitad del fuego, y en el fuego los quemar\u00e1s: de all\u00ed saldr\u00e1 el fuego en toda la casa de Israel. 5\u00a0 As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Esta es Jerusalem: p\u00fasela en medio de las gentes y de las tierras alrededor de ella. 6\u00a0 Y ella mud\u00f3 mis juicios y mis ordenanzas en impiedad m\u00e1s que las gentes, y m\u00e1s que las tierras que est\u00e1n alrededor de ella; porque desecharon mis juicios y mis mandamientos, y no anduvieron en ellos. 7\u00a0 Por tanto, as\u00ed ha dicho Jehov\u00e1: \u00bfPor haberos multiplicado m\u00e1s que \u00e1 las gentes que est\u00e1n alrededor de vosotros, no hab\u00e9is andado en mis mandamientos, ni hab\u00e9is guardado mis leyes? Ni aun seg\u00fan las leyes de las gentes que est\u00e1n alrededor de vosotros hab\u00e9is hecho. 8\u00a0 As\u00ed pues ha dicho el Se\u00f1or Jehov\u00e1: He aqu\u00ed yo contra ti; s\u00ed, yo, y har\u00e9 juicios en medio de ti \u00e1 los ojos de las naciones. 9\u00a0 Y har\u00e9 en ti lo que nunca hice, ni jam\u00e1s har\u00e9 cosa semejante, \u00e1 causa de todas tus abominaciones. 10\u00a0 Por eso los padres comer\u00e1n \u00e1 los hijos en medio de ti, y los hijos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5413","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5413"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5413\/revisions"}],"predecessor-version":[{"id":6972,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5413\/revisions\/6972"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}