{"id":5428,"date":"2015-12-10T22:18:42","date_gmt":"2015-12-10T22:18:42","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/ezk20\/"},"modified":"2019-07-27T10:59:24","modified_gmt":"2019-07-27T14:59:24","slug":"ezk20","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/ezk20\/","title":{"rendered":"Ezequiel 20"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 20<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y ACONTECI\u00d3 en el a\u00f1o s\u00e9ptimo, en el <span class=\"add\">mes<\/span> quinto, \u00e1 los diez del mes, <span class=\"add\">que<\/span> vinieron algunos de los ancianos de Israel \u00e1 consultar \u00e1 Jehov\u00e1, y sent\u00e1ronse delante de m\u00ed.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y fu\u00e9 \u00e1 m\u00ed palabra de Jehov\u00e1, diciendo:  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Hijo del hombre, habla \u00e1 los ancianos de Israel, y diles: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: \u00bfA consultarme ven\u00eds vosotros? Vivo yo, que yo no os responder\u00e9, dice el Se\u00f1or Jehov\u00e1.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> \u00bfQuieres t\u00fa juzgarlos? \u00bflos quieres juzgar t\u00fa, hijo del hombre? Notif\u00edcales las abominaciones de sus padres;  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y diles: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: El d\u00eda que escog\u00ed \u00e1 Israel, y que alc\u00e9 mi mano por la simiente de la casa de Jacob, y que fu\u00ed conocido de ellos en la tierra de Egipto, cuando alc\u00e9 mi mano \u00e1 ellos, diciendo: Yo soy Jehov\u00e1 vuestro Dios;  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Aquel d\u00eda que les alc\u00e9 mi mano, que los sacar\u00eda de la tierra de Egipto \u00e1 la tierra que les hab\u00eda prove\u00eddo, que fluye leche y miel, la cual es la m\u00e1s hermosa de todas las tierras;  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Entonces les dije: Cada uno eche de s\u00ed las abominaciones de sus ojos, y no os contamin\u00e9is en los \u00eddolos de Egipto. Yo soy Jehov\u00e1 vuestro Dios.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Mas ellos se rebelaron contra m\u00ed, y no quisieron obedecerme: no ech\u00f3 de s\u00ed cada uno las abominaciones de sus ojos, ni dejaron los \u00eddolos de Egipto; y dije que derramar\u00eda mi ira sobre ellos, para cumplir mi enojo en ellos en medio de la tierra de Egipto.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Con todo, \u00e1 causa de mi nombre, porque no se infamase en los ojos de las gentes en medio de las cuales estaban, en cuyos ojos fu\u00ed conocido de ellos, hice para sacarlos de tierra de Egipto.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Saqu\u00e9los pues de la tierra de Egipto, y tr\u00e1jelos al desierto;  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y d\u00edles mis ordenanzas, y declar\u00e9les mis derechos, los cuales el hombre que los hiciere, vivir\u00e1 en ellos.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y d\u00edles tambi\u00e9n mis s\u00e1bados, que fuesen por se\u00f1al entre m\u00ed y ellos, para que supiesen que yo soy Jehov\u00e1 que los santifico.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Mas rebel\u00e1ronse contra m\u00ed la casa de Israel en el desierto; no anduvieron en mis ordenanzas, y desecharon mis derechos, los cuales el hombre que los hiciere, vivir\u00e1 en ellos; y mis s\u00e1bados profanaron en gran manera; dije, por tanto, que hab\u00eda de derramar sobre ellos mi ira en el desierto para consumirlos.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Pero en atenci\u00f3n \u00e1 mi nombre hice porque no se infamase \u00e1 la vista de las gentes, delante de cuyos ojos los saqu\u00e9.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y tambi\u00e9n yo les alc\u00e9 mi mano en el desierto, que no los meter\u00eda en la tierra que les d\u00ed, que fluye leche y miel, la cual es la m\u00e1s hermosa de todas las tierras;  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Porque desecharon mis derechos, y no anduvieron en mis ordenanzas, y mis s\u00e1bados profanaron: porque tras sus \u00eddolos iba su coraz\u00f3n.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Con todo los perdon\u00f3 mi ojo, no mat\u00e1ndolos, ni los consum\u00ed en el desierto;  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Antes dije en el desierto \u00e1 sus hijos: No and\u00e9is en las ordenanzas de vuestros padres, ni guard\u00e9is sus leyes, ni os contamin\u00e9is en sus \u00eddolos.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Yo soy Jehov\u00e1 vuestro Dios; andad en mis ordenanzas, y guardad mis derechos, y ponedlos por obra:  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y santificad mis s\u00e1bados, y sean por se\u00f1al entre m\u00ed y vosotros, para que sep\u00e1is que yo soy Jehov\u00e1 vuestro Dios.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y los hijos se rebelaron contra m\u00ed: no anduvieron en mis ordenanzas, ni guardaron mis derechos para ponerlos por obra, los cuales el hombre que los cumpliere, vivir\u00e1 en ellos; profanaron mis s\u00e1bados. Dije entonces que derramar\u00eda mi ira sobre ellos, para cumplir mi enojo en ellos en el desierto.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Mas retraje mi mano, y en atenci\u00f3n \u00e1 mi nombre hice porque no se infamase \u00e1 vista de las gentes, delante de cuyos ojos los saqu\u00e9.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y tambi\u00e9n les alc\u00e9 yo mi mano en el desierto, que los esparcir\u00eda entre las gentes, y que los aventar\u00eda por las tierras;  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Porque no pusieron por obra mis derechos, y desecharon mis ordenanzas, y profanaron mis s\u00e1bados, y tras los \u00eddolos de sus padres se les fueron sus ojos.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Por eso yo tambi\u00e9n les d\u00ed ordenanzas no buenas, y derechos por los cuales no viviesen;  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y contamin\u00e9los en sus ofrendas cuando hac\u00edan pasar <span class=\"add\">por el fuego<\/span> todo primog\u00e9nito, para que los desolase, \u00e1 fin de que supiesen que yo soy Jehov\u00e1.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Por tanto, hijo del hombre, habla \u00e1 la casa de Israel, y diles: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Aun en esto me afrentaron vuestros padres cuando cometieron contra m\u00ed rebeli\u00f3n.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Porque yo los met\u00ed en la tierra sobre la cual hab\u00eda alzado mi mano que les hab\u00eda de dar, y miraron \u00e1 todo collado alto, y \u00e1 todo \u00e1rbol espeso, y all\u00ed sacrificaron sus v\u00edctimas, y all\u00ed presentaron la irritaci\u00f3n de sus ofrendas, all\u00ed pusieron tambi\u00e9n el olor de su suavidad, y all\u00ed derramaron sus libaciones.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Y yo les dije: \u00bfQu\u00e9 es ese alto adonde vosotros vais? Y fu\u00e9 llamado su nombre Bamah hasta el d\u00eda de hoy.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Di, pues, \u00e1 la casa de Israel: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: \u00bfNo os contamin\u00e1is vosotros \u00e1 la manera de vuestros padres, y fornic\u00e1is tras sus abominaciones?  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Porque ofreciendo vuestras ofrendas, haciendo pasar vuestros hijos por el fuego, os hab\u00e9is contaminado con todos vuestros \u00eddolos hasta hoy: \u00bfy he de responderos yo, casa de Israel? Vivo yo, dice el Se\u00f1or Jehov\u00e1, que no os responder\u00e9.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Y no ha de ser lo que hab\u00e9is pensado. Porque vosotros dec\u00eds: Seamos como las gentes, como las familias de las naciones, sirviendo \u00e1 la madera y \u00e1 la piedra.  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Vivo yo, dice el Se\u00f1or Jehov\u00e1, que con mano fuerte, y brazo extendido, y enojo derramado, tengo de reinar sobre vosotros:  <span class=\"verse\" id=\"V34\">34\u00a0<\/span> Y os sacar\u00e9 de entre los pueblos, y os juntar\u00e9 de las tierras en que est\u00e1is esparcidos, con mano fuerte, y brazo extendido, y enojo derramado:  <span class=\"verse\" id=\"V35\">35\u00a0<\/span> Y os he de traer al desierto de pueblos, y all\u00ed litigar\u00e9 con vosotros cara \u00e1 cara.  <span class=\"verse\" id=\"V36\">36\u00a0<\/span> Como litigu\u00e9 con vuestros padres en el desierto de la tierra de Egipto, as\u00ed litigar\u00e9 con vosotros, dice el Se\u00f1or Jehov\u00e1.  <span class=\"verse\" id=\"V37\">37\u00a0<\/span> Y os har\u00e9 pasar bajo de vara y os traer\u00e9 en v\u00ednculo de concierto;  <span class=\"verse\" id=\"V38\">38\u00a0<\/span> Y apartar\u00e9 de entre vosotros los rebeldes, y los que se rebelaron contra m\u00ed: de la tierra de sus destierros los sacar\u00e9, y \u00e1 la tierra de Israel no vendr\u00e1n; y sabr\u00e9is que yo soy Jehov\u00e1.  <span class=\"verse\" id=\"V39\">39\u00a0<\/span> Y vosotros, oh casa de Israel, as\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Andad cada uno tras sus \u00eddolos, y servidles, pues que \u00e1 m\u00ed no me obedec\u00e9is; y no profan\u00e9is m\u00e1s mi santo nombre con vuestras ofrendas, y con vuestros \u00eddolos.  <span class=\"verse\" id=\"V40\">40\u00a0<\/span> Empero en mi santo monte, en el alto monte de Israel, dice el Se\u00f1or Jehov\u00e1, all\u00ed me servir\u00e1 toda la casa de Israel, toda ella en la tierra: all\u00ed los querr\u00e9, y all\u00ed demandar\u00e9 vuestras ofrendas, y las primicias de vuestros dones, con todas vuestras cosas consagradas.  <span class=\"verse\" id=\"V41\">41\u00a0<\/span> En olor de suavidad os aceptar\u00e9, cuando os hubiere sacado de entre los pueblos, y os hubiere juntado de las tierras en que est\u00e1is esparcidos; y ser\u00e9 santificado en vosotros \u00e1 los ojos de las gentes.  <span class=\"verse\" id=\"V42\">42\u00a0<\/span> Y sabr\u00e9is que yo soy Jehov\u00e1, cuando os hubiere metido en la tierra de Israel, en la tierra por la cual alc\u00e9 mi mano que la dar\u00eda \u00e1 vuestros padres.  <span class=\"verse\" id=\"V43\">43\u00a0<\/span> Y all\u00ed os acordar\u00e9is de vuestros caminos, y de todos vuestros hechos en que os contaminasteis; y ser\u00e9is confusos en vuestra misma presencia por todos vuestros pecados que cometisteis.  <span class=\"verse\" id=\"V44\">44\u00a0<\/span> Y sabr\u00e9is que yo soy Jehov\u00e1 cuando hiciere con vosotros por amor de mi nombre, no seg\u00fan vuestros caminos malos, ni seg\u00fan vuestras perversas obras, oh casa de Israel, dice el Se\u00f1or Jehov\u00e1.  <span class=\"verse\" id=\"V45\">45\u00a0<\/span> Y fu\u00e9 \u00e1 m\u00ed palabra de Jehov\u00e1, diciendo:  <span class=\"verse\" id=\"V46\">46\u00a0<\/span> Hijo del hombre, pon tu rostro hacia el mediod\u00eda, y derrama <span class=\"add\">tu palabra<\/span> hacia la parte austral, y profetiza contra el bosque del campo del mediod\u00eda.  <span class=\"verse\" id=\"V47\">47\u00a0<\/span> Y dir\u00e1s al bosque del mediod\u00eda: Oye palabra de Jehov\u00e1: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: He aqu\u00ed que yo enciendo en ti fuego, el cual consumir\u00e1 en ti todo \u00e1rbol verde, y todo \u00e1rbol seco: no se apagar\u00e1 la llama del fuego; y ser\u00e1n quemados en ella todos rostros, desde el mediod\u00eda hasta el norte.  <span class=\"verse\" id=\"V48\">48\u00a0<\/span> Y ver\u00e1 toda carne que yo Jehov\u00e1 lo encend\u00ed; no se apagar\u00e1.  <span class=\"verse\" id=\"V49\">49\u00a0<\/span> Y dije: \u00a1Ah, Se\u00f1or Jehov\u00e1! ellos dicen de m\u00ed: \u00bfNo profiere \u00e9ste par\u00e1bolas?  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Ezequiel<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk40\">40<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk41\">41<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk42\">42<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk43\">43<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk44\">44<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk45\">45<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk46\">46<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk47\">47<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk48\">48<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>20 1\u00a0 Y ACONTECI\u00d3 en el a\u00f1o s\u00e9ptimo, en el mes quinto, \u00e1 los diez del mes, que vinieron algunos de los ancianos de Israel \u00e1 consultar \u00e1 Jehov\u00e1, y sent\u00e1ronse delante de m\u00ed. 2\u00a0 Y fu\u00e9 \u00e1 m\u00ed palabra de Jehov\u00e1, diciendo: 3\u00a0 Hijo del hombre, habla \u00e1 los ancianos de Israel, y diles: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: \u00bfA consultarme ven\u00eds vosotros? Vivo yo, que yo no os responder\u00e9, dice el Se\u00f1or Jehov\u00e1. 4\u00a0 \u00bfQuieres t\u00fa juzgarlos? \u00bflos quieres juzgar t\u00fa, hijo del hombre? Notif\u00edcales las abominaciones de sus padres; 5\u00a0 Y diles: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: El d\u00eda que escog\u00ed \u00e1 Israel, y que alc\u00e9 mi mano por la simiente de la casa de Jacob, y que fu\u00ed conocido de ellos en la tierra de Egipto, cuando alc\u00e9 mi mano \u00e1 ellos, diciendo: Yo soy Jehov\u00e1 vuestro Dios; 6\u00a0 Aquel d\u00eda que les alc\u00e9 mi mano, que los sacar\u00eda de la tierra de Egipto \u00e1 la tierra que les hab\u00eda prove\u00eddo, que fluye leche y miel, la cual es la m\u00e1s hermosa de todas las tierras; 7\u00a0 Entonces les dije: Cada uno eche de s\u00ed las abominaciones de sus ojos, y no os contamin\u00e9is en los \u00eddolos de Egipto. Yo soy Jehov\u00e1 vuestro Dios. 8\u00a0 Mas ellos se rebelaron contra m\u00ed, y no quisieron obedecerme: no ech\u00f3 de s\u00ed cada uno las abominaciones de sus ojos, ni dejaron los \u00eddolos de Egipto; y dije que derramar\u00eda mi ira sobre ellos, para cumplir mi enojo en ellos en medio de la tierra de Egipto. 9\u00a0 Con todo, \u00e1 causa de mi nombre, porque no se infamase en los ojos de las gentes en medio de las cuales estaban, en cuyos ojos fu\u00ed conocido de ellos, hice para sacarlos de tierra de Egipto. 10\u00a0 Saqu\u00e9los pues&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5428","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5428"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5428\/revisions"}],"predecessor-version":[{"id":6935,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5428\/revisions\/6935"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}