{"id":5438,"date":"2015-12-10T22:19:10","date_gmt":"2015-12-10T22:19:10","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/ezk30\/"},"modified":"2019-07-27T11:04:58","modified_gmt":"2019-07-27T15:04:58","slug":"ezk30","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/ezk30\/","title":{"rendered":"Ezequiel 30"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 30<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y FU\u00c9 \u00e1 m\u00ed palabra de Jehov\u00e1, diciendo:  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Hijo del hombre, profetiza, y di: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Aullad: \u00a1Ay del d\u00eda!  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Porque cerca est\u00e1 el d\u00eda, cerca est\u00e1 el d\u00eda del Se\u00f1or; d\u00eda de nublado, d\u00eda de las gentes ser\u00e1.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y vendr\u00e1 espada \u00e1 Egipto, y habr\u00e1 miedo en Etiop\u00eda, cuando caer\u00e1n heridos en Egipto; y tomar\u00e1n su multitud, y ser\u00e1n destru\u00eddos sus fundamentos.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Etiop\u00eda, y Libia, y Lidia, y todo el conjunto de pueblo, y Ch\u00fbb, y los hijos de la tierra de la liga, caer\u00e1n con ellos \u00e1 cuchillo.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> As\u00ed ha dicho Jehov\u00e1: Tambi\u00e9n caer\u00e1n los que sostienen \u00e1 Egipto, y la altivez de su fortaleza caer\u00e1: desde Migdol hasta Seveneh caer\u00e1n en \u00e9l \u00e1 cuchillo, dice el Se\u00f1or Jehov\u00e1.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y ser\u00e1n asolados entre las tierras asoladas, y sus ciudades ser\u00e1n entre las ciudades desiertas.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y sabr\u00e1n que yo soy Jehov\u00e1, cuando pusiere fuego \u00e1 Egipto, y fueren quebrantados todos sus ayudadores.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> En aquel tiempo saldr\u00e1n mensajeros de delante de m\u00ed en nav\u00edos, \u00e1 espantar \u00e1 Etiop\u00eda la confiada, y tendr\u00e1n espanto como en el d\u00eda de Egipto: porque he aqu\u00ed viene.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Har\u00e9 cesar la multitud de Egipto por mano de Nabucodonosor, rey de Babilonia.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> El, y con \u00e9l su pueblo, los m\u00e1s fuertes de las gentes, ser\u00e1n tra\u00eddos \u00e1 destruir la tierra: y desenvainar\u00e1n sus espadas sobre Egipto, y henchir\u00e1n la tierra de muertos.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y secar\u00e9 los r\u00edos, y entregar\u00e9 la tierra en manos de malos, y destruir\u00e9 la tierra y su plenitud por mano de extranjeros: yo Jehov\u00e1 he hablado.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Destruir\u00e9 tambi\u00e9n las im\u00e1genes, y har\u00e9 cesar los \u00eddolos de Memphis; y no habr\u00e1 m\u00e1s pr\u00edncipe de la tierra de Egipto, y en la tierra de Egipto pondr\u00e9 temor.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y asolar\u00e9 \u00e1 Patros, y pondr\u00e9 fuego \u00e1 Zo\u00e1n, y har\u00e9 juicios en No.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y derramar\u00e9 mi ira sobre Sin, fortaleza de Egipto, y talar\u00e9 la multitud de No.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y pondr\u00e9 fuego \u00e1 Egipto; Sin tendr\u00e1 gran dolor, y No ser\u00e1 destrozada, y Memphis tendr\u00e1 continuas angustias.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Los mancebos de Av\u00e9n y de Pibeseth caer\u00e1n \u00e1 cuchillo; y ellas ir\u00e1n en cautiverio.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Y en Tehaphnes ser\u00e1 cerrado el d\u00eda, cuando quebrantar\u00e9 yo all\u00ed las barras de Egipto, y cesar\u00e1 en ella la soberbia de su fortaleza: nublado la cubrir\u00e1, y los moradores de sus aldeas ir\u00e1n en cautiverio.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Har\u00e9 pues juicios en Egipto y sabr\u00e1n que yo soy Jehov\u00e1.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y aconteci\u00f3 en el a\u00f1o und\u00e9cimo, en el <span class=\"add\">mes<\/span> primero, \u00e1 los siete del mes, que fu\u00e9 \u00e1 m\u00ed palabra de Jehov\u00e1, diciendo:  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Hijo del hombre, quebrantado he el brazo de Fara\u00f3n rey de Egipto; y he aqu\u00ed que no ha sido vendado poni\u00e9ndo<span class=\"add\">le<\/span> medicinas, poni\u00e9ndole faja para ligarlo, \u00e1 fin de vigorizarle para que pueda tener espada.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Por tanto, as\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Heme aqu\u00ed contra Fara\u00f3n rey de Egipto, y quebrar\u00e9 sus brazos, el fuerte y el fracturado, y har\u00e9 que la espada se le caiga de la mano.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y esparcir\u00e9 los Egipcios entre las gentes, y aventar\u00e9los por las tierras.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y fortificar\u00e9 los brazos del rey de Babilonia, y pondr\u00e9 mi espada en su mano; mas quebrar\u00e9 los brazos de Fara\u00f3n, y delante de aqu\u00e9l gemir\u00e1 con gemidos de herido de muerte.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Fortificar\u00e9 pues los brazos del rey de Babilonia, y los brazos de Fara\u00f3n caer\u00e1n; y sabr\u00e1n que yo soy Jehov\u00e1, cuando yo pusiere mi espada en la mano del rey de Babilonia, y \u00e9l la extendiere sobre la tierra de Egipto.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y esparcir\u00e9 los Egipcios entre las gentes, y los aventar\u00e9 por las tierras; y sabr\u00e1n que yo soy Jehov\u00e1.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Ezequiel<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk40\">40<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk41\">41<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk42\">42<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk43\">43<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk44\">44<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk45\">45<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk46\">46<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk47\">47<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/ezk48\">48<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>30 1\u00a0 Y FU\u00c9 \u00e1 m\u00ed palabra de Jehov\u00e1, diciendo: 2\u00a0 Hijo del hombre, profetiza, y di: As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Aullad: \u00a1Ay del d\u00eda! 3\u00a0 Porque cerca est\u00e1 el d\u00eda, cerca est\u00e1 el d\u00eda del Se\u00f1or; d\u00eda de nublado, d\u00eda de las gentes ser\u00e1. 4\u00a0 Y vendr\u00e1 espada \u00e1 Egipto, y habr\u00e1 miedo en Etiop\u00eda, cuando caer\u00e1n heridos en Egipto; y tomar\u00e1n su multitud, y ser\u00e1n destru\u00eddos sus fundamentos. 5\u00a0 Etiop\u00eda, y Libia, y Lidia, y todo el conjunto de pueblo, y Ch\u00fbb, y los hijos de la tierra de la liga, caer\u00e1n con ellos \u00e1 cuchillo. 6\u00a0 As\u00ed ha dicho Jehov\u00e1: Tambi\u00e9n caer\u00e1n los que sostienen \u00e1 Egipto, y la altivez de su fortaleza caer\u00e1: desde Migdol hasta Seveneh caer\u00e1n en \u00e9l \u00e1 cuchillo, dice el Se\u00f1or Jehov\u00e1. 7\u00a0 Y ser\u00e1n asolados entre las tierras asoladas, y sus ciudades ser\u00e1n entre las ciudades desiertas. 8\u00a0 Y sabr\u00e1n que yo soy Jehov\u00e1, cuando pusiere fuego \u00e1 Egipto, y fueren quebrantados todos sus ayudadores. 9\u00a0 En aquel tiempo saldr\u00e1n mensajeros de delante de m\u00ed en nav\u00edos, \u00e1 espantar \u00e1 Etiop\u00eda la confiada, y tendr\u00e1n espanto como en el d\u00eda de Egipto: porque he aqu\u00ed viene. 10\u00a0 As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Har\u00e9 cesar la multitud de Egipto por mano de Nabucodonosor, rey de Babilonia. 11\u00a0 El, y con \u00e9l su pueblo, los m\u00e1s fuertes de las gentes, ser\u00e1n tra\u00eddos \u00e1 destruir la tierra: y desenvainar\u00e1n sus espadas sobre Egipto, y henchir\u00e1n la tierra de muertos. 12\u00a0 Y secar\u00e9 los r\u00edos, y entregar\u00e9 la tierra en manos de malos, y destruir\u00e9 la tierra y su plenitud por mano de extranjeros: yo Jehov\u00e1 he hablado. 13\u00a0 As\u00ed ha dicho el Se\u00f1or Jehov\u00e1: Destruir\u00e9 tambi\u00e9n las im\u00e1genes, y har\u00e9 cesar los \u00eddolos de Memphis; y no habr\u00e1 m\u00e1s pr\u00edncipe de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5438","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5438"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5438\/revisions"}],"predecessor-version":[{"id":6963,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5438\/revisions\/6963"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}