{"id":5498,"date":"2015-12-10T22:18:48","date_gmt":"2015-12-10T22:18:48","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/gen32\/"},"modified":"2019-07-14T20:06:40","modified_gmt":"2019-07-15T00:06:40","slug":"gen32","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/gen32\/","title":{"rendered":"G\u00e9nesis 32"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 32<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y JACOB se fu\u00e9 su camino, y sali\u00e9ronle al encuentro \u00e1ngeles de Dios.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y dijo Jacob cuando los vi\u00f3: El campo de Dios es este: y llam\u00f3 el nombre de aquel lugar Mahanaim.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y envi\u00f3 Jacob mensajeros delante de s\u00ed \u00e1 Esa\u00fa su hermano, \u00e1 la tierra de Seir, campo de Edom.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y mand\u00f3les diciendo: As\u00ed dir\u00e9is \u00e1 mi se\u00f1or Esa\u00fa: As\u00ed dice tu siervo Jacob: Con Lab\u00e1n he morado, y deten\u00eddome hasta ahora;  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y tengo vacas, y asnos, y ovejas, y siervos y siervas; y env\u00edo \u00e1 decirlo \u00e1 mi se\u00f1or, por hallar gracia en tus ojos.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y los mensajeros volvieron \u00e1 Jacob, diciendo: Vinimos \u00e1 tu hermano Esa\u00fa, y \u00e9l tambi\u00e9n viene \u00e1 recibirte, y cuatrocientos hombres con \u00e9l.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Entonces Jacob tuvo gran temor, y angusti\u00f3se; y parti\u00f3 el pueblo que ten\u00eda consigo, y las ovejas y las vacas y los camellos, en dos cuadrillas;  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y dijo: Si viniere Esa\u00fa \u00e1 la una cuadrilla y la hiriere, la otra cuadrilla escapar\u00e1.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y dijo Jacob: Dios de mi padre Abraham, y Dios de mi padre Isaac, Jehov\u00e1, que me dijiste: Vu\u00e9lvete \u00e1 tu tierra y \u00e1 tu parentela, y yo te har\u00e9 bien;  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Menor soy que todas las misericordias, y que toda la verdad que has usado para con tu siervo; que con mi bord\u00f3n pas\u00e9 este Jord\u00e1n, y ahora estoy sobre dos cuadrillas.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> L\u00edbrame ahora de la mano de mi hermano, de la mano de Esa\u00fa, porque le temo; no venga quiz\u00e1, y me hiera la madre con los hijos.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y t\u00fa has dicho: Yo te har\u00e9 bien, y pondr\u00e9 tu simiente como la arena del mar, que no se puede contar por la multitud.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y durmi\u00f3 all\u00ed aquella noche, y tom\u00f3 de lo que le vino \u00e1 la mano un presente para su hermano Esa\u00fa:  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Doscientas cabras y veinte machos de cabr\u00edo, doscientas ovejas y veinte carneros,  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Treinta camellas paridas, con sus hijos, cuarenta vacas y diez novillos, veinte asnas y diez borricos.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y entreg\u00f3lo en mano de sus siervos, cada manada de por s\u00ed; y dijo \u00e1 sus siervos: Pasad delante de m\u00ed, y poned espacio entre manada y manada.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y mand\u00f3 al primero, diciendo: Si Esa\u00fa mi hermano te encontrare, y te preguntare, diciendo: \u00bfDe qui\u00e9n eres? \u00bfy ad\u00f3nde vas? \u00bfy para qui\u00e9n es esto que llevas delante de ti?  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Entonces dir\u00e1s: Presente es de tu siervo Jacob, que env\u00eda \u00e1 mi se\u00f1or Esa\u00fa; y he aqu\u00ed tambi\u00e9n \u00e9l viene tras nosotros.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y mand\u00f3 tambi\u00e9n al segundo, y al tercero, y \u00e1 todos los que iban tras aquellas manadas, diciendo: Conforme \u00e1 esto hablar\u00e9is \u00e1 Esa\u00fa, cuando le hallareis.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y dir\u00e9is tambi\u00e9n: He aqu\u00ed tu siervo Jacob viene tras nosotros. Porque dijo: Apaciguar\u00e9 su ira con el presente que va delante de m\u00ed, y despu\u00e9s ver\u00e9 su rostro: quiz\u00e1 le ser\u00e9 acepto.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y pas\u00f3 el presente delante de \u00e9l; y \u00e9l durmi\u00f3 aquella noche en el campamento.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y levant\u00f3se aquella noche, y tom\u00f3 sus dos mujeres, y sus dos siervas, y sus once hijos, y pas\u00f3 el vado de Jaboc.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Tom\u00f3los pues, y pas\u00f3los el arroyo, \u00e9 hizo pasar lo que ten\u00eda.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y qued\u00f3se Jacob solo, y luch\u00f3 con \u00e9l un var\u00f3n hasta que rayaba el alba.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y como vi\u00f3 que no pod\u00eda con \u00e9l, toc\u00f3 en el sitio del encaje de su muslo, y descoyunt\u00f3se el muslo de Jacob mientras con \u00e9l luchaba.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y dijo: D\u00e9jame, que raya el alba. Y \u00e9l dijo: No te dejar\u00e9, si no me bendices.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Y \u00e9l le dijo: \u00bfCu\u00e1l es tu nombre? Y \u00e9l respondi\u00f3: Jacob.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Y \u00e9l dijo: No se dir\u00e1 m\u00e1s tu nombre Jacob, sino Israel: porque has peleado con Dios y con los hombres, y has vencido.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Entonces Jacob le pregunt\u00f3, y dijo: Decl\u00e1rame ahora tu nombre. Y \u00e9l respondi\u00f3: \u00bfPor qu\u00e9 preguntas por mi nombre? Y bend\u00edjolo all\u00ed.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Y llam\u00f3 Jacob el nombre de aquel lugar, Peniel: porque vi \u00e1 Dios cara \u00e1 cara, y fu\u00e9 librada mi alma.  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Y sali\u00f3le el sol pasado que hubo \u00e1 Peniel; y cojeaba de su anca.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Por esto no comen los hijos de Israel, hasta hoy d\u00eda, del tend\u00f3n que se contrajo, el cual est\u00e1 en el encaje del muslo: porque toc\u00f3 \u00e1 Jacob este sitio de su muslo en el tend\u00f3n que se contrajo.  <\/div><hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Genesis<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen36\">36<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen37\">37<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen38\">38<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen39\">39<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen40\">40<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen41\">41<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen42\">42<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen43\">43<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen44\">44<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen45\">45<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen46\">46<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen47\">47<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen48\">48<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen49\">49<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/gen50\">50<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>32 1\u00a0 Y JACOB se fu\u00e9 su camino, y sali\u00e9ronle al encuentro \u00e1ngeles de Dios. 2\u00a0 Y dijo Jacob cuando los vi\u00f3: El campo de Dios es este: y llam\u00f3 el nombre de aquel lugar Mahanaim. 3\u00a0 Y envi\u00f3 Jacob mensajeros delante de s\u00ed \u00e1 Esa\u00fa su hermano, \u00e1 la tierra de Seir, campo de Edom. 4\u00a0 Y mand\u00f3les diciendo: As\u00ed dir\u00e9is \u00e1 mi se\u00f1or Esa\u00fa: As\u00ed dice tu siervo Jacob: Con Lab\u00e1n he morado, y deten\u00eddome hasta ahora; 5\u00a0 Y tengo vacas, y asnos, y ovejas, y siervos y siervas; y env\u00edo \u00e1 decirlo \u00e1 mi se\u00f1or, por hallar gracia en tus ojos. 6\u00a0 Y los mensajeros volvieron \u00e1 Jacob, diciendo: Vinimos \u00e1 tu hermano Esa\u00fa, y \u00e9l tambi\u00e9n viene \u00e1 recibirte, y cuatrocientos hombres con \u00e9l. 7\u00a0 Entonces Jacob tuvo gran temor, y angusti\u00f3se; y parti\u00f3 el pueblo que ten\u00eda consigo, y las ovejas y las vacas y los camellos, en dos cuadrillas; 8\u00a0 Y dijo: Si viniere Esa\u00fa \u00e1 la una cuadrilla y la hiriere, la otra cuadrilla escapar\u00e1. 9\u00a0 Y dijo Jacob: Dios de mi padre Abraham, y Dios de mi padre Isaac, Jehov\u00e1, que me dijiste: Vu\u00e9lvete \u00e1 tu tierra y \u00e1 tu parentela, y yo te har\u00e9 bien; 10\u00a0 Menor soy que todas las misericordias, y que toda la verdad que has usado para con tu siervo; que con mi bord\u00f3n pas\u00e9 este Jord\u00e1n, y ahora estoy sobre dos cuadrillas. 11\u00a0 L\u00edbrame ahora de la mano de mi hermano, de la mano de Esa\u00fa, porque le temo; no venga quiz\u00e1, y me hiera la madre con los hijos. 12\u00a0 Y t\u00fa has dicho: Yo te har\u00e9 bien, y pondr\u00e9 tu simiente como la arena del mar, que no se puede contar por la multitud. 13\u00a0 Y durmi\u00f3 all\u00ed aquella noche, y tom\u00f3 de lo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5498","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5498"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5498\/revisions"}],"predecessor-version":[{"id":6740,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5498\/revisions\/6740"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}