{"id":5807,"date":"2015-12-10T22:18:23","date_gmt":"2015-12-10T22:18:23","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/num01\/"},"modified":"2019-08-04T00:25:26","modified_gmt":"2019-08-04T04:25:26","slug":"num01","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/num01\/","title":{"rendered":"N\u00fameros 1"},"content":{"rendered":"<div class=\"main\">\r\n  <div class=\"mt\">N\u00fameros  <\/div><div class=\"chapterlabel\" id=\"V0\"> 1<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y HABL\u00d3 Jehov\u00e1 \u00e1 Mois\u00e9s en el desierto de Sina\u00ed, en el tabern\u00e1culo del testimonio, en el primero del mes segundo, en el segundo a\u00f1o de su salida de la tierra de Egipto, diciendo:  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Tomad el encabezamiento de toda la congregaci\u00f3n de los hijos de Israel por sus familias, por las casas de sus padres, con la cuenta de los nombres, todos los varones por sus cabezas:  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> De veinte a\u00f1os arriba, todos los que pueden salir \u00e1 la guerra en Israel, los contar\u00e9is t\u00fa y Aar\u00f3n por sus cuadrillas.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y estar\u00e1 con vosotros un var\u00f3n de cada tribu, cada uno cabeza de la casa de sus padres.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y estos son los nombres de los varones que estar\u00e1n con vosotros: De la tribu de Rub\u00e9n, Elisur hijo de Sedeur.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> De Sime\u00f3n, Selumiel hijo de Zurisaddai.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> De Jud\u00e1, Naas\u00f3n hijo de Aminadab.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> De Issach\u00e2r, Nathanael hijo de Suar.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> De Zabul\u00f3n, Eliab hijo de Hel\u00f3n.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> De los hijos de Jos\u00e9: de Ephraim, Elisama hijo de Ammiud; de Manas\u00e9s, Gamaliel hijo de Pedasur.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> De Benjam\u00edn, Abid\u00e1n hijo de Gede\u00f3n.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> De Dan, Ahiezer hijo de Ammisaddai.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> De Aser, Phegiel hijo de Ocr\u00e1n.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> De Gad, Eliasaph hijo de Dehuel.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> De Nephtal\u00ed, Ahira hijo de En\u00e1n.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Estos eran los nombrados de la congregaci\u00f3n, pr\u00edncipes de las tribus de sus padres, capitanes de los millares de Israel.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Tom\u00f3 pues Mois\u00e9s y Aar\u00f3n \u00e1 estos varones que fueron declarados por sus nombres:  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Y juntaron toda la congregaci\u00f3n en el primero del mes segundo, y fueron reunidos sus linajes, por las casas de sus padres, seg\u00fan la cuenta de los nombres, de veinte a\u00f1os arriba, por sus cabezas,  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Como Jehov\u00e1 lo hab\u00eda mandado \u00e1 Mois\u00e9s; y cont\u00f3los en el desierto de Sina\u00ed.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y los hijos de Rub\u00e9n, primog\u00e9nito de Israel, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres por sus cabezas, todos los varones de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Los contados de ellos, de la tribu de Rub\u00e9n, fueron cuarenta y seis mil y quinientos.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> De los hijos de Sime\u00f3n, por sus generaciones, por sus familias, por las casas de sus padres, los contados de ellos conforme \u00e1 la cuenta de los nombres por sus cabezas, todos los varones de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Los contados de ellos, de la tribu de Sime\u00f3n, cincuenta y nueve mil y trescientos.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> De los hijos de Gad, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Los contados de ellos, de la tribu de Gad, cuarenta y cinco mil seiscientos y cincuenta.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> De los hijos de Jud\u00e1, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Los contados de ellos, de la tribu de Jud\u00e1, setenta y cuatro mil y seiscientos.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> De los hijos de Issach\u00e2r, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Los contados de ellos, de la tribu de Issach\u00e2r, cincuenta y cuatro mil y cuatrocientos.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> De los hijos de Zabul\u00f3n, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de sus nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Los contados de ellos, de la tribu de Zabul\u00f3n, cincuenta y siete mil y cuatrocientos.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> De los hijos de Jos\u00e9: de los hijos de Ephraim, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Los contados de ellos, de la tribu de Ephraim, cuarenta mil y quinientos.  <span class=\"verse\" id=\"V34\">34\u00a0<\/span> De los hijos de Manas\u00e9s, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V35\">35\u00a0<\/span> Los contados de ellos, de la tribu de Manas\u00e9s, treinta y dos mil y doscientos.  <span class=\"verse\" id=\"V36\">36\u00a0<\/span> De los hijos de Benjam\u00edn, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V37\">37\u00a0<\/span> Los contados de ellos, de la tribu de Benjam\u00edn, treinta y cinco mil y cuatrocientos.  <span class=\"verse\" id=\"V38\">38\u00a0<\/span> De los hijos de Dan, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V39\">39\u00a0<\/span> Los contados de ellos, de la tribu de Dan, sesenta y dos mil y setecientos.  <span class=\"verse\" id=\"V40\">40\u00a0<\/span> De los hijos de Aser, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V41\">41\u00a0<\/span> Los contados de ellos, de la tribu de Aser, cuarenta y un mil y quinientos.  <span class=\"verse\" id=\"V42\">42\u00a0<\/span> De los hijos de Nephtal\u00ed, por sus generaciones, por sus familias, por las casas de sus padres, conforme \u00e1 la cuenta de los nombres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra;  <span class=\"verse\" id=\"V43\">43\u00a0<\/span> Los contados de ellos, de la tribu de Nephtal\u00ed, cincuenta y tres mil y cuatrocientos.  <span class=\"verse\" id=\"V44\">44\u00a0<\/span> Estos fueron los contados, los cuales contaron Mois\u00e9s y Aar\u00f3n, con los pr\u00edncipes de Israel, que eran doce, uno por cada casa de sus padres.  <span class=\"verse\" id=\"V45\">45\u00a0<\/span> Y fueron todos los contados de los hijos de Israel por las casas de sus padres, de veinte a\u00f1os arriba, todos los que pod\u00edan salir \u00e1 la guerra en Israel;  <span class=\"verse\" id=\"V46\">46\u00a0<\/span> Fueron todos los contados seiscientos tres mil quinientos y cincuenta.  <span class=\"verse\" id=\"V47\">47\u00a0<\/span> Pero los Levitas no fueron contados entre ellos seg\u00fan la tribu de sus padres.  <span class=\"verse\" id=\"V48\">48\u00a0<\/span> Porque habl\u00f3 Jehov\u00e1 \u00e1 Mois\u00e9s, diciendo:  <span class=\"verse\" id=\"V49\">49\u00a0<\/span> Solamente no contar\u00e1s la tribu de Lev\u00ed, ni tomar\u00e1s la cuenta de ellos entre los hijos de Israel:  <span class=\"verse\" id=\"V50\">50\u00a0<\/span> Mas t\u00fa pondr\u00e1s \u00e1 los Levitas en el tabern\u00e1culo del testimonio, y sobre todos sus vasos, y sobre todas las cosas que le pertenecen: ellos llevar\u00e1n el tabern\u00e1culo y todos sus vasos, y ellos servir\u00e1n en \u00e9l, y asentar\u00e1n sus tiendas alrededor del tabern\u00e1culo.  <span class=\"verse\" id=\"V51\">51\u00a0<\/span> Y cuando el tabern\u00e1culo partiere, los Levitas lo desarmar\u00e1n; y cuando el tabern\u00e1culo parare, los Levitas lo armar\u00e1n: y el extra\u00f1o que se llegare, morir\u00e1.  <span class=\"verse\" id=\"V52\">52\u00a0<\/span> Y los hijos de Israel asentar\u00e1n sus tiendas cada uno en su escuadr\u00f3n, y cada uno junto \u00e1 su bandera, por sus cuadrillas;  <span class=\"verse\" id=\"V53\">53\u00a0<\/span> Mas los Levitas asentar\u00e1n las suyas alrededor del tabern\u00e1culo del testimonio, y no habr\u00e1 ira sobre la congregaci\u00f3n de los hijos de Israel: y los Levitas tendr\u00e1n la guarda del tabern\u00e1culo del testimonio.  <span class=\"verse\" id=\"V54\">54\u00a0<\/span> E hicieron los hijos de Israel conforme \u00e1 todas las cosas que mand\u00f3 Jehov\u00e1 \u00e1 Mois\u00e9s; as\u00ed lo hicieron.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de N\u00fameros<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num36\">36<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>N\u00fameros 1 1\u00a0 Y HABL\u00d3 Jehov\u00e1 \u00e1 Mois\u00e9s en el desierto de Sina\u00ed, en el tabern\u00e1culo del testimonio, en el primero del mes segundo, en el segundo a\u00f1o de su salida de la tierra de Egipto, diciendo: 2\u00a0 Tomad el encabezamiento de toda la congregaci\u00f3n de los hijos de Israel por sus familias, por las casas de sus padres, con la cuenta de los nombres, todos los varones por sus cabezas: 3\u00a0 De veinte a\u00f1os arriba, todos los que pueden salir \u00e1 la guerra en Israel, los contar\u00e9is t\u00fa y Aar\u00f3n por sus cuadrillas. 4\u00a0 Y estar\u00e1 con vosotros un var\u00f3n de cada tribu, cada uno cabeza de la casa de sus padres. 5\u00a0 Y estos son los nombres de los varones que estar\u00e1n con vosotros: De la tribu de Rub\u00e9n, Elisur hijo de Sedeur. 6\u00a0 De Sime\u00f3n, Selumiel hijo de Zurisaddai. 7\u00a0 De Jud\u00e1, Naas\u00f3n hijo de Aminadab. 8\u00a0 De Issach\u00e2r, Nathanael hijo de Suar. 9\u00a0 De Zabul\u00f3n, Eliab hijo de Hel\u00f3n. 10\u00a0 De los hijos de Jos\u00e9: de Ephraim, Elisama hijo de Ammiud; de Manas\u00e9s, Gamaliel hijo de Pedasur. 11\u00a0 De Benjam\u00edn, Abid\u00e1n hijo de Gede\u00f3n. 12\u00a0 De Dan, Ahiezer hijo de Ammisaddai. 13\u00a0 De Aser, Phegiel hijo de Ocr\u00e1n. 14\u00a0 De Gad, Eliasaph hijo de Dehuel. 15\u00a0 De Nephtal\u00ed, Ahira hijo de En\u00e1n. 16\u00a0 Estos eran los nombrados de la congregaci\u00f3n, pr\u00edncipes de las tribus de sus padres, capitanes de los millares de Israel. 17\u00a0 Tom\u00f3 pues Mois\u00e9s y Aar\u00f3n \u00e1 estos varones que fueron declarados por sus nombres: 18\u00a0 Y juntaron toda la congregaci\u00f3n en el primero del mes segundo, y fueron reunidos sus linajes, por las casas de sus padres, seg\u00fan la cuenta de los nombres, de veinte a\u00f1os arriba, por sus cabezas, 19\u00a0 Como Jehov\u00e1 lo hab\u00eda mandado \u00e1 Mois\u00e9s; y cont\u00f3los en el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5807","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5807"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5807\/revisions"}],"predecessor-version":[{"id":7051,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5807\/revisions\/7051"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}