{"id":5819,"date":"2015-12-10T22:18:55","date_gmt":"2015-12-10T22:18:55","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/num13\/"},"modified":"2019-08-04T00:24:52","modified_gmt":"2019-08-04T04:24:52","slug":"num13","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/num13\/","title":{"rendered":"N\u00fameros 13"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 13<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y DESPU\u00c9S movi\u00f3 el pueblo de Haseroth, y asentaron el campo en el desierto de Par\u00e1n.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y Jehov\u00e1 habl\u00f3 \u00e1 Mois\u00e9s, diciendo:  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Env\u00eda t\u00fa hombres que reconozcan la tierra de Cana\u00e1n, la cual yo doy \u00e1 los hijos de Israel: de cada tribu de sus padres enviar\u00e9is un var\u00f3n, cada uno pr\u00edncipe entre ellos.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y Mois\u00e9s los envi\u00f3 desde el desierto de Par\u00e1n, conforme \u00e1 la palabra de Jehov\u00e1: y todos aquellos varones eran pr\u00edncipes de los hijos de Israel.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Los nombres de los cuales son \u00e9stos: De la tribu de Rub\u00e9n, Sammua hijo de Zaccur.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> De la tribu de Sime\u00f3n, Saphat hijo de Hur\u00ed.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> De la tribu de Jud\u00e1, Caleb hijo de Jephone.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> De la tribu de Issach\u00e2r, Igal hijo de Joseph.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> De la tribu de Ephraim, Oseas hijo de Nun.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> De la tribu de Benjam\u00edn, Palti hijo de Raphu.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> De la tribu de Zabul\u00f3n, Gaddiel hijo de Sodi.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> De la tribu de Jos\u00e9, de la tribu de Manas\u00e9s, Gaddi hijo de Susi.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> De la tribu de Dan, Ammiel hijo de Gemalli.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> De la tribu de Aser, Sethur hijo de Mich\u00e2el.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> De la tribu de Nephtal\u00ed, Nahab\u00ed hijo de Vapsi.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> De la tribu de Gad, Geuel hijo de Mach\u00ee.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Estos son los nombres de los varones que Mois\u00e9s envi\u00f3 \u00e1 reconocer la tierra: y \u00e1 Oseas hijo de Nun, le puso Mois\u00e9s el nombre de Josu\u00e9.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Envi\u00f3los, pues, Mois\u00e9s \u00e1 reconocer la tierra de Cana\u00e1n, dici\u00e9ndoles: Subid por aqu\u00ed, por el mediod\u00eda, y subid al monte:  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y observad la tierra qu\u00e9 tal es; y el pueblo que la habita, si es fuerte \u00f3 d\u00e9bil, si poco \u00f3 numeroso;  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Qu\u00e9 tal la tierra habitada, si es buena \u00f3 mala; y qu\u00e9 tales son las ciudades habitadas, si de tiendas \u00f3 de fortalezas;  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y cu\u00e1l sea el terreno, si es ping\u00fce \u00f3 flaco, si en \u00e9l hay \u00f3 no \u00e1rboles: y esforzaos, y coged del fruto del pa\u00eds. Y el tiempo era el tiempo de las primeras uvas.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y ellos subieron, y reconocieron la tierra desde el desierto de Zin hasta Rehob, entrando en Emath.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y subieron por el mediod\u00eda, y vinieron hasta Hebr\u00f3n: y all\u00ed estaban Aim\u00e1n, y Sesai, y Talmai, hijos de Anac. Hebr\u00f3n fu\u00e9 edificada siete a\u00f1os antes de Zo\u00e1n, la de Egipto.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y llegaron hasta el arroyo de Escol, y de all\u00ed cortaron un sarmiento con un racimo de uvas, el cual trajeron dos en un palo, y de las granadas y de los higos.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y llam\u00f3se aquel lugar Nahal-escol, por el racimo que cortaron de all\u00ed los hijos de Israel.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Y volvieron de reconocer la tierra al cabo de cuarenta d\u00edas.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Y anduvieron y vinieron \u00e1 Mois\u00e9s y \u00e1 Aar\u00f3n, y \u00e1 toda la congregaci\u00f3n de los hijos de Israel, en el desierto de Par\u00e1n, en Cades, y di\u00e9ronles la respuesta, y \u00e1 toda la congregaci\u00f3n, y les mostraron el fruto de la tierra.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Y le contaron, y dijeron: Nosotros llegamos \u00e1 la tierra \u00e1 la cual nos enviaste, la que ciertamente fluye leche y miel; y este es el fruto de ella.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Mas el pueblo que habita aquella tierra es fuerte, y las ciudades muy grandes y fuertes; y tambi\u00e9n vimos all\u00ed los hijos de Anac.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Amalec habita la tierra del mediod\u00eda; y el Hetheo, y el Jebuseo, y el Amorrheo, habitan en el monte; y el Cananeo habita junto \u00e1 la mar, y \u00e1 la ribera del Jord\u00e1n.  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Entonces Caleb hizo callar el pueblo delante de Mois\u00e9s, y dijo: Subamos luego, y pose\u00e1mosla; que m\u00e1s podremos que ella.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Mas los varones que subieron con \u00e9l, dijeron: No podremos subir contra aquel pueblo; porque es m\u00e1s fuerte que nosotros.  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Y vituperaron entre los hijos de Israel la tierra que hab\u00edan reconocido, diciendo: La tierra por donde pasamos para reconocerla, es tierra que traga \u00e1 sus moradores; y todo el pueblo que vimos en medio de ella, son hombres de grande estatura. Tambi\u00e9n vimos all\u00ed gigantes, hijos de Anac, <span class=\"add\">raza<\/span> de los gigantes: y \u00e9ramos nosotros, \u00e1 nuestro parecer, como langostas; y as\u00ed les parec\u00edamos \u00e1 ellos.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de N\u00fameros<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num36\">36<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>13 1\u00a0 Y DESPU\u00c9S movi\u00f3 el pueblo de Haseroth, y asentaron el campo en el desierto de Par\u00e1n. 2\u00a0 Y Jehov\u00e1 habl\u00f3 \u00e1 Mois\u00e9s, diciendo: 3\u00a0 Env\u00eda t\u00fa hombres que reconozcan la tierra de Cana\u00e1n, la cual yo doy \u00e1 los hijos de Israel: de cada tribu de sus padres enviar\u00e9is un var\u00f3n, cada uno pr\u00edncipe entre ellos. 4\u00a0 Y Mois\u00e9s los envi\u00f3 desde el desierto de Par\u00e1n, conforme \u00e1 la palabra de Jehov\u00e1: y todos aquellos varones eran pr\u00edncipes de los hijos de Israel. 5\u00a0 Los nombres de los cuales son \u00e9stos: De la tribu de Rub\u00e9n, Sammua hijo de Zaccur. 6\u00a0 De la tribu de Sime\u00f3n, Saphat hijo de Hur\u00ed. 7\u00a0 De la tribu de Jud\u00e1, Caleb hijo de Jephone. 8\u00a0 De la tribu de Issach\u00e2r, Igal hijo de Joseph. 9\u00a0 De la tribu de Ephraim, Oseas hijo de Nun. 10\u00a0 De la tribu de Benjam\u00edn, Palti hijo de Raphu. 11\u00a0 De la tribu de Zabul\u00f3n, Gaddiel hijo de Sodi. 12\u00a0 De la tribu de Jos\u00e9, de la tribu de Manas\u00e9s, Gaddi hijo de Susi. 13\u00a0 De la tribu de Dan, Ammiel hijo de Gemalli. 14\u00a0 De la tribu de Aser, Sethur hijo de Mich\u00e2el. 15\u00a0 De la tribu de Nephtal\u00ed, Nahab\u00ed hijo de Vapsi. 16\u00a0 De la tribu de Gad, Geuel hijo de Mach\u00ee. 17\u00a0 Estos son los nombres de los varones que Mois\u00e9s envi\u00f3 \u00e1 reconocer la tierra: y \u00e1 Oseas hijo de Nun, le puso Mois\u00e9s el nombre de Josu\u00e9. 18\u00a0 Envi\u00f3los, pues, Mois\u00e9s \u00e1 reconocer la tierra de Cana\u00e1n, dici\u00e9ndoles: Subid por aqu\u00ed, por el mediod\u00eda, y subid al monte: 19\u00a0 Y observad la tierra qu\u00e9 tal es; y el pueblo que la habita, si es fuerte \u00f3 d\u00e9bil, si poco \u00f3 numeroso; 20\u00a0 Qu\u00e9 tal la tierra habitada, si es buena \u00f3 mala;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5819","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5819"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5819\/revisions"}],"predecessor-version":[{"id":7047,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5819\/revisions\/7047"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}