{"id":5842,"date":"2015-12-10T22:18:30","date_gmt":"2015-12-10T22:18:30","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/num36\/"},"modified":"2019-08-04T00:45:03","modified_gmt":"2019-08-04T04:45:03","slug":"num36","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/num36\/","title":{"rendered":"N\u00fameros 36"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 36<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y LLEGARON los pr\u00edncipes de los padres de la familia de Galaad, hijo de Mach\u00eer, hijo de Manas\u00e9s, de las familias de los hijos de Jos\u00e9; y hablaron delante de Mois\u00e9s, y de los pr\u00edncipes, cabezas de padres de los hijos de Israel,  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y dijeron: Jehov\u00e1 mand\u00f3 \u00e1 mi se\u00f1or que por suerte diese la tierra \u00e1 los hijos de Israel en posesi\u00f3n: tambi\u00e9n ha mandado Jehov\u00e1 \u00e1 mi se\u00f1or, que d\u00e9 la posesi\u00f3n de Salphaad nuestro hermano \u00e1 sus hijas;  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Las cuales, si se casaren con algunos de los hijos de las <span class=\"add\">otras<\/span> tribus de los hijos de Israel, la herencia de ellas ser\u00e1 as\u00ed desfalcada de la herencia de nuestros padres, y ser\u00e1 a\u00f1adida \u00e1 la herencia de la tribu \u00e1 que ser\u00e1n <span class=\"add\">unidas<\/span>: y ser\u00e1 quitada de la suerte de nuestra heredad.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y cuando viniere el jubileo de los hijos de Israel, la heredad de ellas ser\u00e1 a\u00f1adida \u00e1 la heredad de la tribu de sus maridos; y as\u00ed la heredad de ellas ser\u00e1 quitada de la heredad de la tribu de nuestros padres.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Entonces Mois\u00e9s mand\u00f3 \u00e1 los hijos de Israel por dicho de Jehov\u00e1, diciendo: La tribu de los hijos de Jos\u00e9 habla rectamente.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Esto es lo que ha mandado Jehov\u00e1 acerca de las hijas de Salphaad, diciendo: C\u00e1sense como \u00e1 ellas les pluguiere, empero en la familia de la tribu de su padre se casar\u00e1n;  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Para que la heredad de los hijos de Israel no sea traspasada de tribu en tribu; porque cada uno de los hijos de Israel se allegar\u00e1 \u00e1 la heredad de la tribu de sus padres.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y cualquiera hija que poseyere heredad de las tribus de los hijos de Israel, con alguno de la familia de la tribu de su padre se casar\u00e1, para que los hijos de Israel posean cada uno la heredad de sus padres,  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y no ande la heredad rodando de una tribu \u00e1 otra: mas cada una de las tribus de los hijos de Israel se llegue \u00e1 su heredad.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Como Jehov\u00e1 mand\u00f3 \u00e1 Mois\u00e9s, as\u00ed hicieron las hijas de Salphaad.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y <span class=\"add\">as\u00ed<\/span> Maala, y Tirsa, y Hogla, y Milch\u00e2, y Noa, hijas de Salphaad, se casaron con hijos de sus t\u00edos:  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> De la familia de los hijos de Manas\u00e9s, hijo de Jos\u00e9, fueron mujeres; y la heredad de ellas qued\u00f3 en la tribu de la familia de su padre.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Estos son los mandamientos y los estatutos que mand\u00f3 Jehov\u00e1 por mano de Mois\u00e9s \u00e1 los hijos de Israel en los campos de Moab, junto al Jord\u00e1n de Jeric\u00f3.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de N\u00fameros<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num31\">31<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num32\">32<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num33\">33<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num34\">34<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num35\">35<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/num36\">36<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>36 1\u00a0 Y LLEGARON los pr\u00edncipes de los padres de la familia de Galaad, hijo de Mach\u00eer, hijo de Manas\u00e9s, de las familias de los hijos de Jos\u00e9; y hablaron delante de Mois\u00e9s, y de los pr\u00edncipes, cabezas de padres de los hijos de Israel, 2\u00a0 Y dijeron: Jehov\u00e1 mand\u00f3 \u00e1 mi se\u00f1or que por suerte diese la tierra \u00e1 los hijos de Israel en posesi\u00f3n: tambi\u00e9n ha mandado Jehov\u00e1 \u00e1 mi se\u00f1or, que d\u00e9 la posesi\u00f3n de Salphaad nuestro hermano \u00e1 sus hijas; 3\u00a0 Las cuales, si se casaren con algunos de los hijos de las otras tribus de los hijos de Israel, la herencia de ellas ser\u00e1 as\u00ed desfalcada de la herencia de nuestros padres, y ser\u00e1 a\u00f1adida \u00e1 la herencia de la tribu \u00e1 que ser\u00e1n unidas: y ser\u00e1 quitada de la suerte de nuestra heredad. 4\u00a0 Y cuando viniere el jubileo de los hijos de Israel, la heredad de ellas ser\u00e1 a\u00f1adida \u00e1 la heredad de la tribu de sus maridos; y as\u00ed la heredad de ellas ser\u00e1 quitada de la heredad de la tribu de nuestros padres. 5\u00a0 Entonces Mois\u00e9s mand\u00f3 \u00e1 los hijos de Israel por dicho de Jehov\u00e1, diciendo: La tribu de los hijos de Jos\u00e9 habla rectamente. 6\u00a0 Esto es lo que ha mandado Jehov\u00e1 acerca de las hijas de Salphaad, diciendo: C\u00e1sense como \u00e1 ellas les pluguiere, empero en la familia de la tribu de su padre se casar\u00e1n; 7\u00a0 Para que la heredad de los hijos de Israel no sea traspasada de tribu en tribu; porque cada uno de los hijos de Israel se allegar\u00e1 \u00e1 la heredad de la tribu de sus padres. 8\u00a0 Y cualquiera hija que poseyere heredad de las tribus de los hijos de Israel, con alguno de la familia de la tribu de su padre&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5842","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5842"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5842\/revisions"}],"predecessor-version":[{"id":7056,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5842\/revisions\/7056"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}