{"id":5844,"date":"2015-12-10T22:18:34","date_gmt":"2015-12-10T22:18:34","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/pro01\/"},"modified":"2020-03-09T04:23:27","modified_gmt":"2020-03-09T08:23:27","slug":"pro01","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/pro01\/","title":{"rendered":"Proverbios 1"},"content":{"rendered":"<div class=\"main\">\r\n  <div class=\"mt\">Proverbios  <\/div><div class=\"chapterlabel\" id=\"V0\"> 1<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> LOS proverbios de Salom\u00f3n, hijo de David, rey de Israel:  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Para entender sabidur\u00eda y doctrina; para conocer las razones prudentes;  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Para recibir el consejo de prudencia, justicia, y juicio y equidad;  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Para dar sagacidad \u00e1 los simples, y \u00e1 los j\u00f3venes inteligencia y cordura.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Oir\u00e1 el sabio, y aumentar\u00e1 el saber; y el entendido adquirir\u00e1 consejo;  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Para entender par\u00e1bola y declaraci\u00f3n; palabras de sabios, y sus dichos oscuros.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> El principio de la sabidur\u00eda es el temor de Jehov\u00e1: los insensatos desprecian la sabidur\u00eda y la ense\u00f1anza.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Oye, hijo m\u00edo, la doctrina de tu padre, y no desprecies la direcci\u00f3n de tu madre:  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Porque adorno de gracia ser\u00e1n \u00e1 tu cabeza, y collares \u00e1 tu cuello.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Hijo m\u00edo, si los pecadores te quisieren enga\u00f1ar, no consientas.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Si dijeren: Ven con nosotros, pongamos asechanzas \u00e1 la sangre, acechemos sin motivo al inocente;  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Los tragaremos vivos como el sepulcro, y enteros, como los que caen en sima;  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Hallaremos riquezas de todas suertes, henchiremos nuestras casas de despojos;  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Echa tu suerte entre nosotros; tengamos todos una bolsa:  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Hijo m\u00edo, no andes en camino con ellos; aparta tu pie de sus veredas:  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Porque sus pies correr\u00e1n al mal, \u00e9 ir\u00e1n presurosos \u00e1 derramar sangre.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Porque en vano se tender\u00e1 la red ante los ojos de toda ave;  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Mas ellos \u00e1 su propia sangre ponen asechanzas, y \u00e1 sus almas tienden lazo.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Tales son las sendas de todo el que es dado \u00e1 la codicia, <span class=\"add\">la cual<\/span> prender\u00e1 el alma de sus poseedores.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> La sabidur\u00eda clama de fuera, da su voz en las plazas:  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Clama en los principales lugares de concurso; en las entradas de las puertas de la ciudad dice sus razones:  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> \u00bfHasta cu\u00e1ndo, oh simples, amar\u00e9is la simpleza, y los burladores desear\u00e1n el burlar, y los insensatos aborrecer\u00e1n la ciencia?  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Volveos \u00e1 mi reprensi\u00f3n: he aqu\u00ed yo os derramar\u00e9 mi esp\u00edritu, y os har\u00e9 saber mis palabras.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Por cuanto llam\u00e9, y no quisisteis; extend\u00ed mi mano, y no hubo quien escuchase;  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Antes desechasteis todo consejo m\u00edo, y mi reprensi\u00f3n no quisisteis:  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Tambi\u00e9n yo me reir\u00e9 en vuestra calamidad, y me burlar\u00e9 cuando <span class=\"add\">os<\/span> viniere lo que tem\u00e9is;  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Cuando viniere como una destrucci\u00f3n lo que tem\u00e9is, y vuestra calamidad llegare como un torbellino; cuando sobre vosotros viniere tribulaci\u00f3n y angustia.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Entonces me llamar\u00e1n, y no responder\u00e9; buscarme han de ma\u00f1ana, y no me hallar\u00e1n:  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Por cuanto aborrecieron la sabidur\u00eda, y no escogieron el temor de Jehov\u00e1,  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Ni quisieron mi consejo, y menospreciaron toda reprensi\u00f3n m\u00eda:  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Comer\u00e1n pues del fruto de su camino, y se hartar\u00e1n de sus consejos.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Porque el reposo de los ignorantes los matar\u00e1, y la prosperidad de los necios los echar\u00e1 \u00e1 perder.  <span class=\"verse\" id=\"V33\">33\u00a0<\/span> Mas el que me oyere, habitar\u00e1 confiadamente, y vivir\u00e1 reposado, sin temor de mal.  <\/div><hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Proverbios<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro28\">28<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro29\">29<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro30\">30<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/pro31\">31<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>Proverbios 1 1\u00a0 LOS proverbios de Salom\u00f3n, hijo de David, rey de Israel: 2\u00a0 Para entender sabidur\u00eda y doctrina; para conocer las razones prudentes; 3\u00a0 Para recibir el consejo de prudencia, justicia, y juicio y equidad; 4\u00a0 Para dar sagacidad \u00e1 los simples, y \u00e1 los j\u00f3venes inteligencia y cordura. 5\u00a0 Oir\u00e1 el sabio, y aumentar\u00e1 el saber; y el entendido adquirir\u00e1 consejo; 6\u00a0 Para entender par\u00e1bola y declaraci\u00f3n; palabras de sabios, y sus dichos oscuros. 7\u00a0 El principio de la sabidur\u00eda es el temor de Jehov\u00e1: los insensatos desprecian la sabidur\u00eda y la ense\u00f1anza. 8\u00a0 Oye, hijo m\u00edo, la doctrina de tu padre, y no desprecies la direcci\u00f3n de tu madre: 9\u00a0 Porque adorno de gracia ser\u00e1n \u00e1 tu cabeza, y collares \u00e1 tu cuello. 10\u00a0 Hijo m\u00edo, si los pecadores te quisieren enga\u00f1ar, no consientas. 11\u00a0 Si dijeren: Ven con nosotros, pongamos asechanzas \u00e1 la sangre, acechemos sin motivo al inocente; 12\u00a0 Los tragaremos vivos como el sepulcro, y enteros, como los que caen en sima; 13\u00a0 Hallaremos riquezas de todas suertes, henchiremos nuestras casas de despojos; 14\u00a0 Echa tu suerte entre nosotros; tengamos todos una bolsa: 15\u00a0 Hijo m\u00edo, no andes en camino con ellos; aparta tu pie de sus veredas: 16\u00a0 Porque sus pies correr\u00e1n al mal, \u00e9 ir\u00e1n presurosos \u00e1 derramar sangre. 17\u00a0 Porque en vano se tender\u00e1 la red ante los ojos de toda ave; 18\u00a0 Mas ellos \u00e1 su propia sangre ponen asechanzas, y \u00e1 sus almas tienden lazo. 19\u00a0 Tales son las sendas de todo el que es dado \u00e1 la codicia, la cual prender\u00e1 el alma de sus poseedores. 20\u00a0 La sabidur\u00eda clama de fuera, da su voz en las plazas: 21\u00a0 Clama en los principales lugares de concurso; en las entradas de las puertas de la ciudad dice sus razones:&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5844","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=5844"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5844\/revisions"}],"predecessor-version":[{"id":7574,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/5844\/revisions\/7574"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=5844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=5844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=5844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}