{"id":6127,"date":"2015-12-10T22:18:07","date_gmt":"2015-12-10T22:18:07","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/act12\/"},"modified":"2019-08-26T16:54:41","modified_gmt":"2019-08-26T20:54:41","slug":"act12","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/act12\/","title":{"rendered":"Hechos 12"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 12<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y EN el mismo tiempo el rey Herodes ech\u00f3 mano \u00e1 maltratar algunos de la iglesia.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y mat\u00f3 \u00e1 cuchillo \u00e1 Jacobo, hermano de Juan.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y viendo que hab\u00eda agradado \u00e1 los Jud\u00edos, pas\u00f3 adelante para prender tambi\u00e9n \u00e1 Pedro. Eran entonces los d\u00edas de los \u00e1zimos.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y habi\u00e9ndole preso, p\u00fasole en la c\u00e1rcel, entreg\u00e1ndole \u00e1 cuatro cuaterniones de soldados que le guardasen; queriendo sacarle al pueblo despu\u00e9s de la Pascua.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> As\u00ed que, Pedro era guardado en la c\u00e1rcel; y la iglesia hac\u00eda sin cesar oraci\u00f3n \u00e1 Dios por \u00e9l.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y cuando Herodes le hab\u00eda de sacar, aquella misma noche estaba Pedro durmiendo entre dos soldados, preso con dos cadenas, y los guardas delante de la puerta, que guardaban la c\u00e1rcel.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y he aqu\u00ed, el \u00e1ngel del Se\u00f1or sobrevino, y una luz resplandeci\u00f3 en la c\u00e1rcel; \u00e9 hiriendo \u00e1 Pedro en el lado, le despert\u00f3, diciendo: Lev\u00e1ntate prestamente. Y las cadenas se le cayeron de las manos.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y le dijo el \u00e1ngel: C\u00ed\u00f1ete, y \u00e1tate tus sandalias. Y lo hizo as\u00ed. Y le dijo: Rod\u00e9ate tu ropa, y s\u00edgueme.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y saliendo, le segu\u00eda; y no sab\u00eda que era verdad lo que hac\u00eda el \u00e1ngel, mas pensaba que ve\u00eda visi\u00f3n.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y como pasaron la primera y la segunda guardia, vinieron \u00e1 la puerta de hierro que va \u00e1 la ciudad, la cual se les abri\u00f3 de suyo: y salidos, pasaron una calle; y luego el \u00e1ngel se apart\u00f3 de \u00e9l.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Entonces Pedro, volviendo en s\u00ed, dijo: Ahora entiendo verdaderamente que el Se\u00f1or ha enviado su \u00e1ngel, y me ha librado de la mano de Herodes, y de todo el pueblo de los Jud\u00edos que me esperaba.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y habiendo considerado <span class=\"add\">esto<\/span>, lleg\u00f3 \u00e1 casa de Mar\u00eda la madre de Juan, el que ten\u00eda por sobrenombre Marcos, donde muchos estaban juntos orando.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Y tocando Pedro \u00e1 la puerta del patio, sali\u00f3 una muchacha, para escuchar, llamada Rhode:  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> La cual como conoci\u00f3 la voz de Pedro, de gozo no abri\u00f3 el postigo, sino corriendo adentro, di\u00f3 nueva de que Pedro estaba al postigo.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y ellos le dijeron: Est\u00e1s loca. Mas ella afirmaba que as\u00ed era. Entonces ellos dec\u00edan: Su \u00e1ngel es.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Mas Pedro perseveraba en llamar: y cuando abrieron, vi\u00e9ronle, y se espantaron.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Mas \u00e9l haci\u00e9ndoles con la mano se\u00f1al de que callasen, les cont\u00f3 c\u00f3mo el Se\u00f1or le hab\u00eda sacado de la c\u00e1rcel. Y dijo: Haced saber esto \u00e1 Jacobo y \u00e1 los hermanos. Y sali\u00f3, y parti\u00f3 \u00e1 otro lugar.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Luego que fu\u00e9 de d\u00eda, hubo no poco alboroto entre los soldados sobre qu\u00e9 se hab\u00eda hecho de Pedro.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Mas Herodes, como le busc\u00f3 y no le hall\u00f3, hecha inquisici\u00f3n de los guardas, los mand\u00f3 llevar. Despu\u00e9s descendiendo de Judea \u00e1 Cesarea, se qued\u00f3 <span class=\"add\">all\u00ed<\/span>.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Y Herodes estaba enojado contra los de Tiro y los de Sid\u00f3n: mas ellos vinieron concordes \u00e1 \u00e9l, y sobornado Blasto, que era el camarero del rey, ped\u00edan paz; porque las tierras de ellos eran abastecidas por las del rey.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Y un d\u00eda se\u00f1alado, Herodes vestido de ropa real, se sent\u00f3 en el tribunal, y areng\u00f3les.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Y el pueblo aclamaba: Voz de Dios, y no de hombre.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y luego el \u00e1ngel del Se\u00f1or le hiri\u00f3, por cuanto no di\u00f3 la gloria \u00e1 Dios; y espir\u00f3 comido de gusanos.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Mas la palabra del Se\u00f1or crec\u00eda y era multiplicada.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y Bernab\u00e9 y Saulo volvieron de Jerusalem cumplido su servicio, tomando tambi\u00e9n consigo \u00e1 Juan, el que ten\u00eda por sobrenombre Marcos.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Hechos de los Apostoles<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act28\">28<\/a>\r\n  <\/div>\r\n  ","protected":false},"excerpt":{"rendered":"<p>12 1\u00a0 Y EN el mismo tiempo el rey Herodes ech\u00f3 mano \u00e1 maltratar algunos de la iglesia. 2\u00a0 Y mat\u00f3 \u00e1 cuchillo \u00e1 Jacobo, hermano de Juan. 3\u00a0 Y viendo que hab\u00eda agradado \u00e1 los Jud\u00edos, pas\u00f3 adelante para prender tambi\u00e9n \u00e1 Pedro. Eran entonces los d\u00edas de los \u00e1zimos. 4\u00a0 Y habi\u00e9ndole preso, p\u00fasole en la c\u00e1rcel, entreg\u00e1ndole \u00e1 cuatro cuaterniones de soldados que le guardasen; queriendo sacarle al pueblo despu\u00e9s de la Pascua. 5\u00a0 As\u00ed que, Pedro era guardado en la c\u00e1rcel; y la iglesia hac\u00eda sin cesar oraci\u00f3n \u00e1 Dios por \u00e9l. 6\u00a0 Y cuando Herodes le hab\u00eda de sacar, aquella misma noche estaba Pedro durmiendo entre dos soldados, preso con dos cadenas, y los guardas delante de la puerta, que guardaban la c\u00e1rcel. 7\u00a0 Y he aqu\u00ed, el \u00e1ngel del Se\u00f1or sobrevino, y una luz resplandeci\u00f3 en la c\u00e1rcel; \u00e9 hiriendo \u00e1 Pedro en el lado, le despert\u00f3, diciendo: Lev\u00e1ntate prestamente. Y las cadenas se le cayeron de las manos. 8\u00a0 Y le dijo el \u00e1ngel: C\u00ed\u00f1ete, y \u00e1tate tus sandalias. Y lo hizo as\u00ed. Y le dijo: Rod\u00e9ate tu ropa, y s\u00edgueme. 9\u00a0 Y saliendo, le segu\u00eda; y no sab\u00eda que era verdad lo que hac\u00eda el \u00e1ngel, mas pensaba que ve\u00eda visi\u00f3n. 10\u00a0 Y como pasaron la primera y la segunda guardia, vinieron \u00e1 la puerta de hierro que va \u00e1 la ciudad, la cual se les abri\u00f3 de suyo: y salidos, pasaron una calle; y luego el \u00e1ngel se apart\u00f3 de \u00e9l. 11\u00a0 Entonces Pedro, volviendo en s\u00ed, dijo: Ahora entiendo verdaderamente que el Se\u00f1or ha enviado su \u00e1ngel, y me ha librado de la mano de Herodes, y de todo el pueblo de los Jud\u00edos que me esperaba. 12\u00a0 Y habiendo considerado esto, lleg\u00f3 \u00e1 casa de Mar\u00eda la madre de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6127","post","type-post","status-publish","format-standard","hentry","category-nuevotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=6127"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6127\/revisions"}],"predecessor-version":[{"id":7192,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6127\/revisions\/7192"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=6127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=6127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=6127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}