{"id":6141,"date":"2015-12-10T22:18:08","date_gmt":"2015-12-10T22:18:08","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/act26\/"},"modified":"2019-08-26T16:58:08","modified_gmt":"2019-08-26T20:58:08","slug":"act26","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/act26\/","title":{"rendered":"Hechos 26"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 26<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> ENTONCES Agripa dijo \u00e1 Pablo: Se te permite hablar por ti mismo. Pablo entonces, extendiendo la mano, comenz\u00f3 \u00e1 responder por s\u00ed, <span class=\"add\">diciendo<\/span>:  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Acerca de todas las cosas de que soy acusado por los Jud\u00edos, oh rey Agripa, me tengo por dichoso de que haya hoy de defenderme delante de ti;  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Mayormente sabiendo t\u00fa todas las costumbres y cuestiones que hay entre los Jud\u00edos: por lo cual te ruego que me oigas con paciencia.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Mi vida pues desde la mocedad, la cual desde el principio fu\u00e9 en mi naci\u00f3n, en Jerusalem, todos los Jud\u00edos la saben:  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Los cuales tienen ya conocido que yo desde el principio, si quieren testificarlo, conforme \u00e1 la m\u00e1s rigurosa secta de nuestra religi\u00f3n he vivido Fariseo.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y ahora, por la esperanza de la promesa que hizo Dios \u00e1 nuestros padres, soy llamado en juicio;  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> A la cual <span class=\"add\">promesa<\/span> nuestras doce tribus, sirviendo constantemente de d\u00eda y de noche, esperan que han de llegar. Por la cual esperanza, oh rey Agripa, soy acusado de los Jud\u00edos.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> \u00a1Qu\u00e9! \u00bfJ\u00fazgase cosa incre\u00edble entre vosotros que Dios resucite los muertos?  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Yo ciertamente hab\u00eda pensado deber hacer muchas cosas contra el nombre de Jes\u00fas de Nazaret:  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Lo cual tambi\u00e9n hice en Jerusalem, y yo encerr\u00e9 en c\u00e1rceles \u00e1 muchos de los santos, recibida potestad de los pr\u00edncipes de los sacerdotes; y cuando eran matados, yo d\u00ed mi voto.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Y muchas veces, castig\u00e1ndolos por todas las sinagogas, los forc\u00e9 \u00e1 blasfemar; y enfurecido sobremanera contra ellos, los persegu\u00ed hasta en las ciudades extra\u00f1as.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> En lo cual <span class=\"add\">ocupado<\/span>, yendo \u00e1 Damasco con potestad y comisi\u00f3n de los pr\u00edncipes de los sacerdotes,  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> En mitad del d\u00eda, oh rey, vi en el camino una luz del cielo, que sobrepujaba el resplandor del sol, la cual me rode\u00f3 y \u00e1 los que iban conmigo.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y habiendo ca\u00eddo todos nosotros en tierra, o\u00ed una voz que me hablaba, y dec\u00eda en lengua hebraica: Saulo, Saulo, \u00bfpor qu\u00e9 me persigues? Dura cosa te es dar coces contra los aguijones.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Yo entonces dije: \u00bfQui\u00e9n eres, Se\u00f1or? Y el Se\u00f1or dijo: Yo soy Jes\u00fas, \u00e1 quien t\u00fa persigues.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Mas lev\u00e1ntate, y ponte sobre tus pies; porque para esto te he aparecido, para ponerte por ministro y testigo de las cosas que has visto, y de aquellas en que aparecer\u00e9 \u00e1 ti:  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Libr\u00e1ndote del pueblo y de los Gentiles, \u00e1 los cuales ahora te env\u00edo,  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Para que abras sus ojos, para que se conviertan de las tinieblas \u00e1 la luz, y de la potestad de Satan\u00e1s \u00e1 Dios; para que reciban, por la fe que es en m\u00ed, remisi\u00f3n de pecados y suerte entre los santificados.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Por lo cual, oh rey Agripa, no fu\u00ed rebelde \u00e1 la visi\u00f3n celestial:  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> Antes anunci\u00e9 primeramente \u00e1 los que est\u00e1n en Damasco, y Jerusalem, y por toda la tierra de Judea, y \u00e1 los Gentiles, que se arrepintiesen y se convirtiesen \u00e1 Dios, haciendo obras dignas de arrepentimiento.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Por causa de esto los Jud\u00edos, tom\u00e1ndome en el templo, tentaron matarme.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Mas ayudado del auxilio de Dios, persevero hasta el d\u00eda de hoy, dando testimonio \u00e1 peque\u00f1os y \u00e1 grandes, no diciendo nada fuera de las cosas que los profetas y Mois\u00e9s dijeron que hab\u00edan de venir:  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Que Cristo hab\u00eda de padecer, y ser el primero de la resurrecci\u00f3n de los muertos, para anunciar luz al pueblo y \u00e1 los Gentiles.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y diciendo \u00e9l estas cosas en su defensa, Festo \u00e1 gran voz dijo: Est\u00e1s loco, Pablo: las muchas letras te vuelven loco.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Mas \u00e9l dijo: No estoy loco, excelent\u00edsimo Festo, sino que hablo palabras de verdad y de templanza.  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Pues el rey sabe estas cosas, delante del cual tambi\u00e9n hablo confiadamente. Pues no pienso que ignora nada de esto; pues no ha sido esto hecho en <span class=\"add\">alg\u00fan<\/span> rinc\u00f3n.  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> \u00bfCrees, rey Agripa, \u00e1 los profetas? Yo s\u00e9 que crees.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> Entonces Agripa dijo \u00e1 Pablo: Por poco me persuades \u00e1 ser Cristiano.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Y Pablo dijo: \u00a1Pluguiese \u00e1 Dios que por poco \u00f3 por mucho, no solamente t\u00fa, mas tambi\u00e9n todos los que hoy me oyen, fueseis hechos tales cual yo soy, excepto estas prisiones!  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Y como hubo dicho estas cosas, se levant\u00f3 el rey, y el presidente, y Bernice, y los que se hab\u00edan sentado con ellos;  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Y como se retiraron aparte, hablaban los unos \u00e1 los otros, diciendo: Ninguna cosa digna ni de muerte, ni de prisi\u00f3n, hace este hombre.  <span class=\"verse\" id=\"V32\">32\u00a0<\/span> Y Agripa dijo \u00e1 Festo: Pod\u00eda este hombre ser suelto, si no hubiera apelado \u00e1 C\u00e9sar.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Hechos de los Apostoles<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act28\">28<\/a>\r\n  <\/div>\r\n  ","protected":false},"excerpt":{"rendered":"<p>26 1\u00a0 ENTONCES Agripa dijo \u00e1 Pablo: Se te permite hablar por ti mismo. Pablo entonces, extendiendo la mano, comenz\u00f3 \u00e1 responder por s\u00ed, diciendo: 2\u00a0 Acerca de todas las cosas de que soy acusado por los Jud\u00edos, oh rey Agripa, me tengo por dichoso de que haya hoy de defenderme delante de ti; 3\u00a0 Mayormente sabiendo t\u00fa todas las costumbres y cuestiones que hay entre los Jud\u00edos: por lo cual te ruego que me oigas con paciencia. 4\u00a0 Mi vida pues desde la mocedad, la cual desde el principio fu\u00e9 en mi naci\u00f3n, en Jerusalem, todos los Jud\u00edos la saben: 5\u00a0 Los cuales tienen ya conocido que yo desde el principio, si quieren testificarlo, conforme \u00e1 la m\u00e1s rigurosa secta de nuestra religi\u00f3n he vivido Fariseo. 6\u00a0 Y ahora, por la esperanza de la promesa que hizo Dios \u00e1 nuestros padres, soy llamado en juicio; 7\u00a0 A la cual promesa nuestras doce tribus, sirviendo constantemente de d\u00eda y de noche, esperan que han de llegar. Por la cual esperanza, oh rey Agripa, soy acusado de los Jud\u00edos. 8\u00a0 \u00a1Qu\u00e9! \u00bfJ\u00fazgase cosa incre\u00edble entre vosotros que Dios resucite los muertos? 9\u00a0 Yo ciertamente hab\u00eda pensado deber hacer muchas cosas contra el nombre de Jes\u00fas de Nazaret: 10\u00a0 Lo cual tambi\u00e9n hice en Jerusalem, y yo encerr\u00e9 en c\u00e1rceles \u00e1 muchos de los santos, recibida potestad de los pr\u00edncipes de los sacerdotes; y cuando eran matados, yo d\u00ed mi voto. 11\u00a0 Y muchas veces, castig\u00e1ndolos por todas las sinagogas, los forc\u00e9 \u00e1 blasfemar; y enfurecido sobremanera contra ellos, los persegu\u00ed hasta en las ciudades extra\u00f1as. 12\u00a0 En lo cual ocupado, yendo \u00e1 Damasco con potestad y comisi\u00f3n de los pr\u00edncipes de los sacerdotes, 13\u00a0 En mitad del d\u00eda, oh rey, vi en el camino una luz del cielo, que sobrepujaba el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6141","post","type-post","status-publish","format-standard","hentry","category-nuevotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=6141"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6141\/revisions"}],"predecessor-version":[{"id":7205,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6141\/revisions\/7205"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=6141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=6141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=6141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}