{"id":6143,"date":"2015-12-10T22:18:10","date_gmt":"2015-12-10T22:18:10","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/act28\/"},"modified":"2019-08-26T16:57:51","modified_gmt":"2019-08-26T20:57:51","slug":"act28","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/act28\/","title":{"rendered":"Hechos 28"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 28<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y CUANDO escapamos, entonces supimos que la isla se llamaba Melita.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y los b\u00e1rbaros nos mostraron no poca humanidad; porque, encendido un fuego, nos recibieron \u00e1 todos, \u00e1 causa de la lluvia que ven\u00eda, y del fr\u00edo.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Entonces habiendo Pablo recogido algunos sarmientos, y pu\u00e9stolos en el fuego, una v\u00edbora, huyendo del calor, le acometi\u00f3 \u00e1 la mano.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y como los b\u00e1rbaros vieron la v\u00edbora colgando de su mano, dec\u00edan los unos \u00e1 los otros: Ciertamente este hombre es homicida, \u00e1 quien, escapado de la mar, la justicia no deja vivir.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Mas \u00e9l, sacudiendo la v\u00edbora en el fuego, ning\u00fan mal padeci\u00f3.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Empero ellos estaban esperando cu\u00e1ndo se hab\u00eda de hinchar, \u00f3 caer muerto de repente; mas habiendo esperado mucho, y viendo que ning\u00fan mal le ven\u00eda, mudados, dec\u00edan que era un dios.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> En aquellos lugares hab\u00eda heredades del principal de la isla, llamado Publio, el cual nos recibi\u00f3 y hosped\u00f3 tres d\u00edas humanamente.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Y aconteci\u00f3 que el padre de Publio estaba en cama, enfermo de fiebres y de disenter\u00eda: al cual Pablo entr\u00f3, y despu\u00e9s de haber orado, le puso las manos encima, y le san\u00f3:  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y esto hecho, tambi\u00e9n los otros que en la isla ten\u00edan enfermedades, llegaban, y eran sanados:  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Los cuales tambi\u00e9n nos honraron con muchos obsequios; y cuando partimos, nos cargaron de las cosas necesarias.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> As\u00ed que, pasados tres meses, navegamos en una nave Alejandrina que hab\u00eda invernado en la isla, la cual ten\u00eda por ense\u00f1a \u00e1 C\u00e1stor y P\u00f3lux.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y llegados \u00e1 Siracusa, estuvimos all\u00ed tres d\u00edas.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> De all\u00ed, costeando alrededor, vinimos \u00e1 Regio; y otro d\u00eda despu\u00e9s, soplando el austro, vinimos al segundo d\u00eda \u00e1 Puteolos:  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Donde habiendo hallado hermanos, nos rogaron que qued\u00e1semos con ellos siete d\u00edas; y luego vinimos \u00e1 Roma;  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> De donde, oyendo de nosotros los hermanos, nos salieron \u00e1 recibir hasta la plaza de Appio, y Las Tres Tabernas: \u00e1 los cuales como Pablo vi\u00f3, di\u00f3 gracias \u00e1 Dios, y tom\u00f3 aliento.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Y como llegamos \u00e1 Roma, el centuri\u00f3n entreg\u00f3 los presos al prefecto de los ej\u00e9rcitos, mas \u00e1 Pablo fu\u00e9 permitido estar por s\u00ed, con un soldado que le guardase.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y aconteci\u00f3 que tres d\u00edas despu\u00e9s, Pablo convoc\u00f3 \u00e1 los principales de los Jud\u00edos; \u00e1 los cuales, luego que estuvieron juntos, les dijo: Yo, varones hermanos, no habiendo hecho nada contra el pueblo, ni contra los ritos de la patria, he sido entregado preso desde Jerusalem en manos de los Romanos;  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Los cuales, habi\u00e9ndome examinado, me quer\u00edan soltar, por no haber en m\u00ed ninguna causa de muerte.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Mas contradiciendo los Jud\u00edos, fu\u00ed forzado \u00e1 apelar \u00e1 C\u00e9sar; no que tenga de qu\u00e9 acusar \u00e1 mi naci\u00f3n.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> As\u00ed que, por esta causa, os he llamado para veros y hablaros; porque por la esperanza de Israel estoy rodeado de esta cadena.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Entonces ellos le dijeron: Nosotros ni hemos recibido cartas tocante \u00e1 ti de Judea, ni ha venido alguno de los hermanos que haya denunciado \u00f3 hablado alg\u00fan mal de ti.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> Mas querr\u00edamos oir de ti lo que sientes; porque de esta secta notorio nos es que en todos lugares es contradicha.  <span class=\"verse\" id=\"V23\">23\u00a0<\/span> Y habi\u00e9ndole se\u00f1alado un d\u00eda, vinieron \u00e1 \u00e9l muchos \u00e1 la posada, \u00e1 los cuales declaraba y testificaba el reino de Dios, persuadi\u00e9ndoles lo concerniente \u00e1 Jes\u00fas, por la ley de Mois\u00e9s y por los profetas, desde la ma\u00f1ana hasta la tarde.  <span class=\"verse\" id=\"V24\">24\u00a0<\/span> Y algunos asent\u00edan \u00e1 lo que se dec\u00eda, mas algunos no cre\u00edan.  <span class=\"verse\" id=\"V25\">25\u00a0<\/span> Y como fueron entre s\u00ed discordes, se fueron, diciendo Pablo esta palabra: Bien ha hablado el Esp\u00edritu Santo por el profeta Isa\u00edas \u00e1 nuestros padres,  <span class=\"verse\" id=\"V26\">26\u00a0<\/span> Diciendo: Ve \u00e1 este pueblo, y di<span class=\"add\">les<\/span>: De o\u00eddo oir\u00e9is, y no entender\u00e9is; y viendo ver\u00e9is, y no percibir\u00e9is:  <span class=\"verse\" id=\"V27\">27\u00a0<\/span> Porque el coraz\u00f3n de este pueblo se ha engrosado, y de los o\u00eddos oyeron pesadamente, y sus ojos taparon; porque no vean con los ojos, y oigan con los o\u00eddos, y entiendan de coraz\u00f3n, y se conviertan, y yo los sane.  <span class=\"verse\" id=\"V28\">28\u00a0<\/span> S\u00e9aos pues notorio que \u00e1 los Gentiles es enviada esta salud de Dios: y ellos oir\u00e1n.  <span class=\"verse\" id=\"V29\">29\u00a0<\/span> Y habiendo dicho esto, los Jud\u00edos salieron, teniendo entre s\u00ed gran contienda.  <span class=\"verse\" id=\"V30\">30\u00a0<\/span> Pablo empero, qued\u00f3 dos a\u00f1os enteros en su casa de alquiler, y recib\u00eda \u00e1 todos los que \u00e1 \u00e9l ven\u00edan,  <span class=\"verse\" id=\"V31\">31\u00a0<\/span> Predicando el reino de Dios y ense\u00f1ando lo que es del Se\u00f1or Jesucristo con toda libertad, sin impedimento.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Hechos de los Apostoles<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act22\">22<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act23\">23<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act24\">24<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act25\">25<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act26\">26<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act27\">27<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/act28\">28<\/a>\r\n  <\/div>\r\n  ","protected":false},"excerpt":{"rendered":"<p>28 1\u00a0 Y CUANDO escapamos, entonces supimos que la isla se llamaba Melita. 2\u00a0 Y los b\u00e1rbaros nos mostraron no poca humanidad; porque, encendido un fuego, nos recibieron \u00e1 todos, \u00e1 causa de la lluvia que ven\u00eda, y del fr\u00edo. 3\u00a0 Entonces habiendo Pablo recogido algunos sarmientos, y pu\u00e9stolos en el fuego, una v\u00edbora, huyendo del calor, le acometi\u00f3 \u00e1 la mano. 4\u00a0 Y como los b\u00e1rbaros vieron la v\u00edbora colgando de su mano, dec\u00edan los unos \u00e1 los otros: Ciertamente este hombre es homicida, \u00e1 quien, escapado de la mar, la justicia no deja vivir. 5\u00a0 Mas \u00e9l, sacudiendo la v\u00edbora en el fuego, ning\u00fan mal padeci\u00f3. 6\u00a0 Empero ellos estaban esperando cu\u00e1ndo se hab\u00eda de hinchar, \u00f3 caer muerto de repente; mas habiendo esperado mucho, y viendo que ning\u00fan mal le ven\u00eda, mudados, dec\u00edan que era un dios. 7\u00a0 En aquellos lugares hab\u00eda heredades del principal de la isla, llamado Publio, el cual nos recibi\u00f3 y hosped\u00f3 tres d\u00edas humanamente. 8\u00a0 Y aconteci\u00f3 que el padre de Publio estaba en cama, enfermo de fiebres y de disenter\u00eda: al cual Pablo entr\u00f3, y despu\u00e9s de haber orado, le puso las manos encima, y le san\u00f3: 9\u00a0 Y esto hecho, tambi\u00e9n los otros que en la isla ten\u00edan enfermedades, llegaban, y eran sanados: 10\u00a0 Los cuales tambi\u00e9n nos honraron con muchos obsequios; y cuando partimos, nos cargaron de las cosas necesarias. 11\u00a0 As\u00ed que, pasados tres meses, navegamos en una nave Alejandrina que hab\u00eda invernado en la isla, la cual ten\u00eda por ense\u00f1a \u00e1 C\u00e1stor y P\u00f3lux. 12\u00a0 Y llegados \u00e1 Siracusa, estuvimos all\u00ed tres d\u00edas. 13\u00a0 De all\u00ed, costeando alrededor, vinimos \u00e1 Regio; y otro d\u00eda despu\u00e9s, soplando el austro, vinimos al segundo d\u00eda \u00e1 Puteolos: 14\u00a0 Donde habiendo hallado hermanos, nos rogaron que qued\u00e1semos con ellos siete d\u00edas;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6143","post","type-post","status-publish","format-standard","hentry","category-nuevotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=6143"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6143\/revisions"}],"predecessor-version":[{"id":7203,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6143\/revisions\/7203"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=6143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=6143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=6143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}