{"id":6275,"date":"2015-12-10T22:18:13","date_gmt":"2015-12-10T22:18:13","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/rev03\/"},"modified":"2019-08-26T17:44:51","modified_gmt":"2019-08-26T21:44:51","slug":"rev03","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/rev03\/","title":{"rendered":"Apocalipsis 3"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 3<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> Y ESCRIBE al \u00e1ngel de la iglesia en SARDIS: El que tiene los siete Esp\u00edritus de Dios, y las siete estrellas, dice estas cosas: Yo conozco tus obras, que tienes nombre que vives, y est\u00e1s muerto.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> S\u00e9 vigilante y confirma las otras cosas que est\u00e1n para morir; porque no he hallado tus obras perfectas delante de Dios.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Acu\u00e9rdate pues de lo que has recibido y has o\u00eddo, y gu\u00e1rda<span class=\"add\">lo<\/span>, y arrepi\u00e9ntete. Y si no velares, vendr\u00e9 \u00e1 ti como ladr\u00f3n, y no sabr\u00e1s en qu\u00e9 hora vendr\u00e9 \u00e1 ti.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Mas tienes unas pocas personas en Sardis que no han ensuciado sus vestiduras: y andar\u00e1n conmigo en vestiduras blancas; porque son dignos.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> El que venciere, ser\u00e1 vestido de vestiduras blancas; y no borrar\u00e9 su nombre del libro de la vida, y confesar\u00e9 su nombre delante de mi Padre, y delante de sus \u00e1ngeles.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> El que tiene o\u00eddo, oiga lo que el Esp\u00edritu dice \u00e1 las iglesias.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y escribe al \u00e1ngel de la iglesia en FILADELFIA: Estas cosas dice el Santo, el Verdadero, el que tiene la llave de David, el que abre y ninguno cierra, y cierra y ninguno abre:  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Yo conozco tus obras: he aqu\u00ed, he dado una puerta abierta delante de ti, la cual ninguno puede cerrar; porque tienes un poco de potencia, y has guardado mi palabra, y no has negado mi nombre.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> He aqu\u00ed, yo doy de la sinagoga de Satan\u00e1s, los que se dicen ser Jud\u00edos, y no lo son, mas mienten; he aqu\u00ed, yo los constre\u00f1ir\u00e9 \u00e1 que vengan y adoren delante de tus pies, y sepan que yo te he amado.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Porque has guardado la palabra de mi paciencia, yo tambi\u00e9n te guardar\u00e9 de la hora de la tentaci\u00f3n que ha de venir en todo el mundo, para probar \u00e1 los que moran en la tierra.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> He aqu\u00ed, yo vengo presto; ret\u00e9n lo que tienes, para que ninguno tome tu corona.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Al que venciere, yo lo har\u00e9 columna en el templo de mi Dios, y nunca m\u00e1s saldr\u00e1 fuera; y escribir\u00e9 sobre \u00e9l el nombre de mi Dios, y el nombre de la ciudad de mi Dios, la nueva Jerusalem, la cual desciende del cielo de con mi Dios, y mi nombre nuevo.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> El que tiene o\u00eddo, oiga lo que el Esp\u00edritu dice \u00e1 las iglesias.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Y escribe al \u00e1ngel de la iglesia en LAODICEA: He aqu\u00ed dice el Am\u00e9n, el testigo fiel y verdadero, el principio de la creaci\u00f3n de Dios:  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Yo conozco tus obras, que ni eres fr\u00edo, ni caliente. \u00a1Ojal\u00e1 fueses fr\u00edo, \u00f3 caliente!  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Mas porque eres tibio, y no fr\u00edo ni caliente, te vomitar\u00e9 de mi boca.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Porque t\u00fa dices: Yo soy rico, y estoy enriquecido, y no tengo necesidad de ninguna cosa; y no conoces que t\u00fa eres un cuitado y miserable y pobre y ciego y desnudo;  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Yo te amonesto que de m\u00ed compres oro afinado en fuego, para que seas hecho rico, y seas vestido de vestiduras blancas, para que no se descubra la verg\u00fcenza de tu desnudez; y unge tus ojos con colirio, para que veas.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Yo reprendo y castigo \u00e1 todos los que amo: s\u00e9 pues celoso, y arrepi\u00e9ntete.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> He aqu\u00ed, yo estoy \u00e1 la puerta y llamo: si alguno oyere mi voz y abriere la puerta, entrar\u00e9 \u00e1 \u00e9l, y cenar\u00e9 con \u00e9l, y \u00e9l conmigo.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> Al que venciere, yo le dar\u00e9 que se siente conmigo en mi trono; as\u00ed como yo he vencido, y me he sentado con mi Padre en su trono.  <span class=\"verse\" id=\"V22\">22\u00a0<\/span> El que tiene o\u00eddo, oiga lo que el Esp\u00edritu dice \u00e1 las iglesias.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Apocalipsis<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev22\">22<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>3 1\u00a0 Y ESCRIBE al \u00e1ngel de la iglesia en SARDIS: El que tiene los siete Esp\u00edritus de Dios, y las siete estrellas, dice estas cosas: Yo conozco tus obras, que tienes nombre que vives, y est\u00e1s muerto. 2\u00a0 S\u00e9 vigilante y confirma las otras cosas que est\u00e1n para morir; porque no he hallado tus obras perfectas delante de Dios. 3\u00a0 Acu\u00e9rdate pues de lo que has recibido y has o\u00eddo, y gu\u00e1rdalo, y arrepi\u00e9ntete. Y si no velares, vendr\u00e9 \u00e1 ti como ladr\u00f3n, y no sabr\u00e1s en qu\u00e9 hora vendr\u00e9 \u00e1 ti. 4\u00a0 Mas tienes unas pocas personas en Sardis que no han ensuciado sus vestiduras: y andar\u00e1n conmigo en vestiduras blancas; porque son dignos. 5\u00a0 El que venciere, ser\u00e1 vestido de vestiduras blancas; y no borrar\u00e9 su nombre del libro de la vida, y confesar\u00e9 su nombre delante de mi Padre, y delante de sus \u00e1ngeles. 6\u00a0 El que tiene o\u00eddo, oiga lo que el Esp\u00edritu dice \u00e1 las iglesias. 7\u00a0 Y escribe al \u00e1ngel de la iglesia en FILADELFIA: Estas cosas dice el Santo, el Verdadero, el que tiene la llave de David, el que abre y ninguno cierra, y cierra y ninguno abre: 8\u00a0 Yo conozco tus obras: he aqu\u00ed, he dado una puerta abierta delante de ti, la cual ninguno puede cerrar; porque tienes un poco de potencia, y has guardado mi palabra, y no has negado mi nombre. 9\u00a0 He aqu\u00ed, yo doy de la sinagoga de Satan\u00e1s, los que se dicen ser Jud\u00edos, y no lo son, mas mienten; he aqu\u00ed, yo los constre\u00f1ir\u00e9 \u00e1 que vengan y adoren delante de tus pies, y sepan que yo te he amado. 10\u00a0 Porque has guardado la palabra de mi paciencia, yo tambi\u00e9n te guardar\u00e9 de la hora de la tentaci\u00f3n que ha de venir&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6275","post","type-post","status-publish","format-standard","hentry","category-nuevotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=6275"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6275\/revisions"}],"predecessor-version":[{"id":7264,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6275\/revisions\/7264"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=6275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=6275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=6275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}