{"id":6294,"date":"2015-12-10T22:18:09","date_gmt":"2015-12-10T22:18:09","guid":{"rendered":"http:\/\/12tribus.net\/escritura\/rev22\/"},"modified":"2019-08-26T17:44:58","modified_gmt":"2019-08-26T21:44:58","slug":"rev22","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/rev22\/","title":{"rendered":"Apocalipsis 22"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 22<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> DESPU\u00c9S me mostr\u00f3 un r\u00edo limpio de agua de vida, resplandeciente como cristal, que sal\u00eda del trono de Dios y del Cordero.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> En el medio de la plaza de ella, y de la una y de la otra parte del r\u00edo, estaba el \u00e1rbol de la vida, que lleva doce frutos, dando cada mes su fruto: y las hojas del \u00e1rbol eran para la sanidad de las naciones.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y no habr\u00e1 m\u00e1s maldici\u00f3n; sino que el trono de Dios y del Cordero estar\u00e1 en ella, y sus siervos le servir\u00e1n.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y ver\u00e1n su cara; y su nombre <span class=\"add\">estar\u00e1<\/span> en sus frentes.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Y all\u00ed no habr\u00e1 m\u00e1s noche; y no tienen necesidad de lumbre de antorcha, ni de lumbre de sol: porque el Se\u00f1or Dios los alumbrar\u00e1: y reinar\u00e1n para siempre jam\u00e1s.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Y me dijo: Estas palabras son fieles y verdaderas. Y el Se\u00f1or Dios de los santos profetas ha enviado su \u00e1ngel, para mostrar \u00e1 sus siervos las cosas que es necesario que sean hechas presto.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y he aqu\u00ed, vengo presto. Bienaventurado el que guarda las palabras de la profec\u00eda de este libro.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Yo Juan soy el que ha o\u00eddo y visto estas cosas. Y despu\u00e9s que hube o\u00eddo y visto, me postr\u00e9 para adorar delante de los pies del \u00e1ngel que me mostraba estas cosas.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y \u00e9l me dijo: Mira que no lo hagas: porque yo soy siervo contigo, y con tus hermanos los profetas, y con los que guardan las palabras de este libro. Adora \u00e1 Dios.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Y me dijo: No selles las palabras de la profec\u00eda de este libro; porque el tiempo est\u00e1 cerca.  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> El que es injusto, sea injusto todav\u00eda: y el que es sucio, ens\u00faciese todav\u00eda: y el que es justo, sea todav\u00eda justificado: y el santo sea santificado todav\u00eda.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y he aqu\u00ed, yo vengo presto, y mi galard\u00f3n conmigo, para recompensar \u00e1 cada uno seg\u00fan fuere su obra.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Yo soy Alpha y Omega, principio y fin, el primero y el postrero.  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Bienaventurados los que guardan sus mandamientos, para que su potencia sea en el \u00e1rbol de la vida, y que entren por las puertas en la ciudad.  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Mas los perros estar\u00e1n fuera, y los hechiceros, y los disolutos, y los homicidas, y los id\u00f3latras, y cualquiera que ama y hace mentira.  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Yo Jes\u00fas he enviado mi \u00e1ngel para daros testimonio de estas cosas en las iglesias. Yo soy la ra\u00edz y el linaje de David, la estrella resplandeciente, y de la ma\u00f1ana.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Y el Esp\u00edritu y la Esposa dicen: Ven. Y el que oye, diga: Ven. Y el que tiene sed, venga: y el que quiere, tome del agua de la vida de balde.  <span class=\"verse\" id=\"V18\">18\u00a0<\/span> Porque yo protesto \u00e1 cualquiera que oye las palabras de la profec\u00eda de este libro: Si alguno a\u00f1adiere \u00e1 estas cosas, Dios pondr\u00e1 sobre \u00e9l las plagas que est\u00e1n escritas en este libro.  <span class=\"verse\" id=\"V19\">19\u00a0<\/span> Y si alguno quitare de las palabras del libro de esta profec\u00eda, Dios quitar\u00e1 su parte del libro de la vida, y de la santa ciudad, y de las cosas que est\u00e1n escritas en este libro.  <span class=\"verse\" id=\"V20\">20\u00a0<\/span> El que da testimonio de estas cosas, dice: Ciertamente, vengo en breve. Am\u00e9n, sea as\u00ed. Ven, Se\u00f1or Jes\u00fas.  <span class=\"verse\" id=\"V21\">21\u00a0<\/span> La gracia de nuestro Se\u00f1or Jesucristo sea con todos vosotros. Am\u00e9n.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Apocalipsis<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev10\">10<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev11\">11<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev12\">12<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev13\">13<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev14\">14<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev15\">15<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev16\">16<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev17\">17<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev18\">18<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev19\">19<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev20\">20<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev21\">21<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/rev22\">22<\/a>\r\n  <\/div>\r\n  \r\n","protected":false},"excerpt":{"rendered":"<p>22 1\u00a0 DESPU\u00c9S me mostr\u00f3 un r\u00edo limpio de agua de vida, resplandeciente como cristal, que sal\u00eda del trono de Dios y del Cordero. 2\u00a0 En el medio de la plaza de ella, y de la una y de la otra parte del r\u00edo, estaba el \u00e1rbol de la vida, que lleva doce frutos, dando cada mes su fruto: y las hojas del \u00e1rbol eran para la sanidad de las naciones. 3\u00a0 Y no habr\u00e1 m\u00e1s maldici\u00f3n; sino que el trono de Dios y del Cordero estar\u00e1 en ella, y sus siervos le servir\u00e1n. 4\u00a0 Y ver\u00e1n su cara; y su nombre estar\u00e1 en sus frentes. 5\u00a0 Y all\u00ed no habr\u00e1 m\u00e1s noche; y no tienen necesidad de lumbre de antorcha, ni de lumbre de sol: porque el Se\u00f1or Dios los alumbrar\u00e1: y reinar\u00e1n para siempre jam\u00e1s. 6\u00a0 Y me dijo: Estas palabras son fieles y verdaderas. Y el Se\u00f1or Dios de los santos profetas ha enviado su \u00e1ngel, para mostrar \u00e1 sus siervos las cosas que es necesario que sean hechas presto. 7\u00a0 Y he aqu\u00ed, vengo presto. Bienaventurado el que guarda las palabras de la profec\u00eda de este libro. 8\u00a0 Yo Juan soy el que ha o\u00eddo y visto estas cosas. Y despu\u00e9s que hube o\u00eddo y visto, me postr\u00e9 para adorar delante de los pies del \u00e1ngel que me mostraba estas cosas. 9\u00a0 Y \u00e9l me dijo: Mira que no lo hagas: porque yo soy siervo contigo, y con tus hermanos los profetas, y con los que guardan las palabras de este libro. Adora \u00e1 Dios. 10\u00a0 Y me dijo: No selles las palabras de la profec\u00eda de este libro; porque el tiempo est\u00e1 cerca. 11\u00a0 El que es injusto, sea injusto todav\u00eda: y el que es sucio, ens\u00faciese todav\u00eda: y el que es justo, sea todav\u00eda&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6294","post","type-post","status-publish","format-standard","hentry","category-nuevotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=6294"}],"version-history":[{"count":1,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6294\/revisions"}],"predecessor-version":[{"id":7265,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6294\/revisions\/7265"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=6294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=6294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=6294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}