{"id":6488,"date":"2017-02-02T21:53:01","date_gmt":"2017-02-02T21:53:01","guid":{"rendered":"https:\/\/12tribus.net\/escritura\/santa-biblia-reina-valera-1909-ester-4\/"},"modified":"2019-08-28T13:34:21","modified_gmt":"2019-08-28T17:34:21","slug":"est04","status":"publish","type":"post","link":"https:\/\/12tribus.net\/escritura\/est04\/","title":{"rendered":"Ester 4"},"content":{"rendered":"<div class=\"main\">\r\n<div class=\"chapterlabel\" id=\"V0\"> 4<\/div><div class=\"p\"> \r\n <span class=\"verse\" id=\"V1\">1\u00a0<\/span> LUEGO que supo Mardoch\u00eao todo lo que se hab\u00eda hecho, rasg\u00f3 sus vestidos, y visti\u00f3se de saco y de ceniza, y fu\u00e9se por medio de la ciudad clamando con grande y amargo clamor.  <span class=\"verse\" id=\"V2\">2\u00a0<\/span> Y vino hasta delante de la puerta del rey: porque no era l\u00edcito pasar adentro de la puerta del rey con vestido de saco.  <span class=\"verse\" id=\"V3\">3\u00a0<\/span> Y en cada provincia y lugar donde el mandamiento del rey y su decreto llegaba, ten\u00edan los Jud\u00edos grande luto, y ayuno, y lloro, y lamentaci\u00f3n: saco y ceniza era la cama de muchos.  <span class=\"verse\" id=\"V4\">4\u00a0<\/span> Y vinieron las doncellas de Esther y sus eunucos, y dij\u00e9ronselo: y la reina tuvo gran dolor, y envi\u00f3 vestidos para hacer vestir \u00e1 Mardoch\u00eao, y hacerle quitar el saco de sobre \u00e9l; mas \u00e9l no los recibi\u00f3.  <span class=\"verse\" id=\"V5\">5\u00a0<\/span> Entonces Esther llam\u00f3 \u00e1 Atach, uno de los eunucos del rey, que \u00e9l hab\u00eda hecho estar delante de ella, y mand\u00f3lo \u00e1 Mardoch\u00eao, con orden de saber qu\u00e9 era aquello, y por qu\u00e9.  <span class=\"verse\" id=\"V6\">6\u00a0<\/span> Sali\u00f3 pues Atach \u00e1 Mardoch\u00eao, \u00e1 la plaza de la ciudad que estaba delante de la puerta del rey.  <span class=\"verse\" id=\"V7\">7\u00a0<\/span> Y Mardoch\u00eao le declar\u00f3 todo lo que le hab\u00eda acontecido, y di\u00f3le noticia de la plata que Am\u00e1n hab\u00eda dicho que pesar\u00eda para los tesoros del rey por raz\u00f3n de los Jud\u00edos, para destruirlos.  <span class=\"verse\" id=\"V8\">8\u00a0<\/span> Di\u00f3le tambi\u00e9n la copia de la escritura del decreto que hab\u00eda sido dado en Sus\u00e1n para que fuesen destru\u00eddos, \u00e1 fin de que la mostrara \u00e1 Esther y se lo declarase, y le encargara que fuese al rey \u00e1 suplicarle, y \u00e1 pedir delante de \u00e9l por su pueblo.  <span class=\"verse\" id=\"V9\">9\u00a0<\/span> Y vino Atach, y cont\u00f3 \u00e1 Esther las palabras de Mardoch\u00eao.  <span class=\"verse\" id=\"V10\">10\u00a0<\/span> Entonces Esther dijo \u00e1 Atach, y mand\u00f3le <span class=\"add\">decir<\/span> \u00e1 Mardoch\u00eao:  <span class=\"verse\" id=\"V11\">11\u00a0<\/span> Todos los siervos del rey, y el pueblo de las provincias del rey saben, que cualquier hombre \u00f3 mujer que entra al rey al patio de adentro sin ser llamado, por una sola ley ha de morir: salvo aquel \u00e1 quien el rey extendiere el cetro de oro, el cual vivir\u00e1: y yo no he sido llamada para entrar al rey estos treinta d\u00edas.  <span class=\"verse\" id=\"V12\">12\u00a0<\/span> Y dijeron \u00e1 Mardoch\u00eao las palabras de Esther.  <span class=\"verse\" id=\"V13\">13\u00a0<\/span> Entonces dijo Mardoch\u00eao que respondiesen \u00e1 Esther: No pienses en tu alma, que escapar\u00e1s en la casa del rey m\u00e1s que todos los Jud\u00edos:  <span class=\"verse\" id=\"V14\">14\u00a0<\/span> Porque si absolutamente callares en este tiempo, respiro y libertaci\u00f3n tendr\u00e1n los Jud\u00edos de otra parte; mas t\u00fa y la casa de tu padre perecer\u00e9is. \u00bfY qui\u00e9n sabe si para esta hora te han hecho llegar al reino?  <span class=\"verse\" id=\"V15\">15\u00a0<\/span> Y Esther dijo que respondiesen \u00e1 Mardoch\u00eao:  <span class=\"verse\" id=\"V16\">16\u00a0<\/span> Ve, y junta \u00e1 todos los Jud\u00edos que se hallan en Sus\u00e1n, y ayunad por m\u00ed, y no com\u00e1is ni beb\u00e1is en tres d\u00edas, noche ni d\u00eda: yo tambi\u00e9n con mis doncellas ayunar\u00e9 igualmente, y as\u00ed entrar\u00e9 al rey, aunque no sea conforme \u00e1 la ley; y si perezco, que perezca.  <span class=\"verse\" id=\"V17\">17\u00a0<\/span> Entonces se fu\u00e9 Mardoch\u00eao, \u00e9 hizo conforme \u00e1 todo lo que le mand\u00f3 Esther.  <\/div>\r\n<hr>\r\n<\/div>\r\n\r\n  <div class=\"chapters\">\r\n    <h3>Cap\u00edtulos de Ester<\/h3>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est01\">1<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est02\">2<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est03\">3<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est04\">4<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est05\">5<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est06\">6<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est07\">7<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est08\">8<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est09\">9<\/a>\r\n    <a href=\"http:\/\/12tribus.net\/escritura\/est10\">10<\/a>\r\n  <\/div>\r\n  ","protected":false},"excerpt":{"rendered":"<p>4 1\u00a0 LUEGO que supo Mardoch\u00eao todo lo que se hab\u00eda hecho, rasg\u00f3 sus vestidos, y visti\u00f3se de saco y de ceniza, y fu\u00e9se por medio de la ciudad clamando con grande y amargo clamor. 2\u00a0 Y vino hasta delante de la puerta del rey: porque no era l\u00edcito pasar adentro de la puerta del rey con vestido de saco. 3\u00a0 Y en cada provincia y lugar donde el mandamiento del rey y su decreto llegaba, ten\u00edan los Jud\u00edos grande luto, y ayuno, y lloro, y lamentaci\u00f3n: saco y ceniza era la cama de muchos. 4\u00a0 Y vinieron las doncellas de Esther y sus eunucos, y dij\u00e9ronselo: y la reina tuvo gran dolor, y envi\u00f3 vestidos para hacer vestir \u00e1 Mardoch\u00eao, y hacerle quitar el saco de sobre \u00e9l; mas \u00e9l no los recibi\u00f3. 5\u00a0 Entonces Esther llam\u00f3 \u00e1 Atach, uno de los eunucos del rey, que \u00e9l hab\u00eda hecho estar delante de ella, y mand\u00f3lo \u00e1 Mardoch\u00eao, con orden de saber qu\u00e9 era aquello, y por qu\u00e9. 6\u00a0 Sali\u00f3 pues Atach \u00e1 Mardoch\u00eao, \u00e1 la plaza de la ciudad que estaba delante de la puerta del rey. 7\u00a0 Y Mardoch\u00eao le declar\u00f3 todo lo que le hab\u00eda acontecido, y di\u00f3le noticia de la plata que Am\u00e1n hab\u00eda dicho que pesar\u00eda para los tesoros del rey por raz\u00f3n de los Jud\u00edos, para destruirlos. 8\u00a0 Di\u00f3le tambi\u00e9n la copia de la escritura del decreto que hab\u00eda sido dado en Sus\u00e1n para que fuesen destru\u00eddos, \u00e1 fin de que la mostrara \u00e1 Esther y se lo declarase, y le encargara que fuese al rey \u00e1 suplicarle, y \u00e1 pedir delante de \u00e9l por su pueblo. 9\u00a0 Y vino Atach, y cont\u00f3 \u00e1 Esther las palabras de Mardoch\u00eao. 10\u00a0 Entonces Esther dijo \u00e1 Atach, y mand\u00f3le decir \u00e1 Mardoch\u00eao: 11\u00a0 Todos los siervos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6488","post","type-post","status-publish","format-standard","hentry","category-viejotestamento"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/comments?post=6488"}],"version-history":[{"count":2,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6488\/revisions"}],"predecessor-version":[{"id":7315,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/posts\/6488\/revisions\/7315"}],"wp:attachment":[{"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/media?parent=6488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/categories?post=6488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/12tribus.net\/escritura\/wp-json\/wp\/v2\/tags?post=6488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}